{"id":152804,"date":"2017-06-15T14:09:21","date_gmt":"2017-06-15T12:09:21","guid":{"rendered":"http:\/\/www.albinfo.ch\/keshtu-e-sheh-diaspora-fitoren-e-vetevendosjes\/"},"modified":"2024-10-14T22:47:40","modified_gmt":"2024-10-14T20:47:40","slug":"so-sieht-die-diaspora-den-wahlerfolg-von-vetevendosje","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/so-sieht-die-diaspora-den-wahlerfolg-von-vetevendosje\/","title":{"rendered":"So sieht die Diaspora den Wahlerfolg von Vet\u00ebvendosje"},"content":{"rendered":"<p style=\"background: white; margin: 0cm 0cm 7.5pt 0cm;\"><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">Das Wahlergebnis der Wahlen vom letzten Sonntag in Kosova war auch in der Diaspora in der Schweiz ein viel besprochenes Thema. Von einer Wende ist die Rede. Das nun Vet\u00ebvendosje die st\u00e4rkste Partei im kosovarischen Parlament ist, sei auch der Diaspora zuzuschreiben. Albinfo.ch hat diesbez\u00fcglich mit mehreren Aktivisten gesprochen.<\/span><\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/10\/252927399.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-96005\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/10\/252927399-1024x819.jpg\" alt=\"\" width=\"538\" height=\"430\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/10\/252927399.jpg 1024w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/10\/252927399-300x240.jpg 300w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/10\/252927399-495x396.jpg 495w\" sizes=\"auto, (max-width: 538px) 100vw, 538px\" \/><\/a><\/p>\n<p style=\"background: white;\"><strong><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">Ylfete Fanaj, SP-Fraktionsvorsitzende im Luzerner Parlament<\/span><\/strong><\/p>\n<p style=\"background: white;\"><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">Es ist etwas sehr positives. Ein Zeichen des Volkes daf\u00fcr, das eine neue \u00c4ra in der kosovarischen Politik anbricht. Der Wahlerfolg bedeutet aber auch grosse Verantwortung f\u00fcr Vet\u00ebvendosje! Zudem ist dies eine Chance f\u00fcr Kosova, wenn Vet\u00ebvendosje! das Wahlprogramm in Regierungsarbeit umsetzt.<\/span><\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/01\/alban-imeri-bdp.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-104812\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/01\/alban-imeri-bdp.png\" alt=\"\" width=\"544\" height=\"400\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/01\/alban-imeri-bdp.png 780w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/01\/alban-imeri-bdp-300x221.png 300w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/01\/alban-imeri-bdp-538x396.png 538w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/01\/alban-imeri-bdp-151x110.png 151w\" sizes=\"auto, (max-width: 544px) 100vw, 544px\" \/><\/a><\/p>\n<p style=\"background: white;\"><strong><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">Alban Imeri, BDP-Abgeordneter im Thurgauer Parlament<\/span><\/strong><\/p>\n<p style=\"background: white;\"><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">Meiner Meinung nach bestehen Parallelen zwischen den politischen Systemen in der Schweiz und im Kosovo. Ohne eine Koalition einzugehen, hat L\u00ebvizja Vet\u00ebvendosje! einen sensationellen Erfolg eingefahren. Zudem heisst es, die Wahlen wurden extra nicht in den Sommermonaten angesetzt, wenn die Diaspora-Kosovaren im Summerurlaub im Kosovo sind. Denn die Diaspora\u00a0<span class=\"apple-converted-space\">\u00a0<\/span>w\u00fcrde mit \u00fcberw\u00e4ltigender Mehrheit f\u00fcr Vet\u00ebvendosje! stimmen. Die Entwicklung von Vet\u00ebvendosje! \u00e4hnelt sehr der Entwicklung der SVP in der Schweiz. Gleich wie die SVP hat Vet\u00ebndosje! im Kosovo die Themen besetzt, die den Menschem im Land unter den N\u00e4gel brennen. Auch wenn Vet\u00ebvendosje! oft als eine extreme Partei bezeichnet wird, denke ich, dass eine von ihr gef\u00fchrte Regierung dem Land sehr gut tun w\u00fcrde. Denn die \u201ealten\u201c Parteien sind daran gescheitert, eine Ver\u00e4nderung und eine Verbesserung f\u00fcr das Leben der Kosovaren herbeizuf\u00fchren. Vielmehr gelten die alten Parteien als korrupt und werden mit organisierter Kriminalit\u00e4t in Verbindung gebracht. Allerdings ist die Angst auch bei der EU gross, dass bei einer Umsetzung des Programms von Vet\u00ebvendosje! die Region destabilisiert w\u00fcrde. Es sieht danach aus als st\u00fcnde das Land vor der n\u00e4chsten Blockade. Vet\u00ebvendosje! wird wohl mit keiner Partei eine Koalition eingehen k\u00f6nnen. Doch was passiert, wenn PAN (die Koalition mit den meisten Stimmen) mit der Demokratischen Liga des Kosovo eine Koalition eingeht? Dies w\u00fcrde mittelfristig Vet\u00ebvendosje! st\u00e4rken. Denn es ist klar: die bisherigen Koalitionspartner haben keines ihrer Themen voranbringen k\u00f6nnen. Daher w\u00fcrde Kosovo sicherlich eine Konstellation wie der Schweizer Bundesrat helfen, an dem alle parlamentarischen Parteien beteiligt gewesen w\u00e4ren.<\/span><\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/gjyle-krasniqi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-152357\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/gjyle-krasniqi.jpg\" alt=\"\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/gjyle-krasniqi.jpg 720w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/gjyle-krasniqi-150x150.jpg 150w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/gjyle-krasniqi-300x300.jpg 300w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/gjyle-krasniqi-396x396.jpg 396w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/gjyle-krasniqi-280x280.jpg 280w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p style=\"background: white;\"><strong><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">Gjyle-Julie Krasniqi, Kulturmanagerin in Luzern<\/span><\/strong><\/p>\n<p style=\"background: white;\"><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">Wenn den Gewinnern der Wahl Kosovo wirklich im Herzen liegt, k\u00f6nnen sie nun sich beweisen. Sie w\u00fcrden eine Koalition nach dem Vorbild des Schweizer Bundesrates bilden. Dies w\u00e4re die einzige M\u00f6glichkeit, den Willen des Volkes umzusetzen. Nat\u00fcrlich sollten sie dabei nicht davon absehen, die Anzahl der Ministerien von einem Dutzend auf sieben zu reduzieren (so viel wie der Schweizer Bundesrat).<\/span><\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/12\/bashkim-iseni.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-613606\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/12\/bashkim-iseni-1024x768.jpg\" alt=\"\" width=\"533\" height=\"400\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/12\/bashkim-iseni-1024x768.jpg 1024w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/12\/bashkim-iseni-300x225.jpg 300w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/12\/bashkim-iseni-768x576.jpg 768w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/12\/bashkim-iseni-1536x1152.jpg 1536w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/12\/bashkim-iseni-528x396.jpg 528w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/12\/bashkim-iseni-133x100.jpg 133w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/12\/bashkim-iseni-233x175.jpg 233w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/12\/bashkim-iseni.jpg 2048w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><\/a><\/p>\n<p style=\"background: white;\"><strong><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">Dr. Bashkim Iseni, Direktor<\/span><\/strong><span class=\"apple-converted-space\"><b><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">\u00a0<\/span><\/b><\/span><strong><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\"><a href=\"http:\/\/albinfo.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=de&amp;q=http:\/\/albinfo.ch&amp;source=gmail&amp;ust=1497695189510000&amp;usg=AFQjCNG9E3M6mnPd7YsvXIlMHL-Z023zEw\"><span style=\"color: #1155cc;\">albinfo.ch<\/span><\/a>, Politologe Lausanne<\/span><\/strong><\/p>\n<p style=\"background: white;\"><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">Das Wahlergebnis stellt eine substantielle Ver\u00e4nderung der politischen Realit\u00e4t im Kosovo. Besonders der Erfolg von Vet\u00ebvendosje! als nun st\u00e4rkste politische Kraft des Landes. Nach den Wahlen in Mazedonien zeigt sich auch im Kosovo, dass nun ein neues politisches Kapitel aufgeschlagen wird: der Wunsch nach strukturellen Reformen und nach richtiger Europ\u00e4isierung der Region.<\/span><\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/03\/alban-nevzati-kryetar-img_1476.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-76413\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/03\/alban-nevzati-kryetar-img_1476-1024x744.jpg\" alt=\"\" width=\"550\" height=\"400\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/03\/alban-nevzati-kryetar-img_1476-1024x744.jpg 1024w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/03\/alban-nevzati-kryetar-img_1476-300x218.jpg 300w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/03\/alban-nevzati-kryetar-img_1476-151x110.jpg 151w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/03\/alban-nevzati-kryetar-img_1476.jpg 2000w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; background: white;\"><strong><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">P\u00ebrparim Avdili, Bankangestellter, FDP-Politiker, Z\u00fcrich<\/span><\/strong><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; background: white;\"><strong><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333; font-weight: normal;\">Die Wahl zeigte, dass die alten etablierten Parteien nicht immun gegen eine relativ junge Partei sind, die sich ausser auf lokaler Ebene bisher nicht in Regierungsarbeit bew\u00e4hren musste. Der enorme Wahlerfolg von Vet\u00ebvendosje!<\/span><\/strong><span class=\"apple-converted-space\"><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">\u00a0<\/span><\/span><strong><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333; font-weight: normal;\">\u00a0ist auf mehreren Gr\u00fcnden zur\u00fcckzuf\u00fchren. Es gleicht einer Protestpartei \u2013 aus Mangel an Alternativen und aus Protest gegen die alten politischen Eliten w\u00e4hlten die B\u00fcrger Vet\u00ebvendosje! Die Menschen hoffen nun, dass Vet\u00ebvendosje! ihre Probleme l\u00f6sen kann, die jahrelang vernachl\u00e4ssigt wurden. \u00dcber Jahre hinweg hat Vet\u00ebvendosje! die politische Frustration der Menschen kultiviert, indem sie eine Fundamentalopposition betrieben hat. Dank dieser Politik ist sie st\u00e4rkste politische Kraft im Land geworden. Sie tr\u00e4gt nun eine grosse Verantwortung und muss die Frustration in Hoffnung umm\u00fcnzen, damit es kein Opfer der eigenen Politik wird, sollte sie die neue Regierung tats\u00e4chlich stellen.<\/span><\/strong><\/p>\n<p><strong><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/11\/hamit-zeqiri.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-130013\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/11\/hamit-zeqiri-1024x653.png\" alt=\"\" width=\"549\" height=\"350\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/11\/hamit-zeqiri-1024x653.png 1024w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/11\/hamit-zeqiri-300x191.png 300w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/11\/hamit-zeqiri-768x489.png 768w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/11\/hamit-zeqiri-87x56.png 87w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/11\/hamit-zeqiri-587x374.png 587w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/11\/hamit-zeqiri.png 1541w\" sizes=\"auto, (max-width: 549px) 100vw, 549px\" \/><\/a><\/strong><\/p>\n<p style=\"background: white;\"><strong><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">Hamit Zeqiri, Sozialexperte, Vorsitzender KOFI<\/span><\/strong><\/p>\n<p style=\"background: white;\"><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">Der Sonntag war ein grosses Fest f\u00fcr Kosovo. Die Abstimmung war mehr als eine Wahl, es gleicht einem Referendum. Der Wahlerfolg von Vet\u00ebvendosje! zeigt, dass das Volk einen Sinn f\u00fcr Gerechtigkeit hat. Trotz der staatlichen Propagandamaschinerie und der vielen Millionen haben es die Korrupten nicht geschafft.<span class=\"apple-converted-space\">\u00a0<\/span>\u00a0Dies ist der Anfang von ihrem Ende. Dass unser Land nun bald von ehrlichen, w\u00fcrde- und verantwortungsvollen Politikern mit Kompetenz, Mut und Herz gef\u00fchrt wird, macht mich gl\u00fccklich. Ich freue mich darauf, dass wir nicht mehr \u00fcber die F\u00fchrung unseres Landes sch\u00e4men m\u00fcssen. Ab heute weht im Kosovo ein frischer Wind. Kein Parteiengeschacher darf den Willen des Volkes unterminieren.<\/span><\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/04\/perparim-avdili-2015-02-22-16.03.18.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-79870\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/04\/perparim-avdili-2015-02-22-16.03.18-1024x764.jpg\" alt=\"\" width=\"536\" height=\"400\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/04\/perparim-avdili-2015-02-22-16.03.18-1024x764.jpg 1024w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/04\/perparim-avdili-2015-02-22-16.03.18-300x224.jpg 300w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/04\/perparim-avdili-2015-02-22-16.03.18-531x396.jpg 531w\" sizes=\"auto, (max-width: 536px) 100vw, 536px\" \/><\/a><\/p>\n<p style=\"background: white;\"><strong><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">P\u00ebrparim Avdili, Bankangestellter, FDP-Politiker, Z\u00fcrich<\/span><\/strong><\/p>\n<p style=\"background: white;\"><strong><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333; font-weight: normal;\">Die Wahl zeigte, dass die alten etablierten Parteien nicht immun gegen eine relativ junge Partei sind, die sich ausser auf lokaler Ebene bisher nicht in Regierungsarbeit bew\u00e4hren musste. Der enorme Wahlerfolg von Vet\u00ebvendosje!<\/span><\/strong><span class=\"apple-converted-space\"><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333;\">\u00a0<\/span><\/span><strong><span style=\"font-size: 10.5pt; font-family: 'Helvetica',sans-serif; color: #333333; font-weight: normal;\">\u00a0ist auf mehreren Gr\u00fcnden zur\u00fcckzuf\u00fchren. Es gleicht einer Protestpartei \u2013 aus Mangel an Alternativen und aus Protest gegen die alten politischen Eliten w\u00e4hlten die B\u00fcrger Vet\u00ebvendosje! Die Menschen hoffen nun, dass Vet\u00ebvendosje! ihre Probleme l\u00f6sen kann, die jahrelang vernachl\u00e4ssigt wurden. \u00dcber Jahre hinweg hat Vet\u00ebvendosje! die politische Frustration der Menschen kultiviert, indem sie eine Fundamentalopposition betrieben hat. Dank dieser Politik ist sie st\u00e4rkste politische Kraft im Land geworden. Sie tr\u00e4gt nun eine grosse Verantwortung und muss die Frustration in Hoffnung umm\u00fcnzen, damit es kein Opfer der eigenen Politik wird, sollte sie die neue Regierung tats\u00e4chlich stellen.<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Reaktionen auf den Wahlerfolg von Vet\u00ebvendosje waren durchweg positiv. F\u00fcr albinfo.ch \u00e4ussern sich Aktivisten der albanischen Diaspora vor dem Hintergrund von Erfahrungen aus der Schweiz.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3922,1129,1133,1158,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-152804","post","type-post","status-publish","format-standard","hentry","category-kosova-vota-e-diaspores-de","category-ch-balkan","category-e-diaspora-de","category-themen-vor-ort","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/152804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=152804"}],"version-history":[{"count":2,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/152804\/revisions"}],"predecessor-version":[{"id":775701,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/152804\/revisions\/775701"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=152804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=152804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=152804"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=152804"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=152804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}