{"id":167980,"date":"2017-10-28T09:43:08","date_gmt":"2017-10-28T07:43:08","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=167980\/"},"modified":"2017-11-05T22:05:20","modified_gmt":"2017-11-05T21:05:20","slug":"besuch-im-atelier-von-shuk-orani","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/besuch-im-atelier-von-shuk-orani\/","title":{"rendered":"Besuch im Atelier von Shuk Orani\u00a0"},"content":{"rendered":"<p>W\u00e4hrend der Betrachtung einer seiner gespachtelten Landschaften startet leise ein Kopfkino: In einem hellen Zimmer ist nichts zu h\u00f6ren au\u00dfer das Surren eines kleinen Kunststoffkastens, der vor dem Bild installiert ist. W\u00e4hrend seiner langsamen Fahrt in sorgf\u00e4ltig berechneten Winkeln \u00fcbertr\u00e4gt eine darin eingebaute Kamera einzelne Bereiche der Bildoberfl\u00e4che auf einen Monitor. Manchmal stoppt sie f\u00fcr l\u00e4ngere Zeit. Stille. Dann geht das Surren pl\u00f6tzlich weiter.<\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-bildschirmfoto-2017-10-26-um-21.57.31.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-167982\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-bildschirmfoto-2017-10-26-um-21.57.31-1024x639.png\" alt=\"\" width=\"640\" height=\"399\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-bildschirmfoto-2017-10-26-um-21.57.31-1024x639.png 1024w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-bildschirmfoto-2017-10-26-um-21.57.31-300x187.png 300w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-bildschirmfoto-2017-10-26-um-21.57.31-768x479.png 768w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-bildschirmfoto-2017-10-26-um-21.57.31-587x366.png 587w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-bildschirmfoto-2017-10-26-um-21.57.31.png 1581w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>W\u00e4re ein derartiger Apparat zur Betrachtung eines Bildes nicht lediglich eine Begradigung der Bewegung unseres Blicks? Dieser kann nur schwer ruhen, es sei denn, er wurde durch gezielte \u00dcbung dazu gebracht. Im Drang nach Orientierung ist alles in Bewegung: Die Aug\u00e4pfel zucken, wir treten vor und zur\u00fcck, durchleben Ebenen der Wahrnehmung und relativieren unsere Meinung untereinander. Das Bild hingegen ist die ganze Zeit dort und bleibt unver\u00e4ndert.<\/p>\n<p>Sensibilit\u00e4t erhalten die Landschaften in Shuk Oranis Bildern durch die Verbindung seines Wissens \u00fcber die Harmonie und Disharmonie von Farben mit der Einarbeitung des Zufalls ausgehend vom Duktus des Spachtels. \u00dcberlagert werden trockene Farbspuren, cremige Strichf\u00fchrung und transparente Felder \u2013 ein Wechselbad der Gef\u00fchle, oder spricht man heute nur noch von gezielt \u00fcberlegter \u201eKonstruktion\u201c? In einem Radiointerview editiert als Textversion unter dem Titel \u201eThe Use of Color and its Effect. The How and the Why\u201c hatte Ernst H. Gombrich einst im Gespr\u00e4ch mit Bridget Riley die Tendenz untersucht, Malerei entweder als Wissenschaft oder als Experiment einzuordnen. Gespr\u00e4chsgrundlage waren die Landschaften John Constables, enstanden zu Beginn des 19. Jahrhunderts. Markt und Trends, damals wie heute, so ihr Ergebnis, f\u00fchrten zu gut verk\u00e4uflichen Imitationen, doch unvergleichlich bleibt der Gusto eines Kunstwerks, das einem urs\u00e4chlichen Gef\u00fchl entspringt. Eine gute Beobachtung der Erscheinungen habe nichts mit Optik zu tun.*1)<\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-img_1275.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-167983\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-img_1275-1024x768.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-img_1275-1024x768.jpg 1024w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-img_1275-300x225.jpg 300w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-img_1275-768x576.jpg 768w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-img_1275-528x396.jpg 528w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p><strong>Die Ausstellung in Leipzig \u201eDissolution in matter and form\u201c in \u201cHermeling &amp; Schreckenberger Galerie\u201d<\/strong><\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-olymp_so.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-167984\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-olymp_so-678x1024.png\" alt=\"\" width=\"640\" height=\"967\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-olymp_so-678x1024.png 678w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-olymp_so-199x300.png 199w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-olymp_so-768x1160.png 768w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-olymp_so-262x396.png 262w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/10\/shukri-orani-olymp_so.png 837w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>Synthesen aus expressionistischer Formensprache und abstrakter Konstruktion, wie sie vor 100 Jahren auf der Bildfl\u00e4che erschienen, sind h\u00f6chst aktuell. Im Jahr 2017 finden wir uns in einer Zeit gesellschaftlichen Wandels, in der sich der denkende Mensch mit kulturellen Str\u00f6mungen konfrontiert sieht, die einerseits konservative Gewaltenteilungen und andererseits Machtstrukturen der technologischen Zukunft sp\u00fcren lassen. Wie nah erscheinen uns doch bei Shuk Oranis ins Senkrechte und Diagonale laufender Landschaft\u00a0 \u201eOlymp\u201c die kompositorischen Ideen Franz Marcs, in dessen Bild \u201eTierschicksale\u201c (1913) die Turmkonstruktion zu Fall gebracht wird. Bildvisionen wie Lyonel Feiningers Kathedralen und Joseph Stellas Brooklyn Bridge entwerfen R\u00e4ume, die nicht aus St\u00fctze und Last entstehen, sondern aus diagonalen Verstrebungen. Beeinflusste der Ingenieur den Maler oder umgekehrt? Der Erbauer der Brooklyn Bridge hatte Philosophie bei Hegel studiert und Linien sind nach Henry van de Velde \u00fcbertragene Geb\u00e4rden. Sie sind, so Christoph Asendorf, jene Konstanten, mittels derer Mensch und Ding ihren Ort in Kraftfeldern sichern.*2)<\/p>\n<p>Franz Marc bef\u00fcrchtete Gef\u00fchlswidriges in jeglicher Fig\u00fcrlichkeilt, doch die Figur scheint sich hineinzudr\u00e4ngen, sobald der weibliche K\u00f6rper das Motiv bestimmt. Selbst in abstrakter Form verschwindet das Weib nicht aus dem Bild. Es kann nicht weichen und es scheint unverdr\u00e4ngbar. Erscheint uns hier umso st\u00e4rker die Kombination aus Konfrontation durch Entbl\u00f6\u00dfung und Abmilderung durch Zensur? Der kr\u00e4ftige, schwarze Streifen, der in den Medien die Identit\u00e4t einer Abbgelichteten Person zu verdecken sucht, ist weniger Erl\u00f6sung als Einordnung in eine Tabuzone. Hierf\u00fcr macht die Protagonistin alles richtig: \u00dcber den gespreizten Beinen liegt die Hand wohlplatziert an der Lende, w\u00e4hrend die andere \u00fcber ihre runden Flanken hochwandert, um den Finger zwischen die dunkelroten Lippen zu legen. Der schroffe Duktus der Farbe verursacht Sehnsucht nach etwas mehr Weichzeichnung, wie bei den Venusdarstellungen der alten Meister &#8211; die abgrundtiefe L\u00fccke zu den antiken Liebesg\u00f6ttinnen klafft weit, w\u00e4ren da nicht die leisen, hellbraunen Farbauftr\u00e4ge, durchscheinend gehalten, die ihren Bauch bandagieren.<\/p>\n<p>Wie das Theater schafft die Malerei hier die passende Kost\u00fcmierung, verleiht die l\u00fcsterne Pose. Wie die Pressefotografie schafft die Malerei hier ebenso das zensierende Schwarz. Aber wo die Farbe von jeglichem Rollenspiel gel\u00f6st ist und als sch\u00fctzende Schicht auftritt, da beginnt die Sph\u00e4re des Gef\u00fchls, da stellt sich der Einordnung die Unentschlossenheit in den Weg, ob die Venus sich mit ihrer \u00fcblichen Rolle oder mit der freien Farbe neu verbindet.<\/p>\n<p>Wortw\u00f6rtlich geht es um Aufl\u00f6sung des Frauenbildes in Materie und Form, Letztere als Platzhalter f\u00fcr die Beschreibung der Beziehung zu ihr. Beispiele aus Literatur und Kunst gibt es genug. Oranis Bilder erg\u00e4nzen diese zahlreichen Positionen, die dem Drang nach Metamorphose im Alltag Ausdruck verleihen. Fig\u00fcrliches, Wesenhaftest, wird zugelassen, unwillk\u00fcrlich tr\u00fcgerische Kippbilder bilden sich heraus. Die Farbe frisst der Frauenfigur aus der Hand und bandagiert sie im Gegenzug, sie macht vor den weiblichen Konturen erg\u00e4nzend Halt und lenkt den Betrachter gleichzeitig von dem ab, was auf der Bildfl\u00e4che zu sehen ist. Was zeigt sie uns, die da schaut, die ihre Augen geschlossen h\u00e4lt, die den R\u00fccken zu uns kehrt?<\/p>\n<p><strong>[1]Bridget Riley und Ernst H. Gombrich: The Use of Colour and its Effect: The How and the Why, in: The Burlington<\/strong><\/p>\n<p><strong>Magazine, Vol. 136, No. 1096 (Jul. 1994), S. 427-429.<\/strong><\/p>\n<p><strong>[2]Christoph Asendorf: Str\u00f6me und Strahlen \u2013 Das langsame Verschwinden der Materie um 1900, Anabas Verlag, Gie\u00dfen<\/strong><\/p>\n<p><strong>1989, S 89. f.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend der Betrachtung einer seiner gespachtelten Landschaften startet leise ein Kopfkino: In einem hellen Zimmer ist nichts zu h\u00f6ren au\u00dfer das Surren eines kleinen Kunststoffkastens, der vor dem Bild installiert ist. W\u00e4hrend seiner langsamen Fahrt in sorgf\u00e4ltig berechneten Winkeln \u00fcbertr\u00e4gt eine darin eingebaute Kamera einzelne Bereiche der Bildoberfl\u00e4che auf einen Monitor. Manchmal stoppt sie f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":167981,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1138,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-167980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kultur","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/167980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=167980"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/167980\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/167981"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=167980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=167980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=167980"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=167980"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=167980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}