{"id":176226,"date":"2017-12-21T15:55:06","date_gmt":"2017-12-21T14:55:06","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=176226\/"},"modified":"2017-12-25T23:05:57","modified_gmt":"2017-12-25T22:05:57","slug":"cefta-eine-chance-fuer-kosovo","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/cefta-eine-chance-fuer-kosovo\/","title":{"rendered":"CEFTA, eine Chance f\u00fcr Kosovo"},"content":{"rendered":"<p>Am 21. Dezember 2017 findet das 25-Jahre-Jubil\u00e4um des CEFTA statt. Die Bedeutung dieses Staatsvertrags und sein Entwicklungspotential f\u00fcr die Region S\u00fcdosteuropa und die Republik Kosovo wird oft untersch\u00e4tzt. Doch zuerst zur\u00fcck zum Anfang.<\/p>\n<p>Am 21. Dezember 1992 gr\u00fcndeten Polen, Ungarn und die damalige Tschechoslowakei das Mitteleurop\u00e4ische Freihandelsabkommen (Central European Free Trade Agreement; CEFTA) mit dem Ziel, Z\u00f6lle und nichttarif\u00e4re Handelshemmnisse abzubauen. Schon damals galt eine Teilnahme am CEFTA als Vorbereitung zum Beitritt zur Europ\u00e4ischen Union (EU).<\/p>\n<p>Der Mitgliederbestand des CEFTA war einem steten Wandel unterworfen. Die Gr\u00fcndungsmitglieder Polen, Ungarn, Tschechien und Slowakei wurden 2004 in die EU aufgenommen und sind deshalb aus dem CEFTA ausgetreten. Dem CEFTA vorher beigetreten und mit dem EU-Beitritt wieder ausgetreten waren Slowenien (1996\/2004), Rum\u00e4nien (1997\/2007), Bulgarien (1999\/2007) und Kroatien (2002\/2013). Heute sind Albanien, Bosnien und Herzegowina, Kosovo, Mazedonien, Moldawien, Montenegro und Serbien die Mitglieder des CEFTA. Und alle diese Mitglieder des CEFTA haben bei der EU ein Interesse f\u00fcr den Beitritt angemeldet. Es scheint nach der historischen Erfahrung tats\u00e4chlich so zu sein, dass das CEFTA der Schl\u00fcssel zum Beitritt zur EU ist.<\/p>\n<p>Das CEFTA kann aber mehr sein, als der blosse T\u00fcr\u00f6ffner zur EU. Warum? Schauen wir uns die Entwicklung der Gr\u00fcndungsmitglieder an: Polen, Ungarn, die Slowakei und Tschechien bilden innerhalb der EU die Visegr\u00e1d-Gruppe, die als halboffizielles Binnenb\u00fcndnis die Interessen der europ\u00e4ischen Oststaaten in der EU koordiniert und dadurch innerhalb der EU die Interessen der europ\u00e4ischen Oststaaten b\u00fcndelt.\u00a0 Es handelt sich dabei nicht um eine neuartige Erscheinung. Schon vor der Gr\u00fcndung der EU haben sich Belgien, die Niederlande und Luxemburg zur Benelux vereinigt, die bis heute innerhalb der EU als Binnenb\u00fcndnis fortlebt. In der mit heute 28 Mitgliedstaaten gross gewordenen EU ist es wichtig, gemeinsame Interessen b\u00fcndeln zu k\u00f6nnen, was die Benelux und die Visegr\u00e1d-Gruppe eindr\u00fccklich demonstrieren.<\/p>\n<p>Wir wollen uns keinen Illusionen hingeben: die heutigen Mitgliedsstaaten des CEFTA haben untereinander viele Fragen offen, die Uneinigkeiten verursachen. Diese trennenden Aspekte haben uns die letzten tausend Jahre begleitet; sie werden uns auch die n\u00e4chsten tausend Jahre begleiten. Trotz aller Gegens\u00e4tze haben wir in der Region des heutigen CEFTA auch gemeinsame Interessen. So wie es der Benelux oder der Visegr\u00e1d-Gruppe gelang, diese regionalen Interessen innerhalb der EU zu b\u00fcndeln, m\u00fcssen die heutigen CEFTA-Staaten einen Weg finden, ihre gemeinsamen und vor allem wirtschaftlichen Interessen im Hinblick auf den EU-Beitritt und in Hinblick auf die Zeit nach dem Beitritt zu b\u00fcndeln.<\/p>\n<p>Wir werden das Trennende und unsere Geschichte nicht leugnen k\u00f6nnen. Wir werden aber auch nicht leugnen k\u00f6nnen, dass wir in unserer Region trotz aller trennenden Aspekte gemeinsame Interessen gegen\u00fcber der EU haben und haben werden. Damit wir diese Interessen b\u00fcndeln und im regionalen Interesse verfolgen k\u00f6nnen, m\u00fcssen wir einen gemeinsamen regionalen Konsens erarbeiten.\u00a0 Das CEFTA ist in der Region oft unbekannt und oft untersch\u00e4tzt. Aber es ist das Vehikel daf\u00fcr, die Interessen der Region gegen\u00fcber der EU effizient zu vertreten. Das sollten wir am 21. Dezember nicht vergessen.<\/p>\n<p>&nbsp;<\/p>\n<p>(Der Autor ist Rechtskonsulent bei K\u00fcng Rechtsanw\u00e4lte Bassersdorf)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 21. Dezember 2017 findet das 25-Jahre-Jubil\u00e4um des CEFTA statt. Die Bedeutung dieses Staatsvertrags und sein Entwicklungspotential f\u00fcr die Region S\u00fcdosteuropa und die Republik Kosovo wird oft untersch\u00e4tzt<\/p>\n","protected":false},"author":4,"featured_media":37923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3908,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-176226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinungen","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/176226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=176226"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/176226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/37923"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=176226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=176226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=176226"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=176226"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=176226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}