{"id":184880,"date":"2018-02-21T13:12:04","date_gmt":"2018-02-21T12:12:04","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=184880\/"},"modified":"2018-02-23T00:16:41","modified_gmt":"2018-02-22T23:16:41","slug":"der-bundesrat-verabschiedet-den-aussenpolitischen-bericht-2017","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/der-bundesrat-verabschiedet-den-aussenpolitischen-bericht-2017\/","title":{"rendered":"Der Bundesrat verabschiedet den Aussenpolitischen Bericht 2017"},"content":{"rendered":"<p>Die Bilanz des Bundesrates \u00fcber die Aussenpolitik im Jahr 2017 f\u00e4llt uneinheitlich aus: Das Verh\u00e4ltnis zwischen der Schweiz und der EU bleibt fragil und kl\u00e4rungsbed\u00fcrftig und wird weiterhin im Zentrum der Aussenpolitik stehen. In Bezug auf die anderen drei strategischen Schwerpunkte \u2013 globale Partner, Frieden und Sicherheit sowie nachhaltige Entwicklung und Wohlstand \u2013 f\u00e4llt die Bilanz positiv aus.<\/p>\n<p>Das Jahr 2017 war gepr\u00e4gt von anhaltenden globalen Machtverschiebungen. Die entstehende multipolare Welt stand insbesondere im Zeichen der neuen US-Administration und des verst\u00e4rkten Anspruchs Chinas auf eine globale F\u00fchrungsrolle. Die internationale Lage bleibt durch viele Krisen gepr\u00e4gt, es hat aber auch Stabilisierungsfortschritte und positive Entwicklungen gegeben. Die Weltwirtschaft hat sich weiter erholt und die EU pr\u00e4sentiert sich heute gefestigter als noch vor einem Jahr.<\/p>\n<p>Regionale Stabilit\u00e4t in Europa geh\u00f6rt zu den Kerninteressen der Schweiz. Im diesj\u00e4hrigen Schwerpunktkapitel zeigt der Bericht auf, wie die Schweizer Aussenpolitik zur europ\u00e4ischen Sicherheit beitr\u00e4gt. Dabei wird dargelegt, wie sich die Schweiz f\u00fcr die \u00dcberwindung der europ\u00e4ischen Ordnungskrise zwischen Russland und dem Westen engagiert und die Sicherheitskooperation im OSZE-Raum f\u00f6rdert. Am Beispiel des Westbalkans zeigt der Bericht zudem, wie sich die Schweiz auf der Basis ihres umfassenden Sicherheitsverst\u00e4ndnisses auch subregional f\u00fcr Frieden und Entwicklung einsetzt.<\/p>\n<p>Die Normalisierung der Beziehungen mit der EU ist im Berichtsjahr St\u00fcckwerk geblieben. Es bleibt das strategische Ziel des Bundesrates, den bilateralen Weg langfristig zu sichern. Der Bundesrat strebt dabei eine L\u00f6sung an, die Zugang zum Binnenmarkt und Rechtssicherheit bietet und innen- wie aussenpolitisch nachhaltig ist. In Bezug auf die Kl\u00e4rung der institutionellen Fragen ist eine n\u00fcchterne Diskussion von Nutzen und Kosten eines entsprechenden Abkommens gefordert, die wirtschaftliche, aussenpolitische und staatspolitische Aspekte miteinbezieht.<\/p>\n<p>Eine verst\u00e4rkt globale Ausrichtung der Schweizer Aussenpolitik wird eine immer wichtigere Erg\u00e4nzung zur Europapolitik. In der Praxis hat sich dabei ein Schwerpunkt in Asien gebildet, wobei 2017 die Beziehungen mit China und Indien im Rahmen von Staats- respektive Pr\u00e4sidialbesuchen vertieft wurden.<\/p>\n<p>Dar\u00fcber hinaus zeigt sich eine st\u00e4rkere Gewichtung der Pr\u00e4vention in der internationalen Friedens- wie auch der Entwicklungsagenda. Dieser Trend spiegelt eine traditionelle Priorit\u00e4t der Schweizer Aussenpolitik. Auch die Nachfrage nach Beitr\u00e4gen der Schweiz an Frieden und Sicherheit bleibt hoch. Dies zeigte sich etwa in den neuen Schutzmachtmandaten mit dem Iran und Saudi-Arabien, in der wichtigen Rolle der Schweiz in Friedensprozessen wie in Mosambik und Kolumbien oder in den Friedensgespr\u00e4chen in der Schweiz zu Syrien und Zypern. Die Wahl eines Schweizers zum Generalsekret\u00e4r der OSZE illustrierte einmal mehr das Potential und die Glaubw\u00fcrdigkeit unseres Landes als Br\u00fcckenbauer in einer zunehmend polarisierten Welt. In einer solchen Welt gewinnt auch die Aussensicherheitspolitik an Bedeutung, wobei das Engagement im Cyberbereich ausgebaut werden soll.<\/p>\n<p>In der Entwicklungszusammenarbeit schliesslich steht die Umsetzung der Botschaft zur internationalen Zusammenarbeit 2017 \u2013 2020 im Fokus. Die Reduktion und Pr\u00e4vention der Ursachen von Flucht und Migration bleibt dabei eine Priorit\u00e4t.<\/p>\n<p>Die Umsetzung der Aussenpolitischen Strategie 2016-2019 wird fortgesetzt. Zu den Zielen f\u00fcr das Jahr 2018 z\u00e4hlen die St\u00e4rkung der Beziehungen der Schweiz zu Europa, ein umfassendes Engagement f\u00fcr mehr Sicherheit sowie eine fundierte Abst\u00fctzung der Aussenpolitik in der Innenpolitik.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>An seiner Sitzung vom 21. Februar 2018 hat der Bundesrat den Aussenpolitischen Bericht 2017 verabschiedet. Der Bericht zieht Bilanz \u00fcber die wichtigsten aussenpolitischen Aktivit\u00e4ten der Schweiz im Jahr 2017 im Kontext der internationalen Entwicklungen<\/p>\n","protected":false},"author":4,"featured_media":162997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-184880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/184880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=184880"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/184880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/162997"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=184880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=184880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=184880"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=184880"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=184880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}