{"id":194871,"date":"2018-05-01T00:39:27","date_gmt":"2018-04-30T22:39:27","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=194871"},"modified":"2018-05-08T10:52:31","modified_gmt":"2018-05-08T08:52:31","slug":"bund-und-kantone-einigen-sich-auf-gemeinsame-integrationsagenda","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/bund-und-kantone-einigen-sich-auf-gemeinsame-integrationsagenda\/","title":{"rendered":"Bund und Kantone einigen sich auf gemeinsame Integrationsagenda"},"content":{"rendered":"<p>Bund und Kantone wollen Fl\u00fcchtlinge und vorl\u00e4ufig aufgenommene Personen rascher in die Arbeitswelt integrieren \u2013 und damit auch deren Abh\u00e4ngigkeit von der Sozialhilfe reduzieren. Zu diesem Zweck haben sie sich auf eine gemeinsame Integrationsagenda geeinigt, die deutlich erh\u00f6hte Investitionen, konkrete Wirkungsziele sowie einen f\u00fcr alle Akteure verbindlichen Integrationsprozess vorsieht. Die Integrationsagenda wurde am 23. M\u00e4rz 2018 von der Konferenz der Kantonsregierungen und in seiner Sitzung vom 25. April vom Bundesrat genehmigt. Dieser hat dabei auch eine Erh\u00f6hung der Integrationspauschale an die Kantone beschlossen. Bund und Kantone wollen zudem die Fehlanreize im Finanzierungssystem des Asylbereichs gemeinsam und rasch angehen.<\/p>\n<p>Mit den beschleunigten Asylverfahren, die im Fr\u00fchjahr 2019 schweizweit eingef\u00fchrt werden, wissen Schutzsuchende rasch, ob sie in der Schweiz bleiben d\u00fcrfen. Dank der Integrationsagenda werden nun die Voraussetzungen geschaffen, dass die Fl\u00fcchtlinge und vorl\u00e4ufig Aufgenommenen rasch Teil unserer Gesellschaft werden und ins Berufsleben einsteigen k\u00f6nnen. Bund und Kantone gehen davon aus, dass rund 70 Prozent aller Fl\u00fcchtlinge und vorl\u00e4ufig aufgenommenen Personen im erwerbsf\u00e4higen Alter das Potenzial haben, sich nachhaltig in den Arbeitsmarkt zu integrieren und l\u00e4ngerfristig f\u00fcr sich und ihre Familien aufzukommen. Mit Hilfe der Integrationsagenda kann dieses inl\u00e4ndische Potenzial besser genutzt werden und die Schweizer Wirtschaft muss weniger Arbeitskr\u00e4fte im Ausland rekrutieren.<\/p>\n<h3>Fr\u00fche und verbindliche Integration<\/h3>\n<p>Die Integrationsagenda von Bund und Kantonen legt verbindliche Wirkungsziele fest, die durch einen f\u00fcr alle Kantone geltenden Integrationsprozess erreicht werden sollen. Zu diesen Zielsetzungen geh\u00f6rt, dass alle Fl\u00fcchtlinge und vorl\u00e4ufig Aufgenommene nach drei Jahren Grundkenntnisse einer Landessprache haben. Zudem ist mindestens die H\u00e4lfte aller erwachsenen Personen nach sieben Jahren im Arbeitsmarkt integriert. Dieser Integrationsprozess setzt bereits kurz nach der Einreise ein und sieht konkrete F\u00f6rdermassnahmen vor, z.B. beim Spracherwerb, der Vorbereitung auf nachobligatorische Bildungsangebote sowie bei der beruflichen und gesellschaftlichen Integration. Bei allen Fl\u00fcchtlingen und vorl\u00e4ufig Aufgenommenen im erwerbsf\u00e4higen Alter wird k\u00fcnftig eine vertiefte Potenzialabkl\u00e4rung vorgenommen. Sie werden zudem w\u00e4hrend des ganzen Integrationsprozesses durch eine Fachperson verbindlich begleitet und beraten.<\/p>\n<h3>Lohnende Investition<\/h3>\n<p>Um die Finanzierung dieser F\u00f6rdermassnahmen zu sichern, erhalten die Kantone k\u00fcnftig vom Bund eine einmalige Integrationspauschale von 18\u00a0000 Franken pro Person. Umfassende Erhebungen in den Kantonen und gemeinsame Berechnungen haben gezeigt, dass der angestrebte Integrationsprozess diese zus\u00e4tzlichen Mittel erfordert. In einem zweiten Schritt haben sich Bund und Kantone darauf verst\u00e4ndigt, die Finanzierung der Unterbringung, Betreuung und Integration im Fl\u00fcchtlings- und Asylbereich in den n\u00e4chsten zwei Jahren insgesamt zu \u00fcberpr\u00fcfen. Ziel ist es, das Finanzierungssystem zu vereinfachen, Bund und Kantone administrativ zu entlasten und verst\u00e4rkt Integrationsanreize zu setzen. Der Bundesrat erwartet zudem, dass sich damit die heute bestehenden Unterschiede zwischen den Kantonen in Bezug auf die Integrationsmassnahmen und deren Wirkung angleichen.<\/p>\n<p>Ausgehend von rund 11\u00a0000 anerkannten Fl\u00fcchtlingen und vorl\u00e4ufig aufgenommenen Personen pro Jahr, f\u00fchrt dieses Vorgehen beim Bund kurzfristig zu j\u00e4hrlichen Mehrausgaben von 132 Mio. Franken. Berechnungen zeigen, dass die \u00f6ffentliche Hand pro eingesetzten Franken durch die Integrationsagenda bei Personen im arbeitsf\u00e4higen Alter auf lange Sicht bis zu vier Franken einspart. Die Modellrechnungen ergeben, dass beispielsweise bei erwachsenen Personen (26-49 Jahre), die dank der Integrationsagenda rascher in der Berufswelt Fuss fassen, die \u00f6ffentliche Hand durchschnittlich rund 90 000 Franken pro Person einsparen kann. Die Sozialhilfe und auch der Bildungsbereich werden durch die Massnahmen entlastet. Die Integrationsleistungen, die der Bildungsbereich heute f\u00fcr diese Zielgruppe erbringt, sind jedoch nicht Teil der Integrationsagenda.<\/p>\n<p>Die Integrationsagenda beschr\u00e4nkt sich auf den Asylbereich. Bis Ende 2019 soll zus\u00e4tzlich die Frage gekl\u00e4rt werden, wie Integrationsvorleistungen f\u00fcr Jugendliche und junge Erwachsene, die nicht als Asylsuchende in die Schweiz kommen, organisiert und finanziert werden.<\/p>\n<h3>Zus\u00e4tzliche Mittel f\u00fcr unbegleitete minderj\u00e4hrige Personen<\/h3>\n<p>Parallel zur Integrationsagenda haben sich Bund und Kantone auch auf ein System zur fairen Abgeltung der Kosten f\u00fcr unbegleitete minderj\u00e4hrige Personen aus dem Asylbereich (MNA) geeinigt. Diese junge Menschen, die ohne famili\u00e4re Bindung in der Schweiz Schutz suchen, haben aufgrund ihres Alters, ihres Entwicklungs- und Bildungsstands und ihrer Verletzlichkeit besondere Bed\u00fcrfnisse bei der Unterbringung und Betreuung als erwachsene Asylsuchende. Das f\u00fchrt zu h\u00f6heren Kosten in den Kantonen. Eine angemessene Unterbringung und Betreuung von MNA im Asyl- und Fl\u00fcchtlingsbereich stellt aber eine wichtige Voraussetzung f\u00fcr das Gelingen der Integration dieser jungen Personen dar.<\/p>\n<p>Deshalb haben Bund und Kantone die entstehenden Zusatzkosten in enger Koordination mit der Integrationsagenda gemeinsam ermittelt. Demnach betragen die anrechenbaren Kosten f\u00fcr Betreuung und Sozialhilfe insgesamt 100 Franken pro Tag und MNA. Davon soll der Bund k\u00fcnftig 86 Franken \u00fcbernehmen. Der Bundesrat hat heute ebenfalls entschieden, die Subventionen f\u00fcr die Kantone f\u00fcr MNA entsprechend zu erh\u00f6hen. Er hat ein Modell gutgeheissen, das auf der Zahl von MNA basiert, die sich zu einem bestimmten Zeitpunkt in der Schweiz aufhalten. F\u00fcr das Jahr 2018 w\u00fcrden die zus\u00e4tzlichen Subventionen des Bundes an die Kantone &#8211; anhand des Bestandes per Ende Januar 2018 berechnet &#8211; rund 30 Millionen Franken betragen.<\/p>\n<p class=\"nsbtextkasten\">Die Integrationsagenda wurde seit M\u00e4rz 2017 gemeinsam von den zust\u00e4ndigen Departementen beim Bund (Eidgen\u00f6ssisches Justiz- und Polizeidepartement EJPD und Eidgen\u00f6ssisches Departement f\u00fcr Wirtschaft, Bildung und Forschung WBF) sowie den zust\u00e4ndigen kantonalen Regierungskonferenzen (Konferenz der Kantonsregierungen KdK, Konferenz der kantonalen Sozialdirektorinnen und Sozialdirektoren SODK sowie die Konferenz der kantonalen Erziehungsdirektoren EDK) erarbeitet. Sie soll im Fr\u00fchjahr 2019 umgesetzt werden.<\/p>\n<p><a href=\"https:\/\/www.admin.ch\/gov\/de\/start\/dokumentation\/medienmitteilungen.msg-id-70617.html\">admin.ch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bund und Kantone wollen Fl\u00fcchtlinge und vorl\u00e4ufig aufgenommene Personen rascher in die Arbeitswelt integrieren \u2013 und damit auch deren Abh\u00e4ngigkeit von der Sozialhilfe reduzieren. Zu diesem Zweck haben sie sich auf eine gemeinsame Integrationsagenda geeinigt, die deutlich erh\u00f6hte Investitionen, konkrete Wirkungsziele sowie einen f\u00fcr alle Akteure verbindlichen Integrationsprozess vorsieht. Die Integrationsagenda wurde am 23. M\u00e4rz [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":185583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-194871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/194871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=194871"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/194871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/185583"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=194871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=194871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=194871"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=194871"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=194871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}