{"id":206851,"date":"2018-07-17T11:13:56","date_gmt":"2018-07-17T09:13:56","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=206851"},"modified":"2018-07-17T11:14:36","modified_gmt":"2018-07-17T09:14:36","slug":"verhandlungen-ueber-ein-rahmenwerk-fuer-die-globale-koordination-der-migration-erfolgreich-abgeschlossen","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/verhandlungen-ueber-ein-rahmenwerk-fuer-die-globale-koordination-der-migration-erfolgreich-abgeschlossen\/","title":{"rendered":"Verhandlungen \u00fcber ein Rahmenwerk f\u00fcr die globale Koordination der Migration erfolgreich abgeschlossen"},"content":{"rendered":"<p>Beauftragt vom Pr\u00e4sidenten der UNO-Generalversammlung haben der Schweizer UNO-Botschafter in New York, J\u00fcrg Lauber, und sein mexikanischer Kollege Juan Jos\u00e9 G\u00f3mez Camacho, in den vergangenen 15 Monaten Beitr\u00e4ge und Erfahrungen der Staaten zum Thema Migration gesammelt, einen ersten Entwurf f\u00fcr ein Rahmenwerk f\u00fcr die globale Koordination der Migration ausgearbeitet und mit der Staatengemeinschaft konsultiert. Mit der Zustimmung der UNO-Mitgliedstaaten zu diesem Entwurf endet die Verhandlungsphase f\u00fcr den neuen \u00abGlobal Compact\u00bb f\u00fcr Migration. Im Dezember 2018 soll der Text an der intergouvernementalen Konferenz in Marrakesch (Marokko) den Staats- und Regierungschefs der 193 UNO-Staaten zur Verabschiedung vorgelegt werden.<\/p>\n<p>Mit dem Abschluss der Verhandlungen zum Globalen Pakt haben sich die UNO-Mitgliedstaaten gemeinsam auf einen praktisch anwendbaren Handlungsrahmen geeinigt, welcher die internationale Zusammenarbeit in allen Bereichen der Migrationsgouvernanz verst\u00e4rkt und eine langfristige Verankerung und regelm\u00e4ssige \u00dcberpr\u00fcfung der Migrationsthematik im Rahmen der UNO vorsieht. Das Dokument enth\u00e4lt zehn Grunds\u00e4tze (z.B. die uneingeschr\u00e4nkte G\u00fcltigkeit der Menschenrechte f\u00fcr alle Migranten; das souver\u00e4ne Recht der Staaten, ihre eigene Migrationspolitik zu bestimmen), 23 Zielformulierungen und jeweils eine Liste mit Massnahmen zur Zielerreichung. W\u00e4hrend die Zielvorgaben das gemeinsame Bekenntnis aller Staaten widerspiegeln, stellen die Massnahmen m\u00f6gliche Instrumente dar, welche die Staaten gem\u00e4ss ihren Priorit\u00e4ten und Kapazit\u00e4ten eigenst\u00e4ndig umsetzen k\u00f6nnen. Zudem dient der Globale Pakt als Referenzdokument f\u00fcr eine verst\u00e4rkte Zusammenarbeit zwischen den Staaten aber auch mit anderen Akteuren wie dem Privatsektor oder der Zivilgesellschaft.<\/p>\n<p>Aus Schweizer Sicht stellt der Abschluss der Verhandlungen zum \u00abGlobal Compact for Safe, Orderly and Regular Migration\u00bb ein Bekenntnis der Staaten dar, dass kein Staat alleine die Komplexit\u00e4t der Migration bew\u00e4ltigen kann. Die UNO ist somit der richtige Ort, um Migration umfassend aus einer globalen und inklusiven Perspektive gemeinsam anzugehen. Mit der Co-Leitung im Verhandlungsprozess durch Botschafter J\u00fcrg Lauber konnte die Schweiz ausserdem die Chance nutzen, an einem bedeutenden UNO-Prozess zu einer relevanten Frage unserer Zeit an zentraler Stelle mitzuwirken, und \u00fcberdies ihre Rolle im internationalen System mit viel Glaubw\u00fcrdigkeit aus\u00fcben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Schweiz begr\u00fcsst die Zustimmung der UNO-Mitgliedstaaten zum Entwurf des \u00abGlobalen Paktes f\u00fcr sichere, geordnete und regul\u00e4re Migration\u00bb. Der Abschluss der Verhandlungen ist ein wichtiger Schritt auf dem Weg zu gemeinsamen Standards der Staaten, um die positiven Aspekte der Migration zu st\u00e4rken und die negativen Seiten durch gemeinsame Anstrengungen einzud\u00e4mmen. Die Schweiz und Mexiko haben den Verhandlungsprozess geleitet, der nun erfolgreich beendet werden konnte.<\/p>\n","protected":false},"author":10,"featured_media":43503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1188,1141,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-206851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shkurt-ch-de","category-themen","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/206851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=206851"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/206851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/43503"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=206851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=206851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=206851"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=206851"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=206851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}