{"id":257075,"date":"2019-03-13T09:00:14","date_gmt":"2019-03-13T08:00:14","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=257075"},"modified":"2019-03-15T00:23:29","modified_gmt":"2019-03-14T23:23:29","slug":"erleichterte-einbuergerung-von-jugendlichen-der-3-generation-die-ekm-zieht-bilanz","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/erleichterte-einbuergerung-von-jugendlichen-der-3-generation-die-ekm-zieht-bilanz\/","title":{"rendered":"Erleichterte Einb\u00fcrgerung von Jugendlichen der 3. Generation: Die EKM zieht Bilanz"},"content":{"rendered":"<p><strong>Seit dem 15. Februar 2018 k\u00f6nnen sich Ausl\u00e4nderinnen und Ausl\u00e4nder, deren Grosseltern bereits in der Schweiz gelebt haben, erleichtert einb\u00fcrgern lassen. Die Eidgen\u00f6ssische Migrationskommission EKM hat eine Erhebung in Auftrag gegeben. Der Bericht zieht nach einem Jahr Bilanz: Von rund 25 000 jungen Ausl\u00e4nderinnen und Ausl\u00e4ndern, die zur dritten Generation gez\u00e4hlt werden, haben im ersten Jahr circa 3000 Personen ein klares Interesse an der Einb\u00fcrgerung gezeigt, 1065 Gesuche wurden eingereicht und 309 Personen erhielten \u00fcber diesen Weg die Staatsb\u00fcrgerschaft. Der Nachweis, dass ein Elternteil f\u00fcnf Jahre die obligatorische Schule besucht haben muss, zeigte sich als Stolperstein. Diese Anforderung steht im Widerspruch zur damaligen Einwanderungsrealit\u00e4t der Grosseltern.<\/strong><\/p>\n<p>Von den 1065 Antr\u00e4gen entfallen knapp 80% auf Staatsangeh\u00f6rige aus vier L\u00e4ndern: Italien, T\u00fcrkei, Kosovo und Spanien. 55% der Gesuche wurden von EU\/EFTA-Staatsangeh\u00f6rigen gestellt, bei den Eingeb\u00fcrgerten entfielen 72% auf EU\/EFTA-Staatsangeh\u00f6rige.<\/p>\n<p>Zwei Drittel der Einb\u00fcrgerungsgesuche stammten von Jugendlichen aus sechs Kantonen. Hierbei handelt es sich um Kantone mit einem \u00fcberdurchschnittlich hohen Anteil an Personen ausl\u00e4ndischer Staatsangeh\u00f6rigkeit, die die Voraussetzungen f\u00fcr die Einb\u00fcrgerung erf\u00fcllen. Die kantonalen Einb\u00fcrgerungsgesetze von f\u00fcnf dieser Kantone werden als restriktiv eingestuft. Der Bericht legt nahe, dass mit der erleichterten Einb\u00fcrgerung einb\u00fcrgerungswilligen Jugendlichen und jungen Erwachsenen eine M\u00f6glichkeit gegeben wurde, der restriktiven kantonalen Gesetzgebung auszuweichen.<\/p>\n<h3><strong>Einwanderungsrealit\u00e4t der Grosseltern steht im Widerspruch zu den Anforderungen<\/strong><\/h3>\n<p>Welche Anforderungen bereiteten den potenziellen Gesuchstellenden die gr\u00f6ssten Schwierigkeiten? Der Bericht zeigt auf, dass viele Interessierte nicht nachweisen konnten, dass ein Elternteil f\u00fcnf Jahre die obligatorische Schule in der Schweiz besucht hatte. Dies kann auf die damalige Einwanderungsrealit\u00e4t zur\u00fcckgef\u00fchrt werden. Viele Grosseltern der dritten Ausl\u00e4ndergeneration arbeiteten w\u00e4hrend Jahren als Saisonniers in der Schweiz. Der Familiennachzug war erst m\u00f6glich, nachdem die Saisonbewilligung in eine Aufenthaltsbewilligung umgewandelt worden war. Folglich zeigt sich auch, dass viele Eltern der Betroffenen als Jugendliche in die Schweiz kamen. Sie besuchten nur noch wenige Jahre die obligatorische Schule, h\u00e4ngten jedoch eine Berufsbildung an. Die Anforderungen zur erleichterten Einb\u00fcrgerung sind offensichtlich nicht optimal auf diese Einwanderungsgenerationen ausgerichtet. Die EKM empfiehlt aufgrund dieser Erkenntnis, die Berufsbildung bei den Eltern als Nachweis der Integration ebenfalls zu ber\u00fccksichtigen und die entsprechenden Gesetzesbestimmungen anzupassen.<\/p>\n<h3><strong>Aktive Information zur erleichterten Einb\u00fcrgerung<\/strong><\/h3>\n<p>Der EKM ist es ein grosses Anliegen, das Verfahren transparenter und einfacher zu gestalten und betroffene Personen zu ermutigen, vermehrt von ihrem neuen Recht Gebrauch zu machen. Sie erachtet es daher als wichtig, dass die Gemeinden und Kantone einen aktiven Beitrag bei der Verbreitung der notwendigen Informationen leisten.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von rund 25 000 jungen Ausl\u00e4nderinnen und Ausl\u00e4ndern, die zur dritten Generation gez\u00e4hlt werden, haben im ersten Jahr circa 3000 Personen ein klares Interesse an der Einb\u00fcrgerung gezeigt, 1065 Gesuche wurden eingereicht und 309 Personen erhielten \u00fcber diesen Weg die Staatsb\u00fcrgerschaft<\/p>\n","protected":false},"author":4,"featured_media":257076,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1188,1133,1140],"tags":[1633],"vendi":[],"content_country":[],"class_list":["post-257075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shkurt-ch-de","category-e-diaspora-de","category-leben-in-der-schweiz","tag-zvicer-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/257075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=257075"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/257075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/257076"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=257075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=257075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=257075"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=257075"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=257075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}