{"id":316036,"date":"2019-10-05T15:00:56","date_gmt":"2019-10-05T13:00:56","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=316036"},"modified":"2019-10-05T16:10:12","modified_gmt":"2019-10-05T14:10:12","slug":"also-gehen-sie-waehlen","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/also-gehen-sie-waehlen\/","title":{"rendered":"Also, gehen Sie w\u00e4hlen!"},"content":{"rendered":"<p>Letztes Wochenende hatte ich mit meinem Cousin aus dem Kosovo und meiner Cousine aus der Schweiz \u00fcber die Wahlen gesprochen und beide haben das Gleiche gefragt: \u00abJa, wen soll ich w\u00e4hlen?\u00bb Ich habe geantwortet: \u00abJemanden, der kandidiert!\u00bb Beide haben dann gefragt: \u00abJa schon, aber welchen von den Kandidaten?\u00bb Ach ja, dann ist mir in den Sinn gekommen, dass im Oktober 2019 Wahlen im Kosovo und in der Schweiz stattfinden. Die Schweiz hat eine starke albanische Tradition. So wurden beispielsweise 1431 die albanischen Bisch\u00f6fe an das von der christlichen Kirche organisierte Konzil in Basel eingeladen*. Oder die albanische Elena Gjika war als erste Frau 1855 in die Region des Jungfraujochs im Kanton Bern aufgestiegen*. Viele Tunnels, Br\u00fccken, Strassen und Bahnlinien in der Schweiz w\u00e4ren immer noch nicht fertig, wenn nicht albanische H\u00e4nde mitgebaut h\u00e4tten. Viele Pflegeheime und Spit\u00e4ler in der Schweiz k\u00f6nnten ohne albanische H\u00e4nde nicht funktionieren. Und viele dieser albanischen H\u00e4nde zeigen am Zoll den Schweizer Pass. Die Frage, wen wir w\u00e4hlen sollen, ist also durchaus berechtigt. Die Antwort kann aber nicht ich geben; diese muss jeder f\u00fcr sich beantworten. Was ist dabei wichtig?<\/p>\n<p>Politiker versprechen immer, sich f\u00fcr uns nach den Wahlen einzusetzen. War jemand als Politiker bereits in einem Amt, wird es einfach, weil wir ihn bloss fragen m\u00fcssen: \u00abWarum hast Du das, was Du uns nun versprichst, nicht bereits in den letzten Jahren realisiert?\u00bb Wenn er f\u00fcr uns nichts erreicht hat, wieso sollen wir ihn dann wieder w\u00e4hlen? Er soll uns seine Vorst\u00f6sse in der Politik zeigen, damit wir beurteilen k\u00f6nnen, wie er sich f\u00fcr uns engagiert hat. Wir wollen unsere Politiker nicht an ihren Versprechen, sondern an ihren Taten messen! Bei den Neuen Kandidaten wird das etwas schwieriger, aber auch die k\u00f6nnen zeigen, was sie in der Gemeinde oder im Bezirk erreicht haben.<\/p>\n<p>W\u00e4hlen ist kein einfaches Gesch\u00e4ft. \u00d6sterreich (1978) und Deutschland (2000) beschlossen den Ausstieg aus der Stromproduktion mit Atomkraftwerken. Stattdessen wird heute weltweit Strom mit Kohlekraftwerken produziert, was den CO2-Ausstoss f\u00f6rdert. Damit der CO2-Ausstoss gesenkt werden kann, hat Frankreich beschlossen, eine Steuer auf Flugreisen einzuf\u00fchren. Zwar hat kein Politiker erkl\u00e4rt, wie durch h\u00f6here Steuern weniger CO2 produziert wird. Schweizer Politiker k\u00f6nnen das auch nicht erkl\u00e4ren, aber ein Teil davon sind auch f\u00fcr h\u00f6here Steuern. Eine vierk\u00f6pfige Familie, die ihre Sommerferien im Kosovo verbringen will, muss deshalb mit neuen (wohl zu den bereits zu hohen Flugbillettpreisen hinzukommenden) Flugbillett-Steuern von ca. CHF 240 (4x 30 hin und zur\u00fcck) rechnen oder dann halt mit dem Auto dorthin reisen. Macht das Sinn?<\/p>\n<p>Die Regierung hat an der vierten Vollversammlung des Umweltprogramms der Vereinten Nationen (United Nations Environment Assembly; UNEP) in Nairobi (Kenia, Afrika) im M\u00e4rz 2019 teilgenommen. Die UNEP k\u00fcmmert sich um wichtige Umweltanliegen wie das Problem des weltweiten CO2-Ausstosses. Laut den Berichten der UNEP waren \u00fcber 170 Staaten und rund 5&#8217;000 Teilnehmer an der Versammlung vertreten. Das entspricht wohl 5&#8217;000 Hin- und R\u00fcckreisen mit einer weltweit durchschnittlichen Reisedistanz von wohl 10\u2019000km (= 50&#8217;000&#8217;000 km = 50 Mio km) und einem entsprechenden CO2-Ausstoss. Anstatt durch neue Steuern jedem Reisenden mit kleinem Geldbeutel, der in den Kosovo fliegen will, ca. CHF 30 pro Sitzplatz abzukn\u00f6pfen, w\u00e4re es an der Zeit andere Alternativen zu suchen. Oder auch die Beamten selber f\u00fcr Langstreckenreisen bezahlen lassen. Von den 5000 Teilnehmer waren viele Beamten dabei. W\u00e4ren diese auch geflogen, wenn nicht wir Steuerzahler das Flugticket bezahlt h\u00e4tten oder h\u00e4tten sie auf die CO2-Reise verzichtet, wenn sie das Ticket selber bezahlt h\u00e4tten m\u00fcssen? Manch einer der Bundesbeamten h\u00e4tte dann CO2 gespart und stattdessen seinen Vortrag dem Schweizer Botschafter in Nairobi zugeschickt. Die CO2-Ersparnis durch Reise eines einzigen Bundesbeamten nach Nairobi w\u00e4re wohl gleich viel wert, wie sechs Ferienreisen in den Kosovo!<\/p>\n<p>Ich werde mich h\u00fcten, Ihnen zu sagen, wen Sie w\u00e4hlen sollen. Entscheiden Sie sich f\u00fcr jene, die Ihre Interessen tats\u00e4chlich wahrgenommen haben. Sie k\u00f6nnen nicht viel falsch machen, wenn Sie w\u00e4hlen gehen und wenn Sie einen \u00abWarme-Luft-Politiker\u00bb gew\u00e4hlt haben, k\u00f6nnen Sie das in vier Jahren korrigieren. Sie machen aber alles falsch, wenn Sie von Ihren demokratischen Rechten nicht Gebrauch machen und nicht w\u00e4hlen gehen.<\/p>\n<p>Also, gehen Sie w\u00e4hlen nach Ihrem besten Wissen und Gewissen!<\/p>\n<p>*(Quelle: Albert Ramaj: Die Albaner in der Schweiz)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie machen alles falsch, wenn Sie von Ihren demokratischen Rechten nicht Gebrauch machen und nicht w\u00e4hlen gehen. Also, gehen Sie w\u00e4hlen nach Ihrem besten Wissen und Gewissen!<\/p>\n","protected":false},"author":4,"featured_media":273112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3908],"tags":[],"vendi":[],"content_country":[],"class_list":["post-316036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinungen"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/316036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=316036"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/316036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/273112"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=316036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=316036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=316036"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=316036"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=316036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}