{"id":318007,"date":"2019-10-11T09:30:00","date_gmt":"2019-10-11T07:30:00","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=318007"},"modified":"2019-10-11T08:54:35","modified_gmt":"2019-10-11T06:54:35","slug":"es-ist-zeit","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/es-ist-zeit\/","title":{"rendered":"Es ist Zeit"},"content":{"rendered":"<p>\u201eEs ist Zeit\u201c \u2013 mit diesem Slogan kandidierte ich vor vier Jahren zusammen mit dem Stadtparlamentarier aus Wil (SG) Arber Bullakaj f\u00fcr den Nationalrat. Unsere Botschaft war klar: Obwohl wir Albanerinnen und Albaner eine der gr\u00f6ssten Bev\u00f6lkerungsgruppen in der Schweiz sind, obwohl wir uns politisch engagieren und bem\u00fchen, sind wir im nationalen Parlament nicht vertreten. Das muss endlich aufh\u00f6ren.<\/p>\n<p>Vier Jahre sp\u00e4ter hat sich nur etwas ge\u00e4ndert \u2013 ich kandidiere nicht f\u00fcr den Nationalrat. Die Anzahl albanischst\u00e4mmiger Nationalr\u00e4tinnen und Nationalr\u00e4te ist weiterhin: ein grosse, fette, deprimierende Null. So geht das nicht weiter.<\/p>\n<p>Nat\u00fcrlich gibt es diejenigen, die sagen, daran sehe man nur, dass wir eben noch nicht angekommen seien. Dass wir uns zuwenig integriert haben. Aber das ist Bl\u00f6dsinn. Die Idee einer Demokratie basiert darauf, dass die Leute, die an einem Ort, in einem Land leben, dort \u00fcber die Politik mitbestimmen k\u00f6nnen. Wir Albanerinnen und Albaner sind hier \u2013 manche von uns seit vierzig Jahren oder mehr. Und egal, ob wir urspr\u00fcnglich aus Gjakov\u00eb kommen oder aus Ferizaj, aus Shkup oder Tiran\u00eb, wir geh\u00f6ren zur Schweiz. Und deswegen wollen wir mitreden.<\/p>\n<p>Die Zeichen stehen nicht schlecht: Es stehen einige Albanerinnen und Albaner zur Wahl \u2013 teils in aussichtsreicher Position wie zum Beispiel Ylfete Fanaj in Luzern, Islam Alijaj in Z\u00fcrich oder mein alter Weggef\u00e4hrte Arber Bullakaj in St.Gallen. Dass diese drei alle f\u00fcr die SP kandidieren, ist kein Zufall: Es war die Sozialdemokratie, welche sich schon damals f\u00fcr die Rechte der Albanerinnen und Albaner einsetzte, als wir noch keine Schweizer B\u00fcrger waren.<\/p>\n<p>Was nicht heissen soll, dass wir alle automatisch nur die SP w\u00e4hlen sollten. Genausowenig wie es bedeuten darf, dass wir automatisch jemanden w\u00e4hlen, nur weil wir aufgrund des Namens vermuten, dass diese Person auch \u201ezu uns geh\u00f6rt\u201c &#8211; was auch immer das heissen soll. Jemanden in den Nationalrat zu w\u00e4hlen heisst eben, sich darauf wirklich zu verlassen, dass diese Person sich danach vier Jahre f\u00fcr die Dinge einsetzt, die uns wichtig sind.<\/p>\n<p>Das ist es, was ich den Menschen jeweils sage, wenn sie mich fragen, wen sie denn jetzt w\u00e4hlen sollten. Informiert euch. Geht auf smartvote. Geht auf die Webseiten der Leute. Sprecht sie an, wenn ihr sie bei einer der hunderten Wahlkampfaktionen auf der Strasse seht. Fragt sie nach Dingen, die euch wichtig sind. Lasst euch nicht blenden von denen, die nur so tun, also ob sie sich f\u00fcr eure Interessen einsetzen \u2013 wie der SVP-Nationalrat Alfred Heer in Z\u00fcrich, der sich pl\u00f6tzlich auch als \u201eFreund des albanischen Volkes\u201c inszeniert, weil er gemerkt hat, dass er vielleicht Geld verdienen kann, dort, wo unsere Cousins und Grosseltern noch wohnen.<\/p>\n<p>Doch egal, was ihr tut: Geht w\u00e4hlen. Wenn ihr nicht wisst, wie man die Unterlagen ausf\u00fcllt, fragt jemanden. Verpasst die Chance nicht. Denn nur wenn wir die Chance nutzen, k\u00f6nnen wir am 20. Oktober die erste albanische Nationalr\u00e4tin, den ersten albanischen Nationalrat feiern. Und glaubt mir, wenn ich sage: Es ist Zeit.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wir geh\u00f6ren zur Schweiz<\/strong><\/p>\n<p><strong>Die Idee einer Demokratie basiert darauf, dass die Leute, die an einem Ort, in einem Land leben, dort \u00fcber die Politik mitbestimmen k\u00f6nnen. Wir Albanerinnen und Albaner sind hier \u2013 manche von uns seit vierzig Jahren oder mehr. Und egal, ob wir urspr\u00fcnglich aus Gjakov\u00eb kommen oder aus Ferizaj, aus Shkup oder Tiran\u00eb, wir geh\u00f6ren zur Schweiz. Und deswegen wollen wir mitreden.<\/strong><\/p>\n<ul>\n<li><strong>Dieser Beitrag wurde speziel f\u00fcr albinfo.ch geschrieben<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geht w\u00e4hlen! Denn nur wenn wir die Chance nutzen, k\u00f6nnen wir am 20. Oktober die erste albanische Nationalr\u00e4tin, den ersten albanischen Nationalrat feiern. Und glaubt mir, wenn ich sage: Es ist Zeit<\/p>\n","protected":false},"author":4,"featured_media":318008,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,3908,1140],"tags":[],"vendi":[],"content_country":[],"class_list":["post-318007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-meinungen","category-leben-in-der-schweiz"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/318007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=318007"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/318007\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/318008"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=318007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=318007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=318007"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=318007"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=318007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}