{"id":318526,"date":"2019-10-12T21:35:07","date_gmt":"2019-10-12T19:35:07","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=318526"},"modified":"2019-10-14T22:55:31","modified_gmt":"2019-10-14T20:55:31","slug":"mach-mit-bei-einer-wissenschaftlichen-umfrage-ueber-identitaeten-und-politik","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/mach-mit-bei-einer-wissenschaftlichen-umfrage-ueber-identitaeten-und-politik\/","title":{"rendered":"Mach mit bei einer wissenschaftlichen Umfrage \u00fcber Identit\u00e4ten und Politik"},"content":{"rendered":"<p>Personen mit albanischem Migrationshintergrund sind herzlich eingeladen, bei einer Umfrage zu Identit\u00e4ten und politischer Integration teilzunehmen. Die Umfrage ist Teil eines vom Bund finanzierten und von der Universit\u00e4t Z\u00fcrich durchgef\u00fchrten Forschungsprojektes, welches sich mit allen Migrantengruppen befasst.<\/p>\n<p>Uns interessiert dabei wie Integration in den politischen Prozess mit Identit\u00e4ten, Kultur sowie religi\u00f6sem Glauben und gesellschaftlichen Werten zusammenh\u00e4ngt. Die aktuelle Umfrage dauert ca. 9 Minuten und richtet sich an alle Personen albanischer Herkunft, unabh\u00e4ngig davon ob man sich f\u00fcr Politik interessiert oder nicht.<\/p>\n<p>Als Dank erhalten alle Teilnehmer und Teilnehmerinnen die M\u00f6glichkeit, 2 Franken an eine wohlt\u00e4tige Organisation zu spenden. Die Umfrage ist nat\u00fcrlich anonym und erf\u00fcllt die ethischen Kriterien der Universit\u00e4t Z\u00fcrich. Deine Teilnahme hilft uns die komplexe und sich wandelnde Schweizer Gesellschaft besser zu verstehen.<\/p>\n<p>Hier der Link zur Umfrage:\u00a0<a href=\"https:\/\/ipz.qualtrics.com\/jfe\/form\/SV_1EThmUL7O9lBCSx\">LINK<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personen mit albanischem Migrationshintergrund sind herzlich eingeladen, bei einer Umfrage zu Identit\u00e4ten und politischer Integration teilzunehmen. Die Umfrage ist Teil eines vom Bund finanzierten und von der Universit\u00e4t Z\u00fcrich durchgef\u00fchrten Forschungsprojektes, welches sich mit allen Migrantengruppen befasst. Uns interessiert dabei wie Integration in den politischen Prozess mit Identit\u00e4ten, Kultur sowie religi\u00f6sem Glauben und gesellschaftlichen Werten [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":318523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1133,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-318526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-e-diaspora-de","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/318526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=318526"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/318526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/318523"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=318526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=318526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=318526"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=318526"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=318526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}