{"id":364597,"date":"2020-03-21T07:56:28","date_gmt":"2020-03-21T06:56:28","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=364597"},"modified":"2020-03-21T07:58:41","modified_gmt":"2020-03-21T06:58:41","slug":"bundespraesidentin-sommaruga-wir-liebe-mitbuergerinnen-und-mitbuerger-haben-es-in-der-hand","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/bundespraesidentin-sommaruga-wir-liebe-mitbuergerinnen-und-mitbuerger-haben-es-in-der-hand\/","title":{"rendered":"Bundespr\u00e4sidentin Sommaruga: \u00abWir, liebe Mitb\u00fcrgerinnen und Mitb\u00fcrger, haben es in der Hand\u00bb"},"content":{"rendered":"<p>Liebe Mitb\u00fcrgerinnen und Mitb\u00fcrger<\/p>\n<p>Unser Leben hat sich \u00fcber Nacht ver\u00e4ndert. Schulen, Kinos und L\u00e4den sind geschlossen, Veranstaltungen verboten. \u00c4ltere und kranke Menschen bleiben zuhause. Viele Berufst\u00e4tige arbeiten von daheim aus. Im B\u00fcro oder auf der Strasse kommen wir uns nicht n\u00e4her als zwei Meter. Ansammlungen von mehr als f\u00fcnf Personen sind draussen verboten.<\/p>\n<p>Diese Regeln sind wichtig. Denn sie retten Leben. Darum m\u00fcssen wir sie unbedingt einhalten. Nur so k\u00f6nnen wir Ansteckungen vermeiden und die Verbreitung des Corona-Virus verlangsamen. Und das ist jetzt entscheidend. Wenn sich das Virus zu schnell verbreitet, sind die Intensivstationen in unseren Spit\u00e4lern \u00fcberlastet. Die Folgen k\u00f6nnen verheerend sein. Jetzt kommt es auf uns alle an.<\/p>\n<p>Die Opferzahlen in der Schweiz steigen. Das tut weh. Bund, Kantone und Gemeinden arbeiten Tag und Nacht an L\u00f6sungen. Es ist aber wie so h\u00e4ufig in unserem Land: Es braucht die Bev\u00f6lkerung.<\/p>\n<p>Wir, liebe Mitb\u00fcrgerinnen und Mitb\u00fcrger, haben es in der Hand. Im Namen des Bundesrats rufe ich Sie deshalb auf: Bleiben Sie daheim, wenn Sie \u00e4lter als 65 oder krank sind. Bleiben Sie auf Distanz zu anderen Menschen. So helfen Sie sich. Und so helfen Sie den anderen.<\/p>\n<p>Die Beh\u00f6rden lassen die Bev\u00f6lkerung nicht allein. Wir k\u00fcmmern uns um Betriebe und Arbeitspl\u00e4tze. Der Bundesrat hilft Unternehmen, Angestellten und Freischaffenden, die um ihre Existenz k\u00e4mpfen. Er sorgt daf\u00fcr, dass L\u00f6hne bezahlt werden k\u00f6nnen und Firmen Kredite erhalten. Mehr als 40 Milliarden Franken stehen ab sofort zur Verf\u00fcgung, rasch und unb\u00fcrokratisch.<\/p>\n<p>Ein riesengrosses Dankesch\u00f6n! Nicht alle Menschen k\u00f6nnen zu Hause bleiben. Wir brauchen das Gesundheitspersonal, die P\u00f6stler, die Verk\u00e4uferinnen, die Lastwagenfahrer, Bus-Chauffeure, unsere B\u00e4uerinnen und Bauern, die Armeeangeh\u00f6rigen: Sie schauen, dass die Versorgung auch weiterhin funktioniert. Ihnen geb\u00fchrt ein riesengrosses Dankesch\u00f6n! Genau das hat die Schweiz immer ausgezeichnet. Wenn es darauf ankommt, sind wir mehr als 26 Kantone und 8,5 Millionen Menschen. Wir sind ein Land. Und wir sind f\u00fcreinander da.<\/p>\n<p>Ihre<\/p>\n<p>Simonetta Sommaruga<\/p>\n<p>Bundespr\u00e4sidentin<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In ihrem Offenen Brief dankt Bundespr\u00e4sidentin Simonetta Sommaruga unter anderem allen B\u00fcrgerinnen und B\u00fcrgern, die daf\u00fcr sorgen, dass die Versorgung des Landes trotz der anhaltenden Krise weiter funktioniert.\u00a0<\/p>\n","protected":false},"author":4,"featured_media":364595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22520,24006,1140],"tags":[],"vendi":[],"content_country":[],"class_list":["post-364597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus-minute-fuer-minute","category-lajme-jeta-ne-zvicer-de","category-leben-in-der-schweiz"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/364597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=364597"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/364597\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/364595"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=364597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=364597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=364597"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=364597"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=364597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}