{"id":366693,"date":"2020-03-29T01:22:55","date_gmt":"2020-03-29T00:22:55","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=366693"},"modified":"2020-03-29T01:22:55","modified_gmt":"2020-03-29T00:22:55","slug":"coronavirus-kantone-koennen-in-ausnahmefaellen-kurzzeitig-zusaetzliche-massnahmen-beantragen","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/coronavirus-kantone-koennen-in-ausnahmefaellen-kurzzeitig-zusaetzliche-massnahmen-beantragen\/","title":{"rendered":"Coronavirus: Kantone k\u00f6nnen in Ausnahmef\u00e4llen kurzzeitig zus\u00e4tzliche Massnahmen beantragen"},"content":{"rendered":"<p>Der Bundesrat kann den Kantonen im Kampf gegen das Coronavirus erlauben, kurzzeitig die T\u00e4tigkeit bestimmter Wirtschaftsbranchen einzuschr\u00e4nken oder einzustellen, wenn die epidemiologische Situation dies erfordert. An seiner Sitzung vom 27. M\u00e4rz 2020 hat er eine Anpassung der entsprechenden Verordnung beschlossen.<\/p>\n<p>Wenn aufgrund der epidemiologischen Situation eine besondere Gefahr f\u00fcr die Gesundheit der Bev\u00f6lkerung besteht, kann der Bundesrat einem Kanton erlauben, kurzzeitig die T\u00e4tigkeit ganzer Wirtschaftsbranchen einzuschr\u00e4nken oder einzustellen. Betriebe, die glaubhaft die Massnahmen zum Abstandhalten und zur Hygiene erf\u00fcllen, k\u00f6nnen ihren Betrieb allerdings weiterf\u00fchren.<\/p>\n<p>Voraussetzung f\u00fcr ein Gesuch ist, dass im Kanton die Kapazit\u00e4ten in der Gesundheitsversorgung auch nach Unterst\u00fctzung durch andere Kantone nicht mehr ausreichen. Voraussetzung ist auch, dass die betroffenen Wirtschaftsbranchen mit hoher Wahrscheinlichkeit nicht in der Lage sind, die Pr\u00e4ventionsmassnahmen einzuhalten und nicht mehr voll funktionsf\u00e4hig sind, weil Grenzg\u00e4nger ausbleiben. Ausserdem m\u00fcssen die Sozialpartner dem Entscheid zustimmen und die Versorgung der Bev\u00f6lkerung mit G\u00fctern des t\u00e4glichen Bedarfs sowie der Gesundheitseinrichtungen muss sichergestellt sein. Gehen die von einem Kanton getroffenen Massnahmen \u00fcber die Erm\u00e4chtigung des Bundesrates hinaus, so entf\u00e4llt die Kurzarbeitszeitentsch\u00e4digung des Bundes.<\/p>\n<p>Hintergrund dieser Regelung ist ein Entscheid des Kantons Tessin, Betriebe und Baustellen f\u00fcr eine befristete Dauer zu schliessen. Der Bundesrat hatte am 20. M\u00e4rz beschlossen, dass die Kantone lediglich einzelne Betriebe oder Baustellen schliessen k\u00f6nnen, welche die Massnahmen zum Abstandhalten und zur Hygiene nicht einhalten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hintergrund dieser Regelung ist ein Entscheid des Kantons Tessin, Betriebe und Baustellen f\u00fcr eine befristete Dauer zu schliessen<\/p>\n","protected":false},"author":4,"featured_media":366694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22520,24006,1140],"tags":[],"vendi":[],"content_country":[],"class_list":["post-366693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus-minute-fuer-minute","category-lajme-jeta-ne-zvicer-de","category-leben-in-der-schweiz"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/366693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=366693"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/366693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/366694"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=366693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=366693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=366693"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=366693"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=366693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}