{"id":368464,"date":"2020-04-03T22:56:30","date_gmt":"2020-04-03T20:56:30","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=368464"},"modified":"2020-04-03T22:57:21","modified_gmt":"2020-04-03T20:57:21","slug":"coronavirus-bundesrat-regelt-versorgung-mit-wichtigen-medizinischen-guetern","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/coronavirus-bundesrat-regelt-versorgung-mit-wichtigen-medizinischen-guetern\/","title":{"rendered":"Coronavirus: Bundesrat regelt Versorgung mit wichtigen medizinischen G\u00fctern"},"content":{"rendered":"<p>Der Bundesrat \u00fcbertr\u00e4gt dem Bund mehr Kompetenzen, um die Versorgung mit wichtigen medizinischen G\u00fctern zur Bek\u00e4mpfung des Coronavirus zu koordinieren. Dies hat er an seiner Sitzung vom 3. April 2020 beschlossen. So werden etwa die Kantone verpflichtet, ihre aktuellen Materialbest\u00e4nde zu melden.<\/p>\n<p>Mit der Meldepflicht wird der Bestand an wichtigen Heilmitteln und medizinischen G\u00fctern erhoben. Damit k\u00f6nnen Versorgungsengp\u00e4sse fr\u00fchzeitig festgestellt und gezielt behoben werden. Die wichtigen medizinischen G\u00fcter werden in der COVID-19-Verordnung 2 aufgelistet, wie zum Beispiel Beatmungsger\u00e4te, Diagnosetests, chirurgische Masken oder Schutzanz\u00fcge sowie gewisse Arzneimittel.<\/p>\n<p>Der Bundesrat hat auch geregelt, wie der Bund die Kantone sowie gemeinn\u00fctzige Organisationen wie das Schweizerische Rote Kreuz in der Beschaffung von wichtigen medizinischen G\u00fctern unterst\u00fctzt, falls der Bedarf \u00fcber die normalen Beschaffungskan\u00e4le nicht gedeckt werden kann. Die Zuteilung des Materials erfolgt anschliessend zentral.<\/p>\n<p>Um einen raschen Zugang zu neuen, vielversprechenden Therapien sowie zu dringend ben\u00f6tigten Medizinprodukten zu gew\u00e4hrleisten, hat der Bundesrat zudem eine Reihe von Ausnahmen zu bestehenden heilmittelrechtlichen Regelungen beschlossen.<\/p>\n<p>Einschr\u00e4nkungen des Kantons Tessin verl\u00e4ngert<br \/>\nDer Bundesrat hat zudem aufgrund der epidemiologischen Situation den Kanton Tessin erm\u00e4chtigt, die Einschr\u00e4nkungen von Wirtschaftsbranchen bis am 13. April zu verl\u00e4ngern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die wichtigen medizinischen G\u00fcter werden in der COVID-19-Verordnung 2 aufgelistet, wie zum Beispiel Beatmungsger\u00e4te, Diagnosetests, chirurgische Masken oder Schutzanz\u00fcge sowie gewisse Arzneimittel<\/p>\n","protected":false},"author":4,"featured_media":364950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,22520,1140],"tags":[],"vendi":[],"content_country":[],"class_list":["post-368464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-coronavirus-minute-fuer-minute","category-leben-in-der-schweiz"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/368464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=368464"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/368464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/364950"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=368464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=368464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=368464"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=368464"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=368464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}