{"id":380432,"date":"2020-05-22T18:45:33","date_gmt":"2020-05-22T16:45:33","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=380432"},"modified":"2020-05-22T18:47:22","modified_gmt":"2020-05-22T16:47:22","slug":"zusaetzliche-finanzierung-fuer-die-arbeitslosenversicherung-und-schrittweiser-ausstieg-aus-den-covid-massnahmen","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/zusaetzliche-finanzierung-fuer-die-arbeitslosenversicherung-und-schrittweiser-ausstieg-aus-den-covid-massnahmen\/","title":{"rendered":"Zus\u00e4tzliche Finanzierung f\u00fcr die Arbeitslosenversicherung"},"content":{"rendered":"<div class=\"contentHead\">Die Voranmeldungen f\u00fcr Kurzarbeit haben seit Mitte M\u00e4rz 2020 sprunghaft zugenommen. Bisher haben etwa 190\u00a0000 Unternehmen f\u00fcr rund 1,94 Mio. Arbeitnehmende Kurzarbeitsentsch\u00e4digung beantragt. Dies entspricht rund 37% aller angestellten Personen in der Schweiz. Die Voranmeldungen f\u00fcr Kurzarbeit haben sich in der Zwischenzeit stabilisiert.<\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p>Die Zunahme der Kurzarbeit hat aber dazu gef\u00fchrt, dass sich die Arbeitslosenversicherung in k\u00fcrzester Zeit erheblich verschuldet hat. Ohne rasche Zusatzfinanzierung wird sie Ende 2020 sch\u00e4tzungsweise Schulden von \u00fcber 16 Milliarden Franken aufweisen. Somit w\u00fcrde die gesetzlich festgehaltene Schuldenbremse ausgel\u00f6st. Die Arbeitslosenversicherung w\u00e4re dann verpflichtet, eine Gesetzesrevision zur finanziellen Stabilisierung durchzuf\u00fchren. Sie w\u00e4re auch verpflichtet, bereits 2021 die Lohnprozente um mindestens 0,3 Prozentpunkte zu erh\u00f6hen. Der Bundesrat will dies in der aktuell schwierigen Situation vermeiden und sicherstellen, dass die Arbeitslosenversicherung weiterhin ihre Funktion als konjunkturelle Stabilisatorin wahrnehmen kann. Deshalb soll der Bund f\u00fcr das laufende Jahr die Kosten der Kurzarbeitsentsch\u00e4digungen \u00fcbernehmen. Dem Parlament wird dazu ein ausserordentlicher Nachtragskredit von 14,2 Milliarden Franken unterbreitet.<\/p>\n<p>Weiter befasste sich der Bundesrat am 20. Mai 2020 mit dem schrittweisen Ausstieg aus den COVID-Massnahmen. Diese dienten der Abschw\u00e4chung negativer Auswirkungen auf Arbeitnehmende infolge der beh\u00f6rdlichen Verbote und Anordnungen im Rahmen der ausserordentlichen Lage gem\u00e4ss Epidemiengesetz.<\/p>\n<p>Sie haben dazu beigetragen, Arbeitspl\u00e4tze und Einkommen zu erhalten und den betroffenen Betrieben unb\u00fcrokratisch und so rasch wie m\u00f6glich Zahlungen zu gew\u00e4hrleisten. Ebenso wurden die kantonalen Durchf\u00fchrungsstellen der Arbeitslosenversicherung administrativ entlastet.<\/p>\n<p>Die notrechtlich verordneten Massnahmen werden in Abstimmung mit den Lockerungsetappen zur \u00d6ffnung der Wirtschaft schrittweise aufgehoben.<\/p>\n<ul>\n<li>F\u00fcr Personen in arbeitgeber\u00e4hnlicher Stellung sowie mitarbeitende Ehegatten oder eingetragene Partner und Partnerinnen entf\u00e4llt der ausserordentliche Anspruch auf Kurzarbeit auf Ende Mai. Dies entspricht ungef\u00e4hr dem Ende der COVID-Massnahmen f\u00fcr Erwerbsausf\u00e4lle f\u00fcr direkt oder indirekt betroffene Selbst\u00e4ndigerwerbende, die am 16.\u00a0Mai aufgehoben wurden.<\/li>\n<li>Zum gleichen Zeitpunkt erlischt auch der Anspruch auf Kurzarbeit f\u00fcr Lernende. Im Vordergrund steht hier eine m\u00f6glichst rasche Fortsetzung der Ausbildung.<\/li>\n<li>Weiter wird auch die Voranmeldefrist wieder eingef\u00fchrt. Diese wurde aufgehoben, da die verordneten Einschr\u00e4nkungen f\u00fcr Unternehmen nicht vorhersehbar waren. Unterdessen sind die bundesr\u00e4tlichen Massnahmen bekannt und deren Auswirkungen auf die Betriebe besser einsch\u00e4tzbar. F\u00fcr die Unternehmen ist es somit m\u00f6glich, die Voranmeldung unter Einhaltung der Voranmeldefrist vorzunehmen. Unternehmen, f\u00fcr welche Kurzarbeit bereits bewilligt wurde, m\u00fcssen aufgrund dieser Anpassung kein neues Gesuch einreichen.<\/li>\n<\/ul>\n<p>Die \u00fcbrigen notrechtlichen Massnahmen enden wie vorgesehen per 31. August 2020 mit dem Ablauf der Verordnung \u00fcber Massnahmen im Bereich der Arbeitslosenversicherung im Zusammenhang mit dem Coronavirus (COVID-19). Es bleibt den Unternehmen weiterhin m\u00f6glich, aufgrund des Coronavirus das Instrument der Kurzarbeit zu nutzen, um Arbeitspl\u00e4tze zu erhalten.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der Bundesrat hat am 20. Mai 2020 eine Zusatzfinanzierung der Arbeitslosenversicherung von 14,2 Milliarden Franken beschlossen. Zudem hat er entschieden, schrittweise aus den COVID-Massnahmen der Arbeitslosenversicherung auszusteigen. Der Ausstieg erfolgt in Abstimmung mit der schrittweisen \u00d6ffnung der Wirtschaft<\/p>\n","protected":false},"author":4,"featured_media":380433,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22520,24006,1140],"tags":[1633],"vendi":[],"content_country":[31836],"class_list":["post-380432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus-minute-fuer-minute","category-lajme-jeta-ne-zvicer-de","category-leben-in-der-schweiz","tag-zvicer-de","content_country-austria-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/380432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=380432"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/380432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/380433"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=380432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=380432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=380432"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=380432"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=380432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}