{"id":391136,"date":"2020-07-03T00:06:36","date_gmt":"2020-07-02T22:06:36","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=391136"},"modified":"2020-07-03T20:41:43","modified_gmt":"2020-07-03T18:41:43","slug":"neues-coronavirus-empfehlungen-fuer-reisende","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/neues-coronavirus-empfehlungen-fuer-reisende\/","title":{"rendered":"Neues Coronavirus: Empfehlungen f\u00fcr Reisende"},"content":{"rendered":"<p>Viele Staaten, drunter auch die Schweiz, passen ihre Einreisebestimmungen der aktuellen epidemischen Lage an. Innerhalb der Schweiz gilt: Im gesamten \u00d6V muss ab dem 6. Juli 2020 eine Maske getragen werden. Zudem m\u00fcssen sich Einreisende aus gewissen Gebieten in Quarant\u00e4ne begeben.<\/p>\n<p>Einreise in die Schweiz<\/p>\n<p>Aus der Schweiz ins Ausland Reisen<\/p>\n<p>Einreise in die Schweiz<\/p>\n<p>Seit Mitte Juni ist es wiederholt zu einer Ausbreitung des neuen Coronavirus in der Schweiz gekommen, nachdem infizierte Personen aus L\u00e4ndern des Schengenraums und aus Nicht-Schengen-Staaten eingereist sind. Ab Montag, 6. Juli 2020, m\u00fcssen Personen, die aus gewissen Gebieten einreisen, f\u00fcr zehn Tage in Quarant\u00e4ne. Das BAG f\u00fchrt f\u00fcr diese L\u00e4nder eine entsprechende Liste, die regelm\u00e4ssig angepasst wird.<\/p>\n<p>Die betroffenen Personen werden gezielt im Flugzeug, im Reisebus und an den Grenz\u00fcberg\u00e4ngen informiert. Sie m\u00fcssen sich nach der Einreise bei den kantonalen Beh\u00f6rden melden. Die Flug- und Reisebusgesellschaften werden zudem angewiesen, kranke Passagiere nicht zu transportieren.<\/p>\n<p>Informieren Sie sich vor Ihrer Reise auf der Webseite des Staatssekretariats f\u00fcr Migration SEM. Dort finden Sie Fragen und Antworten zu Einreisebeschr\u00e4nkungen und -ausnahmen, zu Personenfreiz\u00fcgigkeit und Visa-Stopp.<br \/>\nListe der Staaten und Gebiete mit erh\u00f6htem Ansteckungsrisiko<br \/>\nStand 2.7.2020<\/p>\n<p>Argentinien<br \/>\nArmenien<br \/>\nAserbaidschan<br \/>\nBahrain<br \/>\nBelarus<br \/>\nBolivien<br \/>\nBrasilien<br \/>\nCabo Verde<br \/>\nChile<br \/>\nDominikanische Republik<br \/>\nHonduras<br \/>\nIrak<br \/>\nIsrael<br \/>\nKatar<br \/>\nKolumbien<br \/>\nKosovo<br \/>\nKuwait<br \/>\nMoldova<br \/>\nNordmazedonien<br \/>\nOman<br \/>\nPanama<br \/>\nPeru<br \/>\nRussland<br \/>\nSaudi-Arabien<br \/>\nSchweden<br \/>\nSerbien<br \/>\nS\u00fcdafrika<br \/>\nTurks- und Caicos-Inseln<br \/>\nVereinigte Staaten von Amerika<\/p>\n<p><strong>Flugh\u00e4fen in der Schweiz<\/strong><\/p>\n<p>Flugpassagiere aus dem Ausland d\u00fcrfen an den Flugh\u00e4fen Z\u00fcrich, Genf und Basel und seit dem 15. Juni auch an Regionalflugh\u00e4fen einreisen. Dort erhalten Sie Hinweise, wie Sie sich gegen eine Ansteckung mit dem neuen Coronavirus sch\u00fctzen k\u00f6nnen. Auf dem Flughafen Basel m\u00fcssen Sie gem\u00e4ss den in Frankreich geltenden Vorschriften zwingend eine Hygienemaske tragen.<\/p>\n<p><strong>Zu beachten innerhalb der Schweiz<\/strong><\/p>\n<p>Ab dem 6. Juli 2020 gilt im \u00f6ffentlichen Verkehr in der Schweiz Schweizer \u00d6V eine Maskenpflicht.<\/p>\n<p>Beachten Sie die in der Schweiz geltenden Verhaltens- und Hygieneregeln. In \u00f6ffentlichen Einrichtungen wie Restaurants, Gesch\u00e4ften oder Museen m\u00fcssen Sie die Vorschriften der jeweiligen Schutzkonzepte der Betriebe befolgen. Informationen dazu erhalten Sie vor Ort.<\/p>\n<p>Treten bei Ihnen Krankheitssymptome auf, nachdem Sie in die Schweiz eingereist sind? Nehmen Sie diese ernst und befolgen Sie die Anweisungen auf der Seite Isolation und Quarant\u00e4ne. So sch\u00fctzen Sie sich und Ihre Mitmenschen am besten.<\/p>\n<p><strong>R\u00fcckkehr Schweizer Staatsangeh\u00f6riger<\/strong><br \/>\nFragen und Antworten zum Thema \u00abR\u00fcckreise in die Schweiz\u00bb finden Sie auf der Webseite des EDA.<\/p>\n<p><strong>Aus der Schweiz ins Ausland reisen<\/strong><br \/>\n<strong>Empfehlungen aufgrund des neuen Coronavirus<\/strong><br \/>\nWir empfehlen Ihnen, auf nicht notwendige Auslandreisen zu verzichten. Von dieser Empfehlung ausgenommen sind seit dem 15. Juni die L\u00e4nder des Schengenraums und Grossbritannien. Dies bedeutet nicht, dass diese L\u00e4nder gleichzeitig ihre Reiserestriktionen aufheben.<\/p>\n<p>Aufgrund der weltweiten Pandemie-Bek\u00e4mpfung ist das Planen von Auslandsreisen komplexer als zuvor. Die Einreisevorschriften unterscheiden sich von Land zu Land. Einige Staaten halten ihre Grenzen f\u00fcr Reisende weiterhin geschlossen. Andere \u00f6ffnen sie schrittweise \u2013 teils nur f\u00fcr bestimmte Gruppen oder Reisezwecke, teils unter Auflagen. Beispiele f\u00fcr solche Auflagen sind die obligatorische Quarant\u00e4ne, die Selbst\u00fcberwachung des Gesundheitszustandes oder sehr selten das Vorweisen eines negativen COVID-19-Tests. Auch die Grenzkontrollen werden unterschiedlich gehandhabt. Zudem gilt f\u00fcr alle L\u00e4nder:<\/p>\n<p>Die Einreisevorschriften k\u00f6nnen sich aufgrund der epidemischen Entwicklung sehr schnell \u00e4ndern. Informieren Sie sich bei der Botschaft oder dem Konsulat Ihres Ziellandes, ob die Einreise an diesem Tag ohne Beschr\u00e4nkungen m\u00f6glich ist oder ob es neue Einreisebestimmungen gibt.<\/p>\n<p>Reisen Sie nicht, wenn Sie sich krank f\u00fchlen oder einzelne Symptome haben, welche auf eine Ansteckung mit dem neuen Coronavirus hinweisen. Bleiben Sie stattdessen zu Hause und machen Sie den Coronavirus-Check oder rufen Sie Ihre \u00c4rztin oder Ihren Arzt an.<\/p>\n<p><strong>Massnahmen innerhalb des Ziellandes<\/strong><br \/>\nUm die Ausbreitung des neuen Coronavirus einzud\u00e4mmen, haben viele Staaten auch Massnahmen innerhalb des Landes beschlossen, die Sie w\u00e4hrend Ihres Auslandaufenthaltes beachten m\u00fcssen. Beispielsweise ist in gewissen L\u00e4ndern die Bewegungsfreiheit eingeschr\u00e4nkt oder es herrscht eine Maskenpflicht f\u00fcr bestimmte Orte. Auch \u00fcber diese Massnahmen informieren die ausl\u00e4ndischen Vertretungen in der Schweiz. Konsultieren Sie nach M\u00f6glichkeit die Informationsangebote und befolgen Sie die geltenden Regeln und Vorschriften Ihres Ziellandes.<\/p>\n<p><strong>Weitere Empfehlungen<\/strong><br \/>\nInformationen zu Grenz\u00f6ffnungen sowie zur Sicherheit und der politischen Situation an Ihrem Reiseziel finden Sie auf den Internetseiten des Eidgen\u00f6ssischen Departements f\u00fcr ausw\u00e4rtige Angelegenheiten EDA und des Staatssekretariats f\u00fcr Migration SEM.<\/p>\n<p>Medizinische Empfehlungen zu den einzelnen Ziell\u00e4ndern, die nicht mit COVID-19 im Zusammenhang stehen, gelten weiterhin. Informieren Sie sich auf www.safetravel.ch.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informieren Sie sich vor Ihrer Reise auf der Webseite des Staatssekretariats f\u00fcr Migration SEM. Dort finden Sie Fragen und Antworten zu Einreisebeschr\u00e4nkungen und -ausnahmen, zu Personenfreiz\u00fcgigkeit und Visa-Stopp<\/p>\n","protected":false},"author":4,"featured_media":386443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22520,24006,1140,1412,2015],"tags":[1651],"vendi":[],"content_country":[31836,31837],"class_list":["post-391136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus-minute-fuer-minute","category-lajme-jeta-ne-zvicer-de","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de","tag-kosova-fr-de","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/391136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=391136"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/391136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/386443"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=391136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=391136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=391136"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=391136"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=391136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}