{"id":408476,"date":"2020-09-19T01:02:32","date_gmt":"2020-09-18T23:02:32","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=408476"},"modified":"2020-09-19T01:02:32","modified_gmt":"2020-09-18T23:02:32","slug":"schweiz-und-oesterreich-wuerdigen-krisenfeste-zusammenarbeit-beider-laender","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/schweiz-und-oesterreich-wuerdigen-krisenfeste-zusammenarbeit-beider-laender\/","title":{"rendered":"Schweiz und \u00d6sterreich w\u00fcrdigen krisenfeste Zusammenarbeit beider L\u00e4nder"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p><strong>Bundespr\u00e4sidentin Simonetta Sommaruga hat am Freitag, 18. September 2020, den \u00f6sterreichischen Bundeskanzler Sebastian Kurz zu einem offiziellen Besuch in der Schweiz empfangen. Neben der Bundespr\u00e4sidentin nahmen die Bundesr\u00e4te Ueli Maurer und Alain Berset an einem Mittagessen mit Bundeskanzler Kurz auf dem Landgut Lohn teil. An den offiziellen Gespr\u00e4chen waren Bundespr\u00e4sidentin Sommaruga, Bundesrat Ignazio Cassis und Bundesr\u00e4tin Karin Keller-Sutter beteiligt.<\/strong><\/p>\n<p>Im Zentrum der Diskussionen standen der Umgang mit der Corona-Pandemie, Klima- und Umweltfragen, die bilateralen Beziehungen sowie europapolitische und internationale Themen. Beide Seiten w\u00fcrdigten die guten Beziehungen zwischen der Schweiz und \u00d6sterreich. Diese haben in den schwierigen Fr\u00fchlingsmonaten eine enge Zusammenarbeit erleichtert. So haben \u00d6sterreich und die Schweiz einander etwa bei der Repatriierung der im Ausland blockierten Staatsangeh\u00f6rigen unterst\u00fctzt.<\/p>\n<p>F\u00fcr die Schweiz bleibt der enge Austausch mit \u00d6sterreich und den anderen europ\u00e4ischen Partnern bei der Bek\u00e4mpfung der Corona-Pandemie wichtig. Die Schweiz unterst\u00fctzt das Bem\u00fchen der EU-Ratspr\u00e4sidentschaft und der EU-Kommission, die Quarant\u00e4neregeln auf kontinentaler Ebene besser zu koordinieren. Die gute Zusammenarbeit in der Krisenphase sei eine gute Grundlage f\u00fcr weitere pragmatische L\u00f6sungen im Verh\u00e4ltnis zwischen der Schweiz und der EU, betonte die Schweizer Delegation.<\/p>\n<p><b>Alpenl\u00e4nder sind vom Klimawandel besonders betroffen<\/b><\/p>\n<p>Beim Austausch \u00fcber die Umwelt- und Verkehrspolitik wies Bundespr\u00e4sidentin Sommaruga auf die Notwendigkeit hin, zum Schutz der Alpen die Verlagerung der G\u00fcter von der Strasse auf die Schiene weiter zu st\u00e4rken. Die Neue Eisenbahn-Alpentransversale (NEAT) mit den drei Basistunneln (L\u00f6tschberg, Gotthard, Ceneri) verbessere die Wettbewerbsf\u00e4higkeit der Bahn. Bundespr\u00e4sidentin Sommaruga k\u00fcndete zudem an, den Vorsitz der Alpenkonvention im n\u00e4chsten Jahr zu nutzen, um ein Treffen der Verkehrs- und Umweltminister der Alpenl\u00e4nder zu organisieren und den Klima- und Alpenschutz weiter voranzubringen. \u00d6sterreich und die Schweiz sind als Alpenl\u00e4nder vom Klimawandel besonders betroffen.<\/p>\n<p>Die Mitglieder des Bundesrates erl\u00e4uterten Bundeskanzler Kurz zudem die anstehenden europapolitischen Entscheide in der Schweiz. Ebenfalls zur Sprache kam die europ\u00e4ische Migrationspolitik. Die beiden Seiten tauschten sich namentlich \u00fcber die anstehende Reform des Dublin-Systems aus, wobei die Schweiz die von der EU-Kommission geplante Dublin-Reform im Grundsatz unterst\u00fctzt.<\/p>\n<p>Im Anschluss an das Treffen im Lohn wird der \u00f6sterreichische Bundeskanzler Kurz am Freitagnachmittag f\u00fcr einen Austausch \u00fcber das Funktionieren f\u00f6deralistischer Staaten in Krisenlagen mit Bundeskanzler Walter Thurnherr zusammenkommen.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Im Zentrum der Diskussionen standen der Umgang mit der Corona-Pandemie, Klima- und Umweltfragen, die bilateralen Beziehungen sowie europapolitische und internationale Themen<\/p>\n","protected":false},"author":4,"featured_media":408437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22520,24006,24631,1140],"tags":[],"vendi":[],"content_country":[31836,31837],"class_list":["post-408476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus-minute-fuer-minute","category-lajme-jeta-ne-zvicer-de","category-nachrichten-de-2","category-leben-in-der-schweiz","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/408476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=408476"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/408476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/408437"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=408476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=408476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=408476"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=408476"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=408476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}