{"id":409374,"date":"2020-09-22T21:04:12","date_gmt":"2020-09-22T19:04:12","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=409374"},"modified":"2020-09-22T21:05:03","modified_gmt":"2020-09-22T19:05:03","slug":"bundesrat-verabschiedet-botschaft-zum-covid-19-geschaeftsmietegesetz","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/bundesrat-verabschiedet-botschaft-zum-covid-19-geschaeftsmietegesetz\/","title":{"rendered":"Bundesrat verabschiedet Botschaft zum Covid-19-Gesch\u00e4ftsmietegesetz"},"content":{"rendered":"<p><strong>Der Bundesrat hat am 18. September 2020 die Botschaft zum Covid-19-Gesch\u00e4ftsmietegesetz verabschiedet und damit einen Auftrag des Parlaments erf\u00fcllt. Er verzichtet aber darauf, dem Parlament die Zustimmung zum Gesetzesentwurf zu beantragen. Die Vorlage sieht vor, dass Mieterinnen und Mieter, die im Fr\u00fchjahr 2020 von einer Schliessung oder starken Einschr\u00e4nkung betroffen waren, f\u00fcr diese Periode 40 Prozent des Mietzinses bezahlen. 60 Prozent gehen zulasten der Vermieterinnen und Vermieter. Die Vorlage wurde in der Vernehmlassung kontrovers beurteilt. Es liegt nun am Parlament, \u00fcber das Gesetzesvorhaben zu entscheiden.<\/strong><\/p>\n<p>National- und St\u00e4nderat hatten in der Sommersession 2020 zwei gleichlautenden Kommis-\u00a0\u00a0 sionsmotionen zugestimmt, mit denen der Bundesrat beauftragt wurde, eine gesetzliche Regelung im Bereich der Gesch\u00e4ftsmieten vorzulegen. Die Vernehmlassung, die vom 1. Juli bis am 4.\u00a0August 2020 durchgef\u00fchrt wurde, ergab ein kontroverses Bild. Elf Kantone, zwei politische Parteien, und die Wirtschafts-, Vermieter- und Immobilienverb\u00e4nde lehnen den Gesetzesvorschlag ab. Zustimmung kam von acht Kantonen, von vier politischen Parteien, dem Schweizerischen St\u00e4dteverband und von den Mieterorganisationen sowie von den Gastro- und von Berufsverb\u00e4nden. Zu den einzelnen Bestimmungen gab es Kritik von beiden Seiten; Den einen geht die Vorlage zu weit, den anderen zu wenig weit.<\/p>\n<p>Der Bundesrat passte die Gesetzesvorlage aufgrund der R\u00fcckmeldungen punktuell an; insgesamt orientiert sich das vorliegende Covid-19-Gesch\u00e4ftsmietegesetz eng am Wortlaut der beiden gleichlautenden Kommissionsmotionen:<\/p>\n<blockquote><p>Die Adressaten des Gesetzes sind die Miet- und Pachtparteien von Betrieben und \u00f6ffentlich zug\u00e4nglichen Einrichtungen (bspw. Restaurants oder Coiffeursalons), die aufgrund von Artikel 6 Absatz 2 der COVID-19-Verordnung 2 geschlossen wurden oder von Gesundheitseinrichtungen, die aufgrund von Artikel 10a Absatz 2 der gleichen Verordnung ihre T\u00e4tigkeiten reduzieren mussten.<\/p>\n<p>Der Gesetzesentwurf legt fest, dass f\u00fcr die betroffenen Einrichtungen der Miet- oder Pachtzins f\u00fcr die Zeit der verordneten Schliessung 40 Prozent betragen soll. Bei Gesundheitseinrichtungen, die ihren Betrieb einschr\u00e4nken mussten, gilt dies f\u00fcr maximal zwei Monate.<\/p>\n<p>Die Regelung bezieht sich auf einen Nettomietzins, resp. Nettopachtzins von maximal 20&#8217;000 Franken pro Monat und Objekt. Bei einem Miet- oder Pachtzins zwischen 15&#8217;000 und 20&#8217;000 Franken sollen beide Mietparteien mit einer einseitigen schriftlichen Mitteilung auf die Gesetzesregelung verzichten k\u00f6nnen. Ausdr\u00fcckliche Einigungen der Vertragsparteien sollen ihre G\u00fcltigkeit behalten.<\/p>\n<p>Vermieterinnen und Vermieter sowie Verp\u00e4chterinnen und Verp\u00e4chter, die infolge von Miet- oder Pachtzinsausf\u00e4llen in eine erhebliche wirtschaftliche Notlage geraten, sollen eine finanzielle Entsch\u00e4digung durch den Bund beantragen k\u00f6nnen. Eine derartige wirtschaftliche Notlage liegt insbesondere vor, wenn die reine Kostenmiete angewendet wird oder wenn nachgewiesen werden kann, dass die finanzielle Einbusse die wirtschaftliche Existenz des Antragstellers bedroht.<\/p><\/blockquote>\n<p>Der Bundesrat h\u00e4lt an seiner bisherigen Position fest, dass ein Eingriff in die privatrechtlichen Beziehungen zwischen Mieterinnen und Mietern und Vermieterinnen und Vermietern zu vermeiden sind. Er verzichtet daher darauf, dem Parlament die Zustimmung zu diesem Gesetzesentwurf zu beantragen. Der Bundesrat wird in den kommenden Wochen einen Monitoringbericht zum Thema der Gesch\u00e4ftsmieten ver\u00f6ffentlichen. Dieser Bericht soll die Situation im Bereich der Gesch\u00e4ftsmieten darstellen und geht auf einen Entscheid des Bundesrates vom 8. April 2020 zur\u00fcck.<\/p>\n<p><a href=\"https:\/\/www.admin.ch\/gov\/de\/start\/dokumentation\/medienmitteilungen.msg-id-80448.html\">admin.ch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Bundesrat hat am 18. September 2020 die Botschaft zum Covid-19-Gesch\u00e4ftsmietegesetz verabschiedet und damit einen Auftrag des Parlaments erf\u00fcllt. Er verzichtet aber darauf, dem Parlament die Zustimmung zum Gesetzesentwurf zu beantragen. Die Vorlage sieht vor, dass Mieterinnen und Mieter, die im Fr\u00fchjahr 2020 von einer Schliessung oder starken Einschr\u00e4nkung betroffen waren, f\u00fcr diese Periode 40 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":369922,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22520],"tags":[],"vendi":[],"content_country":[],"class_list":["post-409374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus-minute-fuer-minute"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/409374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=409374"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/409374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/369922"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=409374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=409374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=409374"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=409374"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=409374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}