{"id":419448,"date":"2020-11-03T17:57:36","date_gmt":"2020-11-03T16:57:36","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=419448"},"modified":"2020-11-18T00:41:16","modified_gmt":"2020-11-17T23:41:16","slug":"coronavirus-neue-teilkampagne-bewirbt-den-online-coronavirus-check","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/coronavirus-neue-teilkampagne-bewirbt-den-online-coronavirus-check\/","title":{"rendered":"Neue Teilkampagne bewirbt den Online-Coronavirus-Check"},"content":{"rendered":"<div class=\"contentHead\">Mit der rasch steigenden Zahl von Coronavirus-F\u00e4llen treten vermehrt verschiedene Krankheitssymptome auf. Um Klarheit zu schaffen, ob es sich hierbei um eine m\u00f6gliche Ansteckung mit dem neuen Coronavirus handelt, lanciert das BAG eine neue Teilkampagne. Diese weist auf den Online-Coronavirus-Check des BAG hin. \u00dcber dieses einfache Online-Tool kann schnell herausgefunden werden, ob Krankheitssymptome einen Coronavirus-Test n\u00f6tig machen. Wer den Online-Check macht, erh\u00e4lt dazu eine Handlungsempfehlung.<\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p><a href=\"https:\/\/bag-coronavirus.ch\/check\/\">https:\/\/bag-coronavirus.ch\/check\/<\/a><\/p>\n<p>Die neue Kampagne startet am Montag, 2. November, mit Anzeigen, TV-Spots, Online-Videos und Online-Ads. Ab dem 9.11. werden zudem digitale Plakate zu sehen sein.<\/p>\n<p>Parallel zur Teilkampagne \u00abCoronavirus-Check\u00bb werden Kommunikationsmittel verbreitet, die die neuen Massnahmen des Bundesrates vom Mittwoch mit den folgenden Botschaften thematisieren: \u00abTreffen Sie weniger Menschen\u00bb, \u00abTragen Sie an \u00f6ffentlichen Orten eine Maske\u00bb, \u00abHalten Sie private Veranstaltungen klein\u00bb, \u00abArbeiten Sie wenn m\u00f6glich im Homeoffice\u00bb.<\/p>\n<p>Diese Kampagne wurde bereits an der Bundesratssitzung vom letzten Mittwoch vorgestellt. Im Rahmen dieser Informationskampagne werden auch Spots erarbeitet, die an die gemeinsame Verantwortung aller appellieren.<\/p>\n<p>Beachten Sie bitte die Kampagnenwebsite: <a href=\"https:\/\/bag-coronavirus.ch\/\">https:\/\/bag-coronavirus.ch\/<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Das Bundesamt f\u00fcr Gesundheit (BAG) lanciert eine neue Teilkampagne, die auf den Coronavirus-Check hinweist. Wer diesen Check macht, erh\u00e4lt eine Empfehlung bez\u00fcglich eines Coronavirus-Tests. Die BAG-Coronavirus-Kampagne hat zudem auf Rot geschaltet.<\/p>\n","protected":false},"author":4,"featured_media":419613,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,22520,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-419448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-coronavirus-minute-fuer-minute","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/419448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=419448"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/419448\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/419613"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=419448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=419448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=419448"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=419448"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=419448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}