{"id":440190,"date":"2021-01-28T19:01:49","date_gmt":"2021-01-28T18:01:49","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=440190"},"modified":"2021-01-28T19:01:49","modified_gmt":"2021-01-28T18:01:49","slug":"bund-uebernimmt-testkosten-fuer-personen-ohne-symptome-und-passt-quarantaeneregeln-an","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/bund-uebernimmt-testkosten-fuer-personen-ohne-symptome-und-passt-quarantaeneregeln-an\/","title":{"rendered":"Bund \u00fcbernimmt Testkosten f\u00fcr Personen ohne Symptome und passt Quarant\u00e4neregeln an"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p><strong>Der Bundesrat hat an seiner Sitzung vom 27. Januar 2021 eine Reihe von Beschl\u00fcssen zur Eind\u00e4mmung und Bew\u00e4ltigung der Corona-Epidemie gefasst. Der Bund \u00fcbernimmt neu die Kosten f\u00fcr Tests an Personen ohne Symptome, um besonders gef\u00e4hrdete Menschen besser zu sch\u00fctzen und lokale Infektionsausbr\u00fcche fr\u00fchzeitig zu bek\u00e4mpfen. Zudem passt er die bisherige Quarant\u00e4neregelung an: Die zehnt\u00e4gige Quarant\u00e4ne kann verk\u00fcrzt werden, falls sich die betroffene Person nach sieben Tagen testen l\u00e4sst und das Resultat negativ ist. Ausserdem regelte der Bundesrat, dass Ordnungsbussen verh\u00e4ngt werden k\u00f6nnen, wenn bestimmte Massnahmen nicht eingehalten werden. Damit Impfungen auch in Apotheken m\u00f6glich sind, \u00fcbernimmt der Bund auch dort die Kosten.<\/strong><\/p>\n<p>Mehr als die H\u00e4lfte der Covid-19-\u00dcbertragungen d\u00fcrfte durch Personen ohne Symptome stattfinden, die gar nicht merken, dass sie infiziert sind. Der Bund hat deshalb Mitte Dezember das Testen von Personen ohne Symptome im Rahmen von Schutzkonzepten, etwa in Alters- und Pflegeheimen, Hotels oder am Arbeitsplatz zugelassen. Um den Anreiz f\u00fcr solche Tests zu erh\u00f6hen, \u00fcbernimmt der Bund neu die Kosten daf\u00fcr. Die Tests k\u00f6nnen vom Personal selbst vor Ort vorgenommen und negative Resultate dieser Schnelltests m\u00fcssen nicht gemeldet werden. Wird jemand positiv getestet, muss ein PCR-Test durchgef\u00fchrt und das Resultat gemeldet werden.<\/p>\n<p>Die erweiterte Teststrategie soll auch dazu beitragen, lokale Infektionsausbr\u00fcche fr\u00fchzeitig zu erkennen und einzud\u00e4mmen, etwa in Schulen. Dies nicht zuletzt auch, weil sich die neuen, ansteckenderen Varianten des Coronavirus in der Schweiz weiter verbreiten. Der Bund \u00fcbernimmt auch in diesen F\u00e4llen die Kosten f\u00fcr die Testung von Personen ohne Symptome. Der Kanton muss dem BAG ein Konzept vorlegen, etwa dazu wo, wer und wie oft getestet wird sowie welche Tests verwendet werden.<\/p>\n<p>Die Testkriterien des Bundesamts f\u00fcr Gesundheit werden entsprechend angepasst. Die erweiterte Teststrategie erfordert eine \u00c4nderung der Covid-19-Verordnung 3, die morgen Donnerstag, 28.1.2021 in Kraft tritt.<\/p>\n<p><strong>Quarant\u00e4neregel angepasst<br \/>\n<\/strong>Die bisherige Regelung der Kontaktquarant\u00e4ne wird durch eine Test- und Freigabestrategie erg\u00e4nzt. Gem\u00e4ss der bis anhin geltenden Regelung muss sich eine Person ab dem letzten Kontakt mit einer infizierten Person in eine 10-t\u00e4gige Quarant\u00e4ne begeben. Neu kann die Quarant\u00e4ne mit Zustimmung der zust\u00e4ndigen kantonalen Beh\u00f6rde vorzeitig beendet werden, wenn die betroffene Person ab dem 7. Tag einen Antigen-Schnelltest oder eine molekularbiologische Analyse (PCR-Test) durchf\u00fchrt und das Resultat negativ ist. Die Testkosten muss die Person selber tragen. Bis zum eigentlichen Ablauf der Quarant\u00e4ne (10. Tag) muss die Person jederzeit eine Gesichtsmaske\u00a0tragen und den Abstand von 1.5 Metern gegen\u00fcber anderen Personen einhalten, ausser sie h\u00e4lt sich in der eigenen Wohnung oder Unterkunft (z.B. Ferienwohnung, Hotel) auf. Bei einem positiven Test muss sich die Person unverz\u00fcglich in Isolation begeben.<\/p>\n<p><strong>Verk\u00fcrzte Reisequarant\u00e4ne<br \/>\n<\/strong>Die neue Test- und Freigabestrategie gilt auch f\u00fcr Einreisende aus Staaten oder Gebieten mit einem erh\u00f6hten Ansteckungsrisiko. Sie m\u00fcssen k\u00fcnftig bei ihrer Einreise einen negativen PCR-Test vorweisen, der nicht \u00e4lter als 72 Stunden ist. Anschliessend begeben sie sich wie bisher in eine 10-t\u00e4gige Quarant\u00e4ne. Sie k\u00f6nnen diese jedoch ab dem 7. Tag verlassen, falls ein negatives Resultat eines Antigen-Schnelltests oder PCR-Tests vorliegt. Bei Flugreisen aus L\u00e4ndern, die nicht zu den Risikogebieten z\u00e4hlen, ist ebenfalls ein negatives PCR-Testresultat vorzuweisen. Die Kontrolle erfolgt vor dem Einsteigen ins Flugzeug.<\/p>\n<p><strong>Breitere Erfassung der Kontaktdaten<br \/>\n<\/strong>Bisher werden nur die Kontaktdaten von Personen aus Risikostaaten oder -gebieten bei ihrer Einreise in die Schweiz erfasst. In Zukunft m\u00fcssen auch Einreisende aus Staaten oder Gebieten ohne erh\u00f6htes Ansteckungsrisiko ihre Kontaktdaten angeben, falls sie per Flugzeug, Schiff, Bus oder Zug einreisen. S\u00e4mtliche Kontaktdaten werden neu mittels eines elektronischen Einreiseformulars erfasst. Dadurch k\u00f6nnen Ansteckungen einfacher und schneller zur\u00fcckverfolgt und Infektionsketten fr\u00fchzeitig unterbrochen werden.<\/p>\n<p>Die vom Bundesrat beschlossenen Quarant\u00e4ne- und Einreiseregeln erfordern eine Anpassung der betreffenden Covid-19-Verordnungen. Sie treten am 8. Februar 2021 in Kraft.<\/p>\n<p><strong>Ordnungsbussen: Straftatbest\u00e4nde explizit aufgef\u00fchrt.<br \/>\n<\/strong>Ab dem 1. Februar 2021 werden Widerhandlungen gegen Massnahmen zur Bek\u00e4mpfung der Epidemie explizit als Straftatbest\u00e4nde aufgef\u00fchrt und k\u00f6nnen teilweise mit Ordnungsbussen bestraft werden. Die H\u00f6he der Busse betr\u00e4gt je nach Delikt zwischen 50 und 200 Franken. Mit einer Ordnungsbusse geb\u00fcsst werden kann etwa, wer im \u00f6ffentlichen Verkehr sowie in den Bahnh\u00f6fen und an den Haltestellen oder in und vor \u00f6ffentlich zug\u00e4nglichen Einrichtungen keine Maske tr\u00e4gt. Ordnungsbussen sind zudem m\u00f6glich f\u00fcr Teilnahme an unzul\u00e4ssigen Veranstaltungen oder die Durchf\u00fchrung einer verbotenen privaten Veranstaltung. Die unmittelbare und rasche Bestrafung mit einer Ordnungsbusse soll die Einhaltung der Massnahmen in der Gesellschaft f\u00f6rdern und die Strafverfolgungsbeh\u00f6rden entlasten.<\/p>\n<p><strong>Bund \u00fcbernimmt Kosten f\u00fcr Impfung in Apotheken<br \/>\n<\/strong>Der Bund \u00fcbernimmt ab dem 1. Februar auch die Kosten f\u00fcr Impfungen durch Apothekerinnen und Apotheker und zwar zu denselben Bedingungen wie f\u00fcr Impfungen in Impfzentren. Dies erlaubt den Kantonen, die Apotheken in ihre Impforganisation zu integrieren.<\/p>\n<p><strong>Pr\u00fcfung von Atemschutzmasken<br \/>\n<\/strong>Atemschutzmasken mit m\u00f6glicherweise ungen\u00fcgendem Sicherheitsnachweis in Lagerbest\u00e4nden des Bundes oder der Kantone, sollen nachtr\u00e4glich gepr\u00fcft werden k\u00f6nnen. Erf\u00fcllen diese Atemschutzmasken die nachtr\u00e4gliche Pr\u00fcfung nicht, d\u00fcrfen diese nicht benutzt werden. Der Bundesrat hat heute die Covid-19-Verordnung 3 entsprechend ge\u00e4ndert. Zu Beginn der Covid-19-Pandemie wurden wegen des hohen Bedarfs beim Gesundheitspersonal in grossen Mengen Atemschutzmasken mit m\u00f6glicherweise ungen\u00fcgendem Sicherheitsnachweis eingekauft.<\/p>\n<p><strong>Nur langsame Abnahme der Fallzahlen<br \/>\n<\/strong>Die epidemiologische Lage entspannt sich in der Schweiz nur langsam, insbesondere bei der Zahl der Neuansteckungen. Deutlicher ist die Abnahme bei den Hospitalisationen und den Todesf\u00e4llen. Auf den Intensivstationen bleibt die Belastung allerdings unver\u00e4ndert hoch. Der Anteil der neuen Virusvarianten verdoppelt sich nach wie vor jede Woche. Der Bundesrat verfolgt diese Entwicklung mit Sorge. Sein Ziel bleibt eine rasche und deutliche Abnahme der Fallzahlen.<\/p>\n<p><strong>Ausfallentsch\u00e4digung f\u00fcr Kulturschaffende<br \/>\n<\/strong>Der Bundesrat hat zudem heute entschieden, dem Parlament zu beantragen, dass Kulturschaffende r\u00fcckwirkend auf den 1. November 2020 Ausfallentsch\u00e4digungen erhalten sollen. Dadurch soll eine Unterst\u00fctzungsl\u00fccke vermieden werden. Kulturschaffende k\u00f6nnen ihr Gesuche einreichen, sobald die gesetzlichen Grundlagen in den f\u00fcr die Umsetzung zust\u00e4ndigen Kantonen bestehen.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Neu kann die Quarant\u00e4ne mit Zustimmung der zust\u00e4ndigen kantonalen Beh\u00f6rde vorzeitig beendet werden, wenn die betroffene Person ab dem 7. Tag einen Antigen-Schnelltest oder eine molekularbiologische Analyse (PCR-Test) durchf\u00fchrt und das Resultat negativ ist<\/p>\n","protected":false},"author":4,"featured_media":439973,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22520,24006,24631,1140],"tags":[],"vendi":[],"content_country":[31836,31837],"class_list":["post-440190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus-minute-fuer-minute","category-lajme-jeta-ne-zvicer-de","category-nachrichten-de-2","category-leben-in-der-schweiz","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/440190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=440190"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/440190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/439973"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=440190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=440190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=440190"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=440190"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=440190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}