{"id":476974,"date":"2021-06-14T13:15:27","date_gmt":"2021-06-14T11:15:27","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=476974"},"modified":"2021-06-14T13:15:27","modified_gmt":"2021-06-14T11:15:27","slug":"falschinformationen-bilden-skeptikerinnen","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/falschinformationen-bilden-skeptikerinnen\/","title":{"rendered":"Falschinformationen bilden Skeptiker:innen"},"content":{"rendered":"<p>Covid-Impfzentren vermissen weiterhin albanische Besucher:innen. Der Berater des Impfzentrums Winterthur, Jacques Gubler, versucht nun unsere Community besser aufzukl\u00e4ren und bittet zur Impfbereitschaft. Nur durch die Impfung wird die Corona-Pandemie in Schach gehalten und schneller vor\u00fcber gehen.<\/p>\n<p><strong>Sie sind der Leiter des Impfzentrums Winterthur, richtig?<\/strong><\/p>\n<p><em>Leiter des impfzentrums ist Thomas Kraft. Ich bin \u00e4rztlicher Berater in der Projektleitung und war f\u00fcr die medizinischen Belange im Aufbau und jetzt in der Betriebsorganisation des Impfzentrums verantwortlich. Als ehemaliger Chefarzt f\u00fcr Infektiologie und Spitalhygiene am Kantonsspital Winterthur konnte ich daf\u00fcr auf meine langj\u00e4hrige Berufserfahrung und vor allem auf <strong>meine Kontakte in der Umgebung zur\u00fcckgreifen<\/strong>. Letzteres hat es erm\u00f6glicht, dass die \u00e4rztliche Pr\u00e4senz im Impfzentrum von pensionierten \u00c4rztinnen und \u00c4rzten sowie solchen, welche ihre freien Tage daf\u00fcr einsetzen, getragen wird. <strong>Diese werden dabei von Apothekerinnen und Apothekern aus der Stadt unterst\u00fctzt<\/strong>.<\/em><\/p>\n<p><strong>Welchen Impfstoff verabreichen Sie?<\/strong><\/p>\n<p><em>Wir verabreichen die beiden in der Schweiz zugelassenen mRNA-Impfstoffe Vaccine Moderna sowie Comirnaty der Firma Pfizer-Biontech.<\/em><\/p>\n<p><strong>\u00a0<\/strong><strong>Woher, denken Sie, kommt die Vorsicht gegen\u00fcber der Covid-Impfung?<\/strong><\/p>\n<p><em>Seit es Impfungen gibt, hat es immer in einem Teil der Bev\u00f6lkerung dazu skeptische Einstellungen gegeben. Daf\u00fcr gibt es sehr viele unterschiedliche Gr\u00fcnde \u2013 einer davon ist die Tatsache, dass eine Impfung einen aktiven Entscheid dazu ben\u00f6tigt, f\u00fcr den man Verantwortung \u00fcbernimmt, w\u00e4hrend eine Infektionserkrankung als schicksalhaft angesehen und angenommen wird. Je gr\u00f6sser die Bedrohung durch die Ansteckung empfunden wird, desto h\u00f6her die Impfbereitschaft. Als Ende der 1950er Jahre gegen Kinderl\u00e4hmung geimpft werden konnte, haben auch in der Schweiz die meisten Eltern ihre Kinder impfen lassen, weil sie alle noch die Krankheit und deren Folgen erlebt hatten. <\/em><\/p>\n<p><strong>\u00a0<\/strong><strong>Wieso vermissen Sie genau die albanische Bev\u00f6lkerung in Ihrem Impfzentrum?<\/strong><\/p>\n<p><em>Die Kolleg:innen des Kantonsspitals haben bemerkt, dass unter den schwer kranken COVID19-Patient:innen im Spital sich \u00fcberdurchschnittlich viele mit Migrationshintergrund befanden, gerade auch aus S\u00fcdosteuropa. Ohne die daf\u00fcr verantwortlichen Gr\u00fcnde zu kennen, hat uns dies bewogen, diese Bev\u00f6lkerungsgruppe speziell von der Impfung zu \u00fcberzeugen. Wir f\u00fchren aber keine Statistik \u00fcber die Zugeh\u00f6rigkeit und Herkunft von Impfwilligen. <\/em><\/p>\n<p><strong>Welche Informationen ben\u00f6tigen die Menschen, um ein positiveres Gef\u00fchl f\u00fcr die Impfung zu erhalten?<\/strong><\/p>\n<p><em>In der heutigen Zeit sind die Menschen eher mit zu viel als zu wenig Information konfrontiert, durch die sozialen Medien und das Internet leider auch mit falschen. Das Wichtigste ist das Vertrauen in die Glaubw\u00fcrdigkeit der Informationsquelle. Hier spielen Meinungstr\u00e4ger:innen eine zentrale Rolle, auch und gerade in Bev\u00f6lkerungsgruppen mit speziellen kulturellen Hintergrund. <\/em><\/p>\n<p><strong>\u00a0<\/strong><strong>Viele glauben auch, dass der Impfstoff die DNA ver\u00e4ndert und die Stammzellen angreift, inwiefern ist das plausibel?<\/strong><\/p>\n<p><em>Alle Zellen produzieren Eiweissmolek\u00fcle nach einem Bauplan, welcher im Zellkern von der DNA abgelesen und mittels mRNA zur zelleigenen &#8220;Eiweissfabrik&#8221; ausserhalb desselben gebracht wird. Mit den mRNA Impfstoffen wird durch die Impfung direkt ein solcher Bauplan f\u00fcr ein spezifisches Viruseiweiss in die Muskelzellen eingespritzt. Die Zellen produzieren anhand dieses &#8220;Bauplans&#8221; das Eiweiss, was zur Bildung von Abwehrstoffen dagegen und damit zum Schutz vor dem Virus f\u00fchrt. Dies findet in der Zelle ausserhalb des Zellkerns statt, in dem das Erbgut in Form von DNA liegt \u2013 eine Beeinflussung derselben ist damit nicht m\u00f6glich, denn die mRNA wird im Zellinnern innert kurzer Zeit abgebaut und geht nicht zur\u00fcck in den Zellkern.<\/em><\/p>\n<p><strong>Woher kommen die vielen Verschw\u00f6rungstheorien?<\/strong><\/p>\n<p><em>Verschw\u00f6rungstheorien hat es zu allen Zeiten der Menschheitsgeschichte gegeben. H\u00e4ufig wurden und werden sie immer noch auch eingesetzt, um Stimmung gegen einzelne Bev\u00f6lkerungsgruppen oder Institutionen zu machen. Verschw\u00f6rungstheorien k\u00f6nnen auch das Vertrauen in Beh\u00f6rden vermindern, was politisch zur Destabilisierung von Regierungen genutzt wird.<\/em><\/p>\n<p><strong>K\u00f6nnen Sie unseren Leser:innen verl\u00e4ssliche Informationsquellen nennen, bei denen sie sich besser informieren k\u00f6nnen?<\/strong><\/p>\n<p><em>Die kantonalen und eidgen\u00f6ssischen Beh\u00f6rden haben zur Coronainfektion und zur Impfung gegen COVID19 spezielle Informationen auch in albanischer Sprache zur Verf\u00fcgung gestellt:<\/em><\/p>\n<p><a href=\"https:\/\/www.zh.ch\/de\/gesundheit\/coronavirus\/informationen-fuer-die-migrationsbevoelkerung.html#-1222746997\">https:\/\/www.zh.ch\/de\/gesundheit\/coronavirus\/informationen-fuer-die-migrationsbevoelkerung.html#-1222746997<\/a><\/p>\n<p>https:\/\/www.bag.admin.ch\/bag\/de\/home\/krankheiten\/ausbrueche-epidemien-pandemien\/aktuelle-ausbrueche-epidemien\/novel-cov\/downloads-in-verschiedenen-sprachen\/informationen-in-sprachen-der-migrationsbevoelkerung.html#23522659<\/p>\n<p><strong>Denken Sie, dass die albanische Bev\u00f6lkerung eher mit Fehlinformationen in Kontakt geraten als andere?<\/strong><\/p>\n<p><em>F\u00fcr Fremdsprachige ist es schwierig, sich \u00fcber die schweizerischen Medien zu informieren. Darum steigt die Bedeutung von Informationen aus zweifelhaften Quellen, deren Glaubw\u00fcrdigkeit nicht \u00fcberpr\u00fcft werden kann. Und \u00fcber soziale Medien werden eher Informationen geteilt und verbreitet, die andere Inhalte als die der offiziellen Stellen beinhalten \u2013 mit fatalen Folgen.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Gesundheits- und Impfzentrum WIN\u00a0AG<\/strong><br \/>\n<strong>c\/o Medbase\u00a0AG<\/strong><br \/>\n<strong>Sch\u00fctzen\u00adstrasse\u00a03<\/strong><br \/>\n<strong>8400\u00a0Winterthur<\/strong><\/p>\n<p><strong>Telefon:<a href=\"tel:+41522089131\">+41\u00a052\u00a0208\u00a091\u00a031<\/a><\/strong><\/p>\n<p><strong>E-Mail: <a href=\"mailto:info@impfzentrumwinterthur.ch\">info@impfzentrum\u00adwinterthur.ch<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr Fremdsprachige ist es schwierig, sich \u00fcber die schweizerischen Medien zu informieren. Darum steigt die Bedeutung von Informationen aus zweifelhaften Quellen, deren Glaubw\u00fcrdigkeit nicht \u00fcberpr\u00fcft werden kann<\/p>\n","protected":false},"author":4,"featured_media":476976,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,3953,3954,1140],"tags":[],"vendi":[],"content_country":[29888,31836,31837],"class_list":["post-476974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-intervista-de","category-shendetesi-2-de","category-leben-in-der-schweiz","content_country-zvicer","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/476974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=476974"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/476974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/476976"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=476974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=476974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=476974"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=476974"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=476974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}