{"id":483291,"date":"2021-06-29T09:00:57","date_gmt":"2021-06-29T07:00:57","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=483291"},"modified":"2021-06-29T11:36:52","modified_gmt":"2021-06-29T09:36:52","slug":"2020-hat-der-internationale-tourismus-wegen-covid-19-stark-gelitten","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/2020-hat-der-internationale-tourismus-wegen-covid-19-stark-gelitten\/","title":{"rendered":"2020 hat der internationale Tourismus wegen Covid-19 stark gelitten"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div>\n<div class=\"mod mod-ws_detail\">\n<div class=\"ws_detail-press\">\n<p><b>Der Tourismussektor wurde 2020 von der Covid-19-Pandemie hart getroffen. Die Zahl der Reisenden ging deutlich zur\u00fcck. In der Fremdenverkehrsbilanz mit den erfassten Einnahmen und Ausgaben spiegelt sich der gewaltige Einbruch wider. Die Einnahmen aus dem Fremdenverkehr sanken um 47,8% auf 9,4 Milliarden Franken und fielen somit auf ihren Stand zu Beginn der 1990er-Jahre. Gleichzeitig halbierten sich die Ausgaben der Schweizer Bev\u00f6lkerung f\u00fcr Reisen im Ausland nahezu. Gem\u00e4ss ersten Sch\u00e4tzungen des Bundesamtes f\u00fcr Statistik (BFS) bel\u00e4uft sich der Saldo der Fremdenverkehrsbilanz auf \u2013290 Millionen Franken.<\/b><\/p>\n<p>Die Schweizer Wohnbev\u00f6lkerung gab im Jahr 2020 f\u00fcr Reisen im Ausland 9,7 Milliarden Franken aus, das sind 48,5% weniger als 2019. Im gleichen Zeitraum wendeten die ausl\u00e4ndischen Besucherinnen und Besucher f\u00fcr Reisen in der Schweiz 9,4 Milliarden Franken auf (\u201347,8%).<\/p>\n<p>Ab M\u00e4rz 2020 nahm die Zahl der Touristinnen und Touristen in der Schweiz stark ab. Die Hotellerie, die 2019 einen Rekordwert bei den Logiern\u00e4chten verzeichnet hatte, wurde stark in Mitleidenschaft gezogen. Die Zahl der Logiern\u00e4chte von ausl\u00e4ndischen G\u00e4sten brach 2020 gegen\u00fcber dem Vorjahr um zwei Drittel ein. Bei den Einnahmen aus \u00dcbernachtungen in Beherbergungsst\u00e4tten und bei Verwandten war der R\u00fcckgang somit besonders markant. Auch bei den Einnahmen aus Studien- und Spitalaufenthalten waren die Auswirkungen der Covid-19-Pandemie zu sp\u00fcren, auch wenn die Mobilit\u00e4t der Studierenden relativ hoch blieb. Der Reiseverkehr mit \u00dcbernachtungen fiel um rekordverd\u00e4chtige 56,0%.<\/p>\n<p>Bei den Reisen ohne \u00dcbernachtungen fiel die Abnahme moderater aus (\u201331,9%), f\u00fcr die Schweizer Wirtschaft resultierte daraus ein Einnahmer\u00fcckgang von nahezu 2 Milliarden Franken. W\u00e4hrend sich die Einnahmen aus dem Tages- und Transitverkehr infolge der vor\u00fcbergehenden Schliessung der Grenzen stark verringerten, hielten die Konsumausgaben der ausl\u00e4ndischen Personen mit Grenzg\u00e4nger- oder Kurzaufenthaltsstatus dem Druck besser stand. Dies l\u00e4sst sich dadurch erkl\u00e4ren, dass die r\u00fcckl\u00e4ufigen Konsumausgaben der von Kurzarbeit betroffenen Grenzg\u00e4ngerinnen und Grenzg\u00e4nger teilweise durch die insgesamt positive Entwicklung der Anzahl erwerbst\u00e4tiger Personen mit Grenzg\u00e4ngerstatus im Jahr 2020 kompensiert wurden.<\/p>\n<p><b>Ausgaben der Schweizer Bev\u00f6lkerung im Ausland um die H\u00e4lfte gesunken<\/b><\/p>\n<p>Neben den Einnahmen aus dem Fremdenverkehr waren auch die Gesundheitsmassnahmen und die beschlossenen Einschr\u00e4nkungen im Zusammenhang mit der Covid-19-Pandemie f\u00fcr den drastischen R\u00fcckgang der Ausgaben in der Fremdenverkehrsbilanz ausschlaggebend. Die St\u00e4rke des Schweizer Frankens gegen\u00fcber anderen W\u00e4hrungen und der in Deutschland eingef\u00fchrte Mindesteinkaufbetrag f\u00fcr den Erhalt einer Ausfuhrbescheinigung fielen weniger stark ins Gewicht. 2020 gab die Schweizer Wohnbev\u00f6lkerung insgesamt 9,7 Milliarden Franken f\u00fcr Reisen ins Ausland aus; das sind 48,5% weniger als 2019.<\/p>\n<p>Rund 57,9% dieser Ausgaben, d.h. 5,6 Milliarden Franken, waren auf den Reiseverkehr mit \u00dcbernachtungen zur\u00fcckzuf\u00fchren. Die entsprechenden Ausgaben gingen um 57,5% zur\u00fcck. Die Ausgaben f\u00fcr Reisen ohne \u00dcbernachtungen, die von den Grenzschliessungen zwischen Mitte M\u00e4rz und Mitte Juni 2020 am st\u00e4rksten betroffen waren, beliefen sich im Jahr 2020 auf 4,1 Milliarden Franken, was gegen\u00fcber 2019 einem R\u00fcckgang um 27,1% entspricht.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Schweizer Wohnbev\u00f6lkerung gab im Jahr 2020 f\u00fcr Reisen im Ausland 9,7 Milliarden Franken aus, das sind 48,5% weniger als 2019. Im gleichen Zeitraum wendeten die ausl\u00e4ndischen Besucherinnen und Besucher f\u00fcr Reisen in der Schweiz 9,4 Milliarden Franken auf (\u201347,8%)<\/p>\n","protected":false},"author":4,"featured_media":398888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-483291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/483291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=483291"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/483291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/398888"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=483291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=483291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=483291"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=483291"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=483291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}