{"id":509805,"date":"2021-10-15T22:50:55","date_gmt":"2021-10-15T20:50:55","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=509805"},"modified":"2021-10-15T22:50:55","modified_gmt":"2021-10-15T20:50:55","slug":"coronavirus-bundesrat-lanciert-impfoffensive","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/coronavirus-bundesrat-lanciert-impfoffensive\/","title":{"rendered":"Coronavirus: Bundesrat lanciert Impfoffensive"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p><strong>Der Bundesrat hat an seiner Sitzung vom 13. Oktober 2021 die Inhalte der geplanten Impfoffensive konkretisiert. Die Impfung bleibt das beste Mittel f\u00fcr den Ausstieg aus der aktuellen Krise. Um weitere Personen dazu zu bewegen, sich impfen zu lassen, plant der Bundesrat gemeinsam mit den Kantonen eine Impfwoche vom 8. bis zum 14. November. Zus\u00e4tzliche mobile Beratungs- und Impfstellen sollen einen niederschwelligen Zugang zur Impfung erm\u00f6glichen. Schliesslich finanziert der Bund die Bereitstellung von Beraterinnen und Beratern durch die Kantone, um auf das Bed\u00fcrfnis von noch nicht geimpften Personen nach Information einzugehen. Diese Impfoffensive kostet den Bund maximal 96.2 Millionen Franken.<\/strong><\/p>\n<p>Im Vergleich mit anderen europ\u00e4ischen L\u00e4ndern verzeichnet die Schweiz mit 71,2% vollst\u00e4ndig geimpften Personen ab 18 Jahren weiterhin eine tiefe Impfrate. Die Impfung bleibt jedoch das beste Mittel f\u00fcr den Ausstieg aus der Covid-19-Pandemie. Nur mit einer deutlich h\u00f6heren Impfrate kann die Bev\u00f6lkerung ausreichend immunisiert und vor schweren Erkrankungen gesch\u00fctzt sowie eine \u00dcberlastung des Gesundheitswesens verhindert werden. Nach dem heutigen Kenntnisstand sollte diese Impfrate \u2013 ohne Einrechnung der bereits genesenen Personen \u2013 bei den \u00fcber 65-J\u00e4hrigen bei ca. 93% und bei den 18- bis 65-J\u00e4hrigen bei 80% liegen, damit die geltenden Massnahmen aufgehoben werden k\u00f6nnen.<\/p>\n<p>Das derzeitige Impftempo ist zu langsam, zumal die Temperaturen zu sinken beginnen und die Pandemie sich wieder beschleunigen k\u00f6nnte. Deshalb hat der Bundesrat nach Konsultation der Kantone und der Sozialpartner beschlossen, gemeinsam mit den Kantonen eine gezielte Impfoffensive zu starten. Diese vom Bund finanzierte und von den Kantonen umgesetzte Impfoffensive besteht aus drei Teilen: einer nationalen Impfwoche, zus\u00e4tzlichen mobilen Beratungs- und Impfstellen sowie pers\u00f6nlichen Informationsangeboten. Aufgrund der Konsultationsergebnisse wurde auf die M\u00f6glichkeit verzichtet, Personen, die jemanden von der Impfung \u00fcberzeugen konnten, mit einem Gutschein zu belohnen.<\/p>\n<p><b>Nationale Impfwoche\u00a0<\/b><b>vom 8. bis zum 14. November<\/b><b>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/b><\/p>\n<p>Ziel dieser vom 8. bis zum 14. November dauernden Impfwoche ist es, m\u00f6glichst viele Menschen \u00fcber den Nutzen einer Impfung zu informieren, indem in mehreren Sprachen verl\u00e4ssliche Fakten zur Impfung auf verst\u00e4ndliche Art und Weise vermittelt werden, etwa zur Wirksamkeit, zur Sicherheit, zu den Nebenwirkungen der Impfstoffe, zu den gesundheitlichen Risiken einer Infektion oder zu den Impfm\u00f6glichkeiten. Neben einer nationalen Medienkampagne sind die Kantone, die Gemeinden und andere Partner aufgerufen, Informationsveranstaltungen oder lokale Anl\u00e4sse zur Information der Bev\u00f6lkerung zu organisieren. Der Bundesrat wird sich in einem Brief an die Bev\u00f6lkerung wenden, um die Bedeutung der Impfung zu unterstreichen. Die Kosten dieser Informationsmassnahmen werden vom Bund \u00fcbernommen und belaufen sich auf maximal 15.2 Millionen Franken.<\/p>\n<p><b>Mobile Beratungs- und Impfstellen<\/b><\/p>\n<p>Ebenfalls auf Zuspruch stiess in der Konsultation der Vorschlag, mit mobilen Beratungs- und Impfstellen wie beispielsweise Impfbussen noch nicht geimpften Personen den Zugang zu einer Beratung und allenfalls einer spontanen Impfung niederschwellig zu erm\u00f6glichen, indem man auf sie zugeht und ihnen Anfahrten erspart. Die Zahl der mobilen Beratungs- und Impfstellen liegt derzeit bei 50 und kann mit der Unterst\u00fctzung des Bundes deutlich erh\u00f6ht werden. Dieser \u00fcbernimmt bis zu 220\u00a0000 Franken pro zus\u00e4tzliche mobile Beratungs- und Impfstelle, insgesamt aber maximal 38 Millionen Franken.<\/p>\n<p><b>Individuelle Information<\/b><\/p>\n<p>Der Bund m\u00f6chte auch noch untentschlossene Personen individuell beraten. Die Beratung soll mittels Gruppengespr\u00e4chen, pers\u00f6nlichen oder telefonischen Kontakten oder \u00fcber die individuelle Chat-Funktion in den Sozialen Medien erfolgen. Die Beratungspersonen erfahren nicht und fragen nicht, ob eine Person, die sie ansprechen, geimpft ist oder nicht. Weder Bund noch Kantone sind in Besitz solcher Daten. Die Beratungspersonen gehen auf die Informationsbed\u00fcrfnisse der Bev\u00f6lkerung ein und unterst\u00fctzen die Menschen beispielsweise dabei, ein Impfzentrum zu finden, eine \u00c4rztin oder einen Arzt zu kontaktieren oder eine \u00dcbersetzerin oder einen \u00dcbersetzer hinzuzuziehen.<\/p>\n<p>Die Kantone k\u00f6nnen selbst Beratungspersonen rekrutieren, aber auch Organisationen oder Institutionen wie die Spitex oder verschiedene Beratungsstellen mit dieser Beratungst\u00e4tigkeit beauftragen. Der Bund deckt die Kosten, die durch den Einsatz dieser Beratungspersonen entstehen. Daf\u00fcr sind 43 Millionen Franken vorgesehen.<\/p>\n<p><b>Nachhaltige Investition<\/b><\/p>\n<p>F\u00fcr den Bund fallen durch die Impfoffensive maximale Kosten von 96.2 Millionen Franken an. Verglichen mit den Kosten der Wunschtests von rund 50 Millionen Franken pro Woche ist diese Investition nachhaltig. Eine hohe Impfrate bietet zudem einen unbestrittenen gesundheitspolitischen und wirtschaftlichen Nutzen: Im Schnitt kann pro 100 Impfungen eine Hospitalisierung und pro 250 Impfungen eine Belegung auf der Intensivstation vermieden werden. Hinzu kommt, dass durch die Vermeidung von Lockdowns weitere Kosten gespart werden k\u00f6nnen. Dies kommt insbesondere den betroffenen Branchen wie der Gastronomie und Hotellerie, den Fitnesszentren oder der Unterhaltungsindustrie zu Gute.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>m weitere Personen dazu zu bewegen, sich impfen zu lassen, plant der Bundesrat gemeinsam mit den Kantonen eine Impfwoche vom 8. bis zum 14. November<\/p>\n","protected":false},"author":4,"featured_media":500858,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22520,24006,1140],"tags":[],"vendi":[],"content_country":[29888,31836,31837],"class_list":["post-509805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus-minute-fuer-minute","category-lajme-jeta-ne-zvicer-de","category-leben-in-der-schweiz","content_country-zvicer","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/509805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=509805"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/509805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/500858"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=509805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=509805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=509805"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=509805"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=509805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}