{"id":517251,"date":"2021-11-13T12:00:55","date_gmt":"2021-11-13T11:00:55","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=517251"},"modified":"2021-11-13T12:00:55","modified_gmt":"2021-11-13T11:00:55","slug":"neue-tourismusstrategie-bundesrat-entwickelt-bewaehrte-politik-weiter","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/neue-tourismusstrategie-bundesrat-entwickelt-bewaehrte-politik-weiter\/","title":{"rendered":"Neue Tourismusstrategie: Bundesrat entwickelt bew\u00e4hrte Politik weiter"},"content":{"rendered":"<p><strong>Bern,\u00a010.11.2021\u00a0&#8211;\u00a0Der Bundesrat hat am 10. November 2021 die neue Tourismusstrategie des Bundes verabschiedet. Diese bildet die Grundlage f\u00fcr die Tourismuspolitik des Bundes und setzt die Stossrichtung der bisherigen, bew\u00e4hrten Strategie fort. Mit der neuen Tourismusstrategie wird insbesondere der Beitrag der Tourismuspolitik zur nachhaltigen Entwicklung des Tourismus gest\u00e4rkt. Ein weiterer Schwerpunkt wird auf die Weiterentwicklung der Investitionsf\u00f6rderung des Bundes gelegt.<\/strong><\/p>\n<p>Mit der am 10. November 2021 verabschiedeten Tourismusstrategie hat der Bundesrat \u00fcber die Umsetzung der Tourismuspolitik des Bundes in den vergangenen Jahren informiert. Gleichzeitig legte er die aktualisierte und erneuerte Tourismusstrategie des Bundes vor. Damit wird die Tourismusstrategie aus dem Jahr 2017 als strategische Grundlage der Tourismuspolitik des Bundes abgel\u00f6st.<\/p>\n<p>Die Covid-19-Pandemie hat den Schweizer Tourismus rasch und hart getroffen. Die Tourismusnachfrage ist ab M\u00e4rz 2020 stark zur\u00fcckgegangen. Zurzeit ist nicht absehbar, wann die Auswirkungen der Covid-19-Pandemie vollst\u00e4ndig \u00fcberwunden sein werden. Bei der Bew\u00e4ltigung der unmittelbaren Auswirkungen der Pandemie wird der Schweizer Tourismus durch zahlreiche allgemeine sowie tourismusspezifische St\u00fctzungsmassnahmen unterst\u00fctzt. So hat der Bundesrat beispielsweise am 1. September 2021 ein Recovery Programm f\u00fcr den Schweizer Tourismus f\u00fcr die Jahre 2022-2026 beschlossen.<\/p>\n<p><strong>Bew\u00e4hrte Politik weiterentwickeln<\/strong><\/p>\n<p>Der Bundesrat ist der Ansicht, dass sich die bisherige Tourismusstrategie des Bundes bew\u00e4hrt hat, auch vor dem Hintergrund der Covid-19-Pandemie. Die Ziele adressieren die Herausforderungen und die Bed\u00fcrfnisse des Schweizer Tourismus und setzen Schwerpunkte, die eine fokussierte Umsetzung der Tourismuspolitik des Bundes erm\u00f6glichen.<\/p>\n<p>Die Umsetzungsorientierung der Tourismuspolitik stellt deren Agilit\u00e4t sowie Aktions- und Reaktionsf\u00e4higkeit sicher. Der Bundesrat h\u00e4lt deshalb bei der Erneuerung der Tourismusstrategie an deren bisherigen Konzeption fest.<\/p>\n<p>Die Ziele der bisherigen Tourismusstrategie des Bundes werden beibehalten: Rahmenbedingungen verbessern, Unternehmertum f\u00f6rdern, Chancen der Digitalisierung nutzen und Attraktivit\u00e4t des Angebots und des Marktauftritts st\u00e4rken. Zus\u00e4tzlich wird das Ziel \u00abZur nachhaltigen Entwicklung beitragen\u00bb aufgenommen. Die nachhaltige Entwicklung bietet f\u00fcr den Tourismus zahlreiche Chancen, die es zu nutzen gilt.<\/p>\n<p><strong>Tourismuspolitische F\u00f6rderinstrumente<\/strong><\/p>\n<p>F\u00fcr die Umsetzung der Tourismusstrategie des Bundes sind die vier bew\u00e4hrten tourismuspolitischen F\u00f6rderinstrumente von Bedeutung: F\u00f6rderung von Innovation, Zusammenarbeit und Wissensaufbau im Tourismus (\u00abInnotour\u00bb), Schweizerische Gesellschaft f\u00fcr Hotelkredit (SGH), Schweiz Tourismus (ST) sowie Neue Regionalpolitik (NRP). Inhaltlich wird in den kommenden Jahren ein Schwerpunkt auf die Weiterentwicklung der Investitionsf\u00f6rderung des Bundes gelegt. Ziel ist es, die Investitionsf\u00f6rderung der SGH und der NRP zu modernisieren und zu st\u00e4rken.<\/p>\n<p><strong>Begleitung durch Tourismusakteure<\/strong><\/p>\n<p>Die Umsetzung der Tourismusstrategie des Bundes wird seit 2017 durch eine Begleitgruppe unterst\u00fctzt. Tourismusunternehmerinnen und -unternehmer, Vertreterinnen und Vertreter der Politik, der Tourismusverb\u00e4nde, der Kantone und der Wissenschaft sind vertreten. Die Begleitgruppe hat sich bew\u00e4hrt und ist f\u00fcr die Umsetzung der Tourismuspolitik des Bundes von entscheidender Bedeutung. W\u00e4hrend der Covid-19-Pandemie hat die Begleitgruppe den direkten und regelm\u00e4ssigen Austausch zwischen dem Eidgen\u00f6ssischen Departement f\u00fcr Wirtschaft, Bildung und Forschung (WBF),dem Staatssekretariat f\u00fcr Wirtschaft (SECO) und den relevanten Tourismusakteuren erm\u00f6glicht. Auch in Zukunft soll die Umsetzung der Tourismusstrategie des Bundes durch eine Begleitgruppe unterst\u00fctzt werden.<\/p>\n<p>Das WBF wird dem Bundesrat in vier Jahren erneut \u00fcber die Umsetzung der Tourismuspolitik des Bundes Bericht erstatten, d.h. per Ende 2025. Dabei werden die strategischen Grundlagen der Tourismuspolitik \u00fcberpr\u00fcft und bei Bedarf angepasst.<\/p>\n<p><a href=\"https:\/\/www.admin.ch\/gov\/de\/start\/dokumentation\/medienmitteilungen.msg-id-85811.html\">admin.ch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bern,\u00a010.11.2021\u00a0&#8211;\u00a0Der Bundesrat hat am 10. November 2021 die neue Tourismusstrategie des Bundes verabschiedet. Diese bildet die Grundlage f\u00fcr die Tourismuspolitik des Bundes und setzt die Stossrichtung der bisherigen, bew\u00e4hrten Strategie fort. Mit der neuen Tourismusstrategie wird insbesondere der Beitrag der Tourismuspolitik zur nachhaltigen Entwicklung des Tourismus gest\u00e4rkt. Ein weiterer Schwerpunkt wird auf die Weiterentwicklung der [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":381507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,24656,1140],"tags":[],"vendi":[31855],"content_country":[],"class_list":["post-517251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-tourismus","category-leben-in-der-schweiz","vendi-bern-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/517251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=517251"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/517251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/381507"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=517251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=517251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=517251"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=517251"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=517251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}