{"id":523901,"date":"2021-12-07T09:00:54","date_gmt":"2021-12-07T08:00:54","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=523901"},"modified":"2021-12-16T00:23:28","modified_gmt":"2021-12-15T23:23:28","slug":"sommersaison-2021-logiernaechte-in-der-schweizer-hotellerie-legen-um-345-zu","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/sommersaison-2021-logiernaechte-in-der-schweizer-hotellerie-legen-um-345-zu\/","title":{"rendered":"Sommersaison 2021: Logiern\u00e4chte in der Schweizer Hotellerie legen um 34,5% zu"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div>\n<div class=\"mod mod-ws_detail\">\n<div class=\"ws_detail-press\">\n<p><b>Die Schweizer Hotellerie verzeichnete in der Sommersaison 2021 (Mai bis Oktober) insgesamt 18,2 Millionen Logiern\u00e4chte. Dies entspricht gegen\u00fcber der entsprechenden Vorjahresperiode einer Zunahme um 34,5% (+4,7 Millionen Logiern\u00e4chte). Die ausl\u00e4ndische Nachfrage legte um 78,8% auf 5,6 Millionen Logiern\u00e4chte zu (+2,5 Millionen). Bei den inl\u00e4ndischen G\u00e4sten stieg die Nachfrage um 21,3% (+2,2 Millionen) auf 12,7 Millionen Logiern\u00e4chte. Dies geht aus den provisorischen Ergebnissen des Bundesamtes f\u00fcr Statistik (BFS) hervor.<\/b><\/p>\n<p>In der Sommersaison 2021 blieb die Nachfrage im Vergleich zur entsprechenden Vorjahresperiode weiterhin hoch. Ein sehr starker Anstieg wurde im Mai verzeichnet (+213,0%). Dieser Anstieg ist in Zusammenhang mit den 2020 geltenden pandemiebedingten Einschr\u00e4nkungen zu betrachten. In den Monaten Juni bis Oktober wurde ebenfalls eine steigende Nachfrage beobachtet. Diese reichte von 6,0% (Juli) bis 55,4% (Juni). Gegen\u00fcber der Sommersaison 2019 fielen die Logiern\u00e4chte in der Sommersaison 2021 hingegen um 19,5% tiefer aus.<\/p>\n<p><b>Steigende inl\u00e4ndische Nachfrage\u00a0<\/b><\/p>\n<p>In der Sommersaison 2021 stieg die Logiern\u00e4chtezahl der Schweizer G\u00e4ste gegen\u00fcber der entsprechenden Vorjahresperiode um 21,3% und kletterte damit auf den Rekordwert von 12,7 Millionen. Im Vergleich zu 2019 betrug die Zunahme 29,0%. Namentlich im Mai 2021 fiel die inl\u00e4ndische Nachfrage mit einem Plus von 196,8% gegen\u00fcber Mai 2020 besonders hoch aus. Die Monate Juni (+48,8%), August (+13,5%), September (+3,0%) und Oktober (+14,8%) verzeichneten gegen\u00fcber den entsprechenden Vorjahresmonaten ebenfalls ein Logiern\u00e4chteplus, wenn auch in geringerem Ausmass. Einzig im Juli gingen die Logiern\u00e4chte um 3,1% zur\u00fcck. Dabei ist anzumerken, dass die Schweizer G\u00e4ste im Juli 2020 mit einem Plus von 35,0% gegen\u00fcber 2019 einen Rekordwert erreicht hatten.<\/p>\n<p><b>Ausl\u00e4ndische Nachfrage wieder erstarkt\u00a0<\/b><\/p>\n<p>Die ausl\u00e4ndische Nachfrage nahm in der Sommersaison 2021 gegen\u00fcber der entsprechenden Vorjahresperiode deutlich zu (+78,8%). Alle Monate dieser Periode verzeichneten ein Plus. Besonders hoch war die Zunahme in den Monaten Mai (+321,3%) und Oktober (+161,3%). Dies ist auf die \u00e4usserst tiefe Logiern\u00e4chtezahl der ausl\u00e4ndischen G\u00e4ste im Vorjahr zur\u00fcckzuf\u00fchren. Trotz dieser Zunahme fiel die Logiern\u00e4chtezahl in der Sommersaison 2021 gegen\u00fcber 2019 um 56,6% tiefer aus.<\/p>\n<p>Differenziert nach Herkunft der G\u00e4ste nahm die Nachfrage in der Sommersaison 2021 gegen\u00fcber der entsprechenden Vorjahresperiode aus allen Kontinenten stark zu. Die Logiern\u00e4chte der G\u00e4ste aus Europa legten um 51,0% zu (+1,5 Millionen). Sie machten mit 4,4 Millionen 79,0% aller ausl\u00e4ndischen Logiern\u00e4chte aus. Die G\u00e4ste aus Asien (+602,3% \/ +468 000 Logiern\u00e4chte) und aus Amerika (+483,5% \/ +466 000) verbuchten ebenfalls mehr Logiern\u00e4chte. Dennoch lag die Nachfrage aus diesen Kontinenten 2021 weit unter jener von 2019: Die G\u00e4ste aus Asien verzeichneten ein Logiern\u00e4chteminus von 85,4%, jene aus Amerika von 74,0% und Besucherinnen und Besucher aus Europa von 32,5%.<\/p>\n<p><b>Logiern\u00e4chteplus in allen Tourismusregionen<\/b><\/p>\n<p>In der Sommersaison 2021 wiesen alle Tourismusregionen gegen\u00fcber der entsprechenden Vorjahresperiode ein Logiern\u00e4chteplus aus. Die drei st\u00e4dtischen Regionen Basel, Z\u00fcrich und Genf verbuchten gegen\u00fcber 2020 sehr starke Zunahmen zwischen 75,8% und 136,8%. Verglichen mit der Sommersaison 2019 sind jedoch deutliche R\u00fcckg\u00e4nge zu beobachten. Trotz des 2021 in allen Tourismusregionen verzeichneten markanten Anstiegs, legten die Logiern\u00e4chte gegen\u00fcber 2019 lediglich im Tessin (+27,7%), im Jura &amp; Drei-Seen-Land (+16,6%), in Graub\u00fcnden (+13,5%) und in der Ostschweiz (+7,6%) zu.<\/p>\n<p>Von Mai bis Oktober 2021 steigerte sich die inl\u00e4ndische Nachfrage gegen\u00fcber 2020 in allen Tourismusregionen deutlich. Zehn der dreizehn Regionen verbuchten bei der inl\u00e4ndischen Nachfrage sogar h\u00f6here Werte als 2019. Obschon die drei st\u00e4dtischen Regionen 2021 am st\u00e4rksten zulegen konnten, blieb die Nachfrage noch unter jener von 2019. Die ausl\u00e4ndischen Logiern\u00e4chte nahmen gegen\u00fcber 2020 ebenfalls in allen Tourismusregionen deutlich zu, und auch hier waren die st\u00e4rksten Zunahmen in den st\u00e4dtischen Regionen zu beobachten. Die ausl\u00e4ndische Nachfrage lag jedoch in allen Tourismusregionen noch unter jener von 2019.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ein sehr starker Anstieg wurde im Mai verzeichnet (+213,0%). Dieser Anstieg ist in Zusammenhang mit den 2020 geltenden pandemiebedingten Einschr\u00e4nkungen zu betrachten<\/p>\n","protected":false},"author":4,"featured_media":226547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,22520,1140,1412,2015],"tags":[],"vendi":[],"content_country":[29888,31836,31837],"class_list":["post-523901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-coronavirus-minute-fuer-minute","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de","content_country-zvicer","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/523901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=523901"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/523901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/226547"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=523901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=523901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=523901"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=523901"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=523901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}