{"id":545007,"date":"2022-03-06T12:33:25","date_gmt":"2022-03-06T11:33:25","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=545007"},"modified":"2022-03-06T22:08:48","modified_gmt":"2022-03-06T21:08:48","slug":"bundesrat-baut-administrative-huerden-bei-der-zuwanderung-aus-drittstaaten-ab","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/bundesrat-baut-administrative-huerden-bei-der-zuwanderung-aus-drittstaaten-ab\/","title":{"rendered":"Bundesrat baut administrative H\u00fcrden bei der Zuwanderung aus Drittstaaten ab"},"content":{"rendered":"<div class=\"contentHead\"><strong>Der Bundesrat hat an seiner Sitzung vom 4. M\u00e4rz 2022 eine Reihe von Massnahmen zur Optimierung der Zulassung von qualifizierten Erwerbst\u00e4tigen aus Drittstaaten beschlossen. Damit k\u00f6nnen administrative H\u00fcrden abgebaut und die Innovationskraft der Wirtschaft gest\u00e4rkt werden. Die Massnahmen sind sozialvertr\u00e4glich und entsprechen in Bezug auf die Steuerung der Zuwanderung der Verfassung. Als Sofortmassnahme sollen bis Ende 2022 erste administrative Erleichterungen in Bereichen mit ausgewiesenem Fachkr\u00e4ftemangel umgesetzt werden.<\/strong><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p>Der Bundesrat zeigt in seinem Bericht, den er am 4. M\u00e4rz 2022 in Erf\u00fcllung des Postulats Nantermod (19.3651) verabschiedet hat, eine Reihe von m\u00f6glichen Massnahmen auf, die den Abbau administrativer H\u00fcrden zum Ziel haben, Prozessbeschleunigungen erm\u00f6glichen, die Innovationskraft der Schweizer Wirtschaft st\u00e4rken und die Rechtssicherheit f\u00fcr Unternehmen erh\u00f6hen. F\u00fcr einige Massnahmen hat er direkt die Umsetzung beschlossen, f\u00fcr andere hat er eine Pr\u00fcfung in Auftrag gegeben.<\/p>\n<h3>Konkrete Massnahmen<\/h3>\n<p>Zwei der drei Massnahmen, die vom Eidgen\u00f6ssischen Justiz- und Polizeidepartement (EJPD) direkt auf Weisungsstufe umgesetzt werden, betreffen die Zulassungsvoraussetzungen f\u00fcr erwerbst\u00e4tige Drittstaatsangeh\u00f6rige. So soll bei Berufen mit nachweislich starkem Fachkr\u00e4ftemangel darauf verzichtet werden, in jedem Einzelfall zu pr\u00fcfen, ob das inl\u00e4ndische Fachkr\u00e4ftepotential ausgesch\u00f6pft worden ist. Ausserdem sollen k\u00fcnftig auch Personen in qualifizierten T\u00e4tigkeiten mit ausgewiesenem Fachkr\u00e4ftemangel eine Aufenthaltsbewilligung erhalten k\u00f6nnen, auch wenn sie keine akademische Bildung vorzuweisen haben. Bisher ist das nur bei Personen mit besonderen beruflichen Kenntnissen m\u00f6glich.<\/p>\n<p>Die dritte Massnahme vereinfacht den Wechsel von einer unselbst\u00e4ndigen zu einer selbst\u00e4ndigen Erwerbst\u00e4tigkeit von Inhaberinnen und Inhabern einer Aufenthaltsbewilligung. Diese drei Massnahmen sollen bis Ende 2022 umgesetzt werden. Im Rahmen einer n\u00e4chsten Revision des Ausl\u00e4nder- und Integrationsgesetzes, sp\u00e4testens bis Ende Dezember 2023, soll das EJPD zudem dem Bundesrat eine Botschaft vorlegen, welche die rechtlichen Voraussetzungen f\u00fcr die Aufhebung der Bewilligungspflicht beim Wechsel von einer unselbst\u00e4ndigen zu einer selbst\u00e4ndigen Erwerbst\u00e4tigkeit schafft.<\/p>\n<p>Zus\u00e4tzliche Verbesserungen am Kontingentssystem f\u00fcr qualifizierte Fachkr\u00e4fte aus Drittstaaten sollen durch das EJPD in Zusammenarbeit mit dem Departement f\u00fcr Wirtschaft, Bildung und Forschung (WBF) und unter Einbezug der Kantone und Sozialpartner einer vertieften Pr\u00fcfung unterzogen werden. Ausserdem pr\u00fcft das EJPD, ob eine Expressgeb\u00fchr eingef\u00fchrt werden kann, welche die Verfahren auf Stufe Bund und Kantone beschleunigen k\u00f6nnte. Das EJPD erstattet dem Bundesrat bis Ende M\u00e4rz 2023 Bericht \u00fcber die Ergebnisse dieser Pr\u00fcfauftr\u00e4ge und unterbreitet ihm einen Vorschlag f\u00fcr das weitere Vorgehen.<\/p>\n<h3>Bericht zur Zuwanderung aus Drittstaaten<\/h3>\n<p>Mit dem Postulat \u00abF\u00fcr eine Zuwanderungsregelung, die den Bed\u00fcrfnissen der Schweiz entspricht\u00bb (19.3651, Nantermod) hat das Parlament den Bundesrat aufgefordert, zu analysieren, ob das Zulassungssystem f\u00fcr Erwerbst\u00e4tige aus Drittstaaten verbessert werden kann, und ob das geltende Kontingentsmodell ersetzt werden soll. Dazu hat das Staatssekretariat f\u00fcr Migration (SEM) eine Bed\u00fcrfniserhebung bei Wirtschaft, Sozialpartnern und Kantonen durchgef\u00fchrt.<\/p>\n<h3>Abkehr vom Kontingentssystem dr\u00e4ngt sich nicht auf<\/h3>\n<p>Diese Konsultation hat ergeben, dass das heutige System in seinen Grundz\u00fcgen nicht in Frage gestellt wird. Punktuelle Optimierungen aber sind erw\u00fcnscht, um die Erwartungssicherheit f\u00fcr die Wirtschaft mittelfristig weiter zu erh\u00f6hen und die Prozesse zu vereinfachen. Daher schl\u00e4gt der Bericht m\u00f6gliche Anpassungen vor, die sowohl den Anliegen der verschiedenen Anspruchsgruppen als auch dem verfassungsm\u00e4ssigen Auftrag in Bezug auf die Steuerung der Zuwanderung entsprechen. Die Zuwanderung muss zudem sozialvertr\u00e4glich bleiben. Eine Abkehr vom heutigen Kontingentssystem dr\u00e4ngt sich nicht auf.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Als Sofortmassnahme sollen bis Ende 2022 erste administrative Erleichterungen in Bereichen mit ausgewiesenem Fachkr\u00e4ftemangel umgesetzt werden<\/p>\n","protected":false},"author":4,"featured_media":505704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1188,1141,1140,1412,2015],"tags":[],"vendi":[],"content_country":[29888,31836,31837],"class_list":["post-545007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shkurt-ch-de","category-themen","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de","content_country-zvicer","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/545007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=545007"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/545007\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/505704"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=545007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=545007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=545007"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=545007"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=545007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}