{"id":564175,"date":"2022-05-24T00:45:28","date_gmt":"2022-05-23T22:45:28","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=564175"},"modified":"2022-05-24T23:58:52","modified_gmt":"2022-05-24T21:58:52","slug":"wef-davos-schweiz-und-deutschland-im-austausch-zu-wirtschafts-und-energiethemen","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/wef-davos-schweiz-und-deutschland-im-austausch-zu-wirtschafts-und-energiethemen\/","title":{"rendered":"WEF Davos: Schweiz und Deutschland im Austausch zu Wirtschafts- und Energiethemen"},"content":{"rendered":"<div class=\"contentHead\"><strong>Am 22. Mai 2022 haben sich Bundesr\u00e4tin Simonetta Sommaruga und Bundesrat Guy Parmelin im Vorfeld des WEF in Davos mit Robert Habeck getroffen, dem deutschen Vizekanzler und Bundesminister f\u00fcr Wirtschaft und Klimaschutz. Dabei haben sie \u00fcber die Auswirkungen des Ukraine-Kriegs insbesondere auf die Energieversorgung gesprochen. Beide L\u00e4nder sind daran, die Abh\u00e4ngigkeit von russischem Gas rasch zu senken sowie die Dekarbonisierung voranzutreiben. Um allf\u00e4llige Engp\u00e4sse besser bew\u00e4ltigen zu k\u00f6nnen, haben sie vereinbart, zur gegenseitigen Unterst\u00fctzung Verhandlungen f\u00fcr ein Solidarit\u00e4tsabkommen aufzunehmen.<\/strong><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p>Bundesr\u00e4tin Sommaruga, Vorsteherin des Eidgen\u00f6ssischen Departements f\u00fcr Umwelt, Verkehr, Energie und Kommunikation (UVEK), und Bundesrat Guy Parmelin, Vorsteher des Eidgen\u00f6ssisches Departement f\u00fcr Wirtschaft, Bildung und Forschung (WBF) haben vor dem Start des Jahrestreffens des World Economic Forum (WEF) Vizekanzler Robert Habeck in Davos empfangen. Das Gespr\u00e4ch stand unter dem Eindruck des Krieges in der Ukraine und dessen Auswirkungen auf Europa.<\/p>\n<p>Bundesr\u00e4tin Sommaruga hat mit Minister Habeck \u00fcber die Massnahmen gesprochen, welche die beiden L\u00e4nder getroffen haben, um die Abh\u00e4ngigkeit von russischem Gas zu senken und die n\u00f6tigen Gasreserven zu schaffen. Um f\u00fcr allf\u00e4llige Engp\u00e4sse besser gewappnet zu sein, haben verschiedene EU-L\u00e4nder begonnen, untereinander Abkommen zur gegenseitigen Unterst\u00fctzung zu pr\u00fcfen und abzuschliessen. Eine entsprechende Vereinbarung ist auch im Interesse der Schweiz und Deutschlands. Die Schweiz und Deutschland haben daher heute in Davos abgemacht, rasch die Verhandlungen f\u00fcr ein Solidarit\u00e4tsabkommen aufzunehmen<i>.<br \/>\n<\/i><\/p>\n<p>Thematisiert wurden auch die Massnahmen zur St\u00e4rkung der Stromversorgung. Aufgrund der hohen Preisausschl\u00e4ge und des erh\u00f6hten Liquidit\u00e4tsbedarfs der Stromunternehmen, hat der Bundesrat einen Rettungsschirm erarbeitet. Die deutsche Regierung hat Anfang April ebenfalls ein Schutzschild geschaffen. Eine sichere Stromversorgung ist f\u00fcr Bev\u00f6lkerung und Wirtschaft zentral. Entscheidend daf\u00fcr ist auch die Netzstabilit\u00e4t und eine entsprechend enge Zusammenarbeit zwischen den Nachbarl\u00e4ndern sowie innerhalb Europas. Bundesr\u00e4tin Sommaruga hat deutlich gemacht, dass die Schweiz f\u00fcr die Netzstabilit\u00e4t in Europa eine wichtige Rolle spielen kann und deshalb in die Arbeiten einbezogen werden sollte.<\/p>\n<p>Seitens WBF standen die bilateralen Wirtschaftsbeziehungen und die Beziehungen der Schweiz mit der EU im Zentrum des Gespr\u00e4ches. Bundesrat Guy Parmelin betonte, dass Deutschland der wichtigste Wirtschaftspartner der Schweiz ist, und dass sich auch die Partnerschaft mit der EU f\u00fcr beide Seiten vorteilhaft auswirkt. Der Entschluss der Schweiz, die Sanktionen der EU im Zusammenhang mit dem Ukraine-Krieg zu \u00fcbernehmen, ist das j\u00fcngste Beispiel daf\u00fcr, dass sich die Schweiz als Teil einer Wertegemeinschaft mit der EU sieht. Bundesrat Parmelin erl\u00e4uterte den Willen des Bundesrates, den bilateralen Weg mit der EU &#8211; neu mit einem breiten Paketansatz &#8211; fortzusetzen.<\/p>\n<p>Deutschland ist der mit Abstand wichtigste Handelspartner der Schweiz. Im vergangenen Jahr exportierte unser Land G\u00fcter im Wert von 51 Milliarden Franken, w\u00e4hrend sich die Importe auf 57 Milliarden beliefen. Deutschland und die Schweiz sind gegenseitig auch als Investoren von grosser Bedeutung. Die schweizerischen Direktinvestitionen in Deutschland betrugen Ende 2020 70 Milliarden Franken, w\u00e4hrend deutsche Unternehmen \u00fcber 38 Milliarden Franken in der Schweiz investierten.<\/p>\n<p>Bundesr\u00e4tin Sommaruga hat sich vor dem Gespr\u00e4ch mit Minister Habeck in Davos auch mit Arifin Tasrif, dem indonesischen Energieminister, sowie mit Xie Zhenhua, dem chinesischen Sondergesandten f\u00fcr das Klima zu einem Austausch getroffen<i>.<\/i><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Beide L\u00e4nder sind daran, die Abh\u00e4ngigkeit von russischem Gas rasch zu senken sowie die Dekarbonisierung voranzutreiben<\/p>\n","protected":false},"author":4,"featured_media":564186,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1188,1141,1140,1412,2015],"tags":[],"vendi":[],"content_country":[29888,31836,31837],"class_list":["post-564175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shkurt-ch-de","category-themen","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de","content_country-zvicer","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/564175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=564175"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/564175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/564186"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=564175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=564175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=564175"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=564175"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=564175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}