{"id":595024,"date":"2022-10-10T17:09:17","date_gmt":"2022-10-10T15:09:17","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=595024"},"modified":"2022-10-12T03:26:09","modified_gmt":"2022-10-12T01:26:09","slug":"weltlehrertag-2022-im-schatten-der-bildungskrise","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/weltlehrertag-2022-im-schatten-der-bildungskrise\/","title":{"rendered":"Weltlehrertag 2022 im Schatten der Bildungskrise"},"content":{"rendered":"<p><strong>Gem\u00e4ss einer Erhebung der UNESCO, Initianten des Weltlehrertages fehlt weltweit jeder zehnten Lehrkraft die entsprechende Ausbildung und im gleichen Atemzug h\u00e4lt UNESCO (Organisation der Vereinten Nationen f\u00fcr Erziehung, Wissenschaft und Kultur) fest, dass qualifizierte Bildung nur durch genug qualifizierte Lehrerinnen und Lehrer m\u00f6glich sei. Taulant Lulaj ausgewiesene und erfahrene Lehrperson aus Z\u00fcrich nickt mit ernster Miene und zeigt Verst\u00e4ndnis f\u00fcr die alarmante Situation. Zusammen mit Albinfo beleuchtet Herr Lulaj die Thematik im Kontext der Schweizer Volksschule und zeigt interessierten Leserinnen und Leser auf, weshalb man bei Bildungsbed\u00fcrfnissen immer von Kind zu Kind differenzieren muss.<\/strong><\/p>\n<p><strong>albinfo.ch: Herr Lulaj was ist Ihr Statement zum diesj\u00e4hrigen Motto des Weltlehrtages?<\/strong><\/p>\n<p><strong>Taulant Lulaj:<\/strong>\u00a0Ich denke, dass die gegenw\u00e4rtige Situation der Schweizer Volksschule eine besondere ist. Die Schule steht am Scheideweg und es braucht dringend L\u00f6sungen damit die Schule ihren gesellschaftlichen Auftrag auch in Zukunft wahrnehmen kann. Die gegenw\u00e4rtige \u00abKrise\u00bb, welche insbesondere durch den Lehrermangel gepr\u00e4gt ist, erachte ich aber auch als Chance sofern ihre Akteure auch wirklich gemeinsam nach gangbaren und sinnvollen L\u00f6sungen suchen. Nehmen wir das Motto des Weltlehrertags w\u00f6rtlich, so m\u00fcsste man den Bildungsbegriff ganz grunds\u00e4tzlich hinterfragen. Was brauchen Kinder und Jugendliche wirklich, damit erfolgreiche gesellschaftliche Integration m\u00f6glich wird. Auch auf dieser kleineren, unmittelbareren Ebene sind positive Ver\u00e4nderungen durch eine einzige Lehrperson m\u00f6glich.<\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/10\/taulant-dua.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-595028\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/10\/taulant-dua.jpg\" alt=\"\" width=\"540\" height=\"227\" \/><\/a><\/p>\n<p>Im Gespr\u00e4ch mit Eltern und Elternorganisationen f\u00e4llt mir vermehrt auf, dass immer mehr Eltern \u00fcber eine Privatschule oder Homeschooling (Schule zuhause) nachdenken. Das macht mir pers\u00f6nlich Sorgen, jedoch kann ich die Beweggr\u00fcnde und \u00c4ngste der Eltern auf der anderen Seite auch nachvollziehen. Der Mangel an ausgebildeten Lehrpersonen wird sich in den kommenden Jahren versch\u00e4rfen, daher m\u00fcssen meiner Meinung nach die P\u00e4dagogischen Hochschulen, die Kantone und die Politik in die Pflicht genommen werden. Eine Volksschule die versagt, gef\u00e4hrdet nicht zuletzt auch unseren sozialen Frieden und unseren Wohlstand in der Schweiz.<\/p>\n<p><strong>albinfo.ch: Herr Lulaj laut Ihrer Homepage <a href=\"https:\/\/www.dua-beratung.ch\">www.dua-beratung.ch<\/a>\u00a0haben Sie neben Ihrer Ausbildung als Lehrperson auch einen Master in Special Needs Education. Warum muss man sich auf Master-Niveau spezialisieren um mit Kindern mit besonderen Bed\u00fcrfnissen kompetent arbeiten zu k\u00f6nnen? Kinder mit besonderen Bed\u00fcrfnissen in der Schule brauchen doch lediglich einfachere Aufgaben und weniger Schule, wie erkl\u00e4ren Sie sich in diesem Fall die Notwendigkeit zur beruflichen Spezialisierung.<\/strong><\/p>\n<p><strong>Taulant Lulaj: <\/strong>Mit dem notwendigen sonderp\u00e4dagogischen Wissen \u00fcber Lernschw\u00e4chen oder Verhaltensschwierigkeiten kann der Unterricht und die F\u00f6rderung ganz anders gedacht werden. Durch eine ressourcenorientierte F\u00f6rderdiagnostik weiss man wo ein Kind wirklich steht und entwickelt mittels eines F\u00f6rderplanung wohin die Lernreise eines Kindes gehen soll damit es in seiner pers\u00f6nlichen und schulischen Entwicklung weiterkommt. Das sind nicht zwingend \u00abeinfachere Aufgaben\u00bb oder \u00abweniger Schule\u00bb. Die kompetente Auswahl passender Aufgaben, die der geplanten F\u00f6rderung dienen und dem Lernstand des Kindes angepasst sind hierbei essenziell damit ein Kind gen\u00fcgend heraus- jedoch nicht \u00fcberfordert wird. \u00abWeniger Schule\u00bb sehe ich in den seltensten F\u00e4llen als L\u00f6sung, da dies insbesondere diese Kinder, die sich ja irgendwie bereits stigmatisiert f\u00fchlen, der sozialen Integration in der Klasse beraubt. Man ist kein Teil der Klasse, man ist dann zeitweise einfach nur Gast. Dies muss unter allen Umst\u00e4nden verhindert werden. Letztlich wollen wir Menschen doch einfach dazugeh\u00f6ren k\u00f6nnen.<\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/10\/taulant-lulaj-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-595031\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/10\/taulant-lulaj-2.jpg\" alt=\"\" width=\"400\" height=\"501\" \/><\/a><\/p>\n<p>Man stelle sich eine fehlende sonderp\u00e4dagogische Kompetenz so vor: Wir w\u00fcrden mit einem Leiden am Arm auch nicht zum Arzt gehen wollen, der mal irgendwo beginnt zu behandeln und Medikamente zu verabreichen bis er nach Monaten auf die Idee k\u00e4me sich den Arm mal genauer anzuschauen und da punktuell anzusetzen. Wir w\u00e4ren vielleicht bereits nach dem ersten Termin nie wieder zu diesem Arzt hin, in der Schule haben Kinder und Jugendliche diese Wahl nicht. Diese lassen sich das mit sich machen oder rebellieren und bleiben so erst recht auf der Strecke.<\/p>\n<p><strong>albinfo.ch: Auch im Gespr\u00e4ch vor dem Interview erz\u00e4hlten Sie von Ihrer Beobachtung, dass manche Eltern sich weigern Hilfe von der Schule anzunehmen. Anderseits gibt es Eltern, die ungeduldig werden falls bei Ihrem Kind schulischer F\u00f6rdeberdarf erkannt wird, jedoch die Kinder auf eine Warteliste der Schule gestellt werden, weil beispielsweise Logop\u00e4denInnen, Heilp\u00e4dogenInnen oder DaZ-Lehrpersonen fehlen oder jene Fachlehrpersonen bereits volle Klassenzimmer haben. Bestimmte Eltern greifen auf privatem Weg zu externen Lehrpersonen um den besonderen Bed\u00fcrfnissen ihrer Kinder nachzugehen. Wie erkl\u00e4ren Sie sich das diese Diskrepanz?\u00a0<\/strong><\/p>\n<p><strong>Taulant Lulaj: <\/strong>Ich vermute, dass dies stark mit der eigenen Schulkarriere und dem kulturellen Hintergrund zu tun hat. Die Generation der albanischen Diaspora, die bereits Kinder im schulf\u00e4higen Alter hat, musste noch das sozialistische Schulsystem Jugoslawiens durchmachen. Da war das Verh\u00e4ltnis per se schon assymetrisch, da die Schule im Dienste des sozialistischen Regimes war. Man durfte sich gl\u00fccklich sch\u00e4tzen, wenn die Eltern so wenig wie m\u00f6glich mit der Schule zu tun hatten. In der Schweiz ist es aber wichtig, dass es eine Kooperation oder mindestens einen Dialog zwischen Eltern und Lehrpersonen gibt. Nur so kann gemeinsam f\u00fcr das Kind mehr erreicht werden. Kontraproduktiv ist, wenn die Eltern oder Lehrpersonen nichts voneinander halten. Das bringt ein Kind, welches ja sowohl seine Eltern als auch seine Lehrperson mag in einen unheimlichen Loyalit\u00e4tskonflikt.<\/p>\n<p>Auf der anderen Seite sind viele Eltern aber auch \u00abgebrannte Kinder\u00bb da sie insbesondere bei Verhaltensauff\u00e4lligkeiten sehr oft von Lehrpersonen kontaktiert werden. Da ich selbst Vater bin, w\u00fcrde mich das in dieser Lage selbst unheimlich stressen. W\u00fcrde ich das schweizerische Bildungssystem nicht kennen, umso mehr. Der angesprochene Lehrermangel versch\u00e4rft diese Situation noch, da den Lehrpersonen h\u00e4ufig auch ausreichend Wissen fehlt, wie mit St\u00f6rungen oder besonderen (Bildungs-)Bed\u00fcrfnissen im Unterricht umzugehen ist. Die Folge sind st\u00e4ndige Sanktionen und Schulausschl\u00fcsse, die wenig bis nichts bringen oder gar, dass das Kind in eine Sonderschule kommt.<\/p>\n<p>Der Mangel an Lehrpersonen ist schlimm genug, der Mangel an sonderp\u00e4dagogischen Fachpersonen wie Sonderp\u00e4dagogInnen, Logop\u00e4dInnen oder DaZ-Lehrpersonen ist eine Trag\u00f6die. Die schw\u00e4chsten Glieder des Schulsystems leiden unter dieser Situation, was sich auf Generationen hinaus r\u00e4chen d\u00fcrfte. Unter dem gegenw\u00e4rtigen Mangel verstehe ich dann auch Eltern die auf solche Massnahmen verzichten. Wie das angesprochene Beispiel mit dem Arzt, muss jemand wissen was er da tut, sonst\u00a0 hat das Kind den \u00abStempel\u00bb als F\u00f6rdersch\u00fclerin oder F\u00f6rdersch\u00fcler auf lange Zeit hinaus und nichts wurde gewonnen. Die Schulen braucht angesichts dieser Situation von aussen dringend Unterst\u00fctzung, was wir im sonderp\u00e4dagogischen Bereich mit DUA Beratungen bieten.<\/p>\n<p><strong>albinfo.ch: Gibt es so was wie eine Erfolgsgeschichte mit einem Sch\u00fcler, einer Sch\u00fclerin mit besonderen Bed\u00fcrfnissen, welche durch die Ressourcen der Schule zu ihrem individuellen Schulerfolg gelangte?\u00a0<\/strong><\/p>\n<p><strong>Taulant Lulaj: <\/strong>Das gab es in meiner Karriere als Klassenlehrperson und Sonderp\u00e4dagoge definitiv. Neben dem Fachwissen und der sonderp\u00e4dagogischen F\u00f6rderung m\u00f6chte ich eines hervorheben: Die vorurteilslose und wertsch\u00e4tzende Sicht auf diese Kinder und Jugendlichen. Meist haben diese jungen Menschen unheimliche Ressourcen, an die man ohne diese Sichtweise nicht herankommen w\u00fcrde. Ich hatte Sch\u00fclerinnen und Sch\u00fcler die Eltern hatten, die Schichtarbeiten ausf\u00fchrten. Diese Jugendlichen sorgten daf\u00fcr, dass ihre j\u00fcngeren Geschwister p\u00fcnktlich aufstanden und f\u00fcr die Schule bereit waren. W\u00e4hrend der Mittagszeit k\u00fcmmerten sie sich ganz alleine um das Mittag- und Abendessen. Neben der Schulzeit betreuten und verpflegten sie ihre Geschwister und gingen verantwortungsvoll mit dem Essensgeld um damit es f\u00fcr den Tag reicht. Diese Jugendlichen darf man beispielsweise nicht als unzuverl\u00e4ssig beschreiben, nur weil unter dieser riesigen Verantwortung hier und da etwas Schulisches mal auf der Strecke bleibt. Zeigt eine Lehrperson, dass ihm das Kind oder der Jugendliche wichtig ist und der Lernende sp\u00fcrt das, ist enormes Potenzial m\u00f6glich. Erfolg ist f\u00fcr mich dann, wenn alle gerne in die Schule kommen und dazugeh\u00f6ren.<\/p>\n<p>Der sichtbarste Erfolg wird nach der obligatorischen Schulzeit deutlich. Im Lehrbetrieb z\u00e4hlen pers\u00f6nliche Attribute und Eigenschaften mehr. Da k\u00f6nnen sich diese Sch\u00fcler beweisen. Schulisch sind sie nat\u00fcrlich auf weitere F\u00f6rderung angewiesen, w\u00e4hrend der gesamten Schulzeit haben sie ein Anrecht darauf, kaum ist die Schule vorbei, gibt es diese Hilfe nicht mehr, obwohl die Herausforderungen und der st\u00e4ndige Rollenwechsel vom Lehrling als Arbeitnehmenden und in der Berufsschule als Sch\u00fcler ihnen extrem viel abverlangen. Mit <a href=\"http:\/\/www.myndset.ch\">www.myndset.ch<\/a> wollen wir sonderp\u00e4dagogische F\u00f6rderung und Begleitung auch w\u00e4hrend der Lehrzeit sicherstellen. Die Ergebnisse bislang sind sehr vielversprechend.<\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/10\/taulant-dua-a.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-595025\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2022\/10\/taulant-dua-a.jpg\" alt=\"\" width=\"600\" height=\"149\" \/><\/a><\/p>\n<p><strong>albinfo.ch: Was w\u00e4re aus Sicht eines Kindes ein w\u00fcnschenswerter Umgang von Eltern mit dem \u00a0&#8220;besonderen Bed\u00fcrfnissen&#8221; ihrer eigenen Kinder und warum?<\/strong><\/p>\n<p><strong>Taulant Lulaj: <\/strong>Wichtig ist, dass diese Tabuisierung aufh\u00f6rt und man sich nicht vor der Tatsache verschliesst, dass dieses Kind dringend Unterst\u00fctzung braucht. Eine so aufwendige Selbstsabotage belastet auf Dauer jede Familie. Wichtiger ist es die Situation anzuerkennen und trotzdem f\u00fcr das Kind immer da zu sein. Weder die Eltern noch das Kind k\u00f6nnen etwas daf\u00fcr und das hat auch nichts damit zu tun, dass man als Elternteil irgendwo in der Erziehung versagt h\u00e4tte. Die Anerkennung ist der erste Schritt, als n\u00e4chstes muss man wissen, wie damit umzugehen ist und wo man n\u00f6tigenfalls Hilfe kriegt. Mit <a href=\"http:\/\/www.myndset.ch\">www.myndset.ch<\/a> einem sonderp\u00e4dagogischen Berufsintegrationsangebot unterst\u00fctze ich Jugendliche mit besonderem F\u00f6rderbedarf bei der Suche und w\u00e4hrend der gesamten Lehre. Insbesondere Eltern mit Migrationshintergrund kennen diese wertvollen Unterst\u00fctzungsangebote, wie bspw. die Unterst\u00fctzung durch die IV-Berufsberatung \u00fcberhaupt nicht. Diesen Eltern m\u00f6chte ich gerne kostenlos dabei helfen, da dies f\u00fcr mich eine Herzensangelegenheit ist und ich tagt\u00e4glich sehe, was erst durch diese Unterst\u00fctzung bei den Jugendlichen m\u00f6glich wird.<\/p>\n<p>Was ist wichtiger? Den Anschein zu wahren, dass alles in Ordnung ist, w\u00e4hrend das Kind st\u00e4ndig nur Misserfolge hat oder dass das Kind vielleicht ein Handicap hat, aber einen Umgang damit lernt und im Leben erfolgreich wie jedes andere sein kann? Ich m\u00f6chte Eltern dabei gerne unterst\u00fctzen.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zusammen mit albinfo.ch beleuchtet Herr Lulaj die Thematik im Kontext der Schweizer Volksschule und zeigt interessierten Leserinnen und Leser auf, weshalb man bei Bildungsbed\u00fcrfnissen immer von Kind zu Kind differenzieren muss<\/p>\n","protected":false},"author":4,"featured_media":595034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3908,3952,1129],"tags":[],"vendi":[],"content_country":[29888,31836,31837],"class_list":["post-595024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinungen","category-kosova-de","category-ch-balkan","content_country-zvicer","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/595024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=595024"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/595024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media\/595034"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=595024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=595024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=595024"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=595024"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=595024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}