{"id":93566,"date":"2015-09-22T09:42:54","date_gmt":"2015-09-22T07:42:54","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=93566"},"modified":"2015-09-27T22:33:40","modified_gmt":"2015-09-27T20:33:40","slug":"die-sozialdemokratische-partei-hat-sehr-starke-beziehungen-zu-albanern","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/die-sozialdemokratische-partei-hat-sehr-starke-beziehungen-zu-albanern\/","title":{"rendered":"&#8220;Die sozialdemokratische Partei hat sehr starke Beziehungen zu Albanern&#8221;"},"content":{"rendered":"<div>\n<p>In ihrem Interview f\u00fcr albinfo.ch spricht G\u00e9raldine Savary, Vize-Chefin der SP, \u00fcber die Gr\u00fcnde der Fl\u00fcchtlingskrise, \u00fcber die (Nicht-)M\u00f6glichkeiten von Personen mit Migrationshintergrund, an Wahlen anzutreten und abzustimmen, \u00fcber das Einb\u00fcrgerungsgesetz, \u00fcber die nunmehr traditionellen Beziehungen, die die albanische Gemeinde in der Schweiz mit der SP hat etc.<\/p>\n<p><strong>albinfo.ch:<\/strong> Was denken Sie \u00fcber die aktuelle Fl\u00fcchtlingskrise, \u00fcber die Migranten die vor den Toren Europas stehen? Welche L\u00f6sungen sind in dieser Situation angebracht?<\/p>\n<p><strong>Savary:<\/strong> Die aktuelle Fl\u00fcchtlingskrise ist unfassbar; sie ist die vielleicht schlimmste Krise seit dem Ende des zweiten Weltkrieges. Menschen fliehen wegen den furchtbaren Kriegen und der Gewalt in Afrika und im Nahen Osten, die teilweise eine Folge der Politik des Westens gegen\u00fcber diese Regionen sind. Wir m\u00fcssen jetzt menschlich und effektiv auf diese Krise antworten. Auf europ\u00e4ischer Ebene m\u00fcssen wir daf\u00fcr sorgen, dass die Fl\u00fcchtlinge fair verteilt werden. Es ist nicht in Ordnung, dass die gr\u00f6sste Last der Krise nur die L\u00e4nder der EU-Aussengrenzen im Osten und im S\u00fcden tragen m\u00fcssen. Und es ist nicht hinnehmbar, dass die EU-Aussengrenzen nun mit Stacheldraht gesch\u00fctzt werden. Wir sollten die Trag\u00f6die nicht noch mehr verschlimmern. Die Schweiz hat versprochen, Teil der L\u00f6sung zu sein, und sie muss Teil der L\u00f6sung werden. Wir haben die n\u00f6tigen menschlichen und technischen Kapazit\u00e4ten, um mehr Fl\u00fcchtlinge aufzunehmen. L\u00e4ngerfristig m\u00fcssen wir sicherhstellen, dass die Asylsuchenden sich intergrieren und arbeiten k\u00f6nnen. Schliesslich m\u00fcssen wir die Asylverfahren beschleunigen , so wie es im neuen Asylgesetz vorgesehen ist. Das System von Dublin hat gezeigt, dass es an seine Grenzen gestossen ist.<\/p>\n<p><strong>albinfo.ch:<\/strong> Was ist die Haltung Ihrer Partei bez\u00fcglich der Integration von Ausl\u00e4ndern in der Schweiz? Und wie sehen Sie die weitere Entwicklung der Schweizer Bev\u00f6lkerung mit albanischen Wurzeln?<\/p>\n<p><strong>Savary:<\/strong> Die Sozialdemokratische Partei pflegt sehr starke Beziehungen zur albanischen Gemeinde &#8211; viele Menschen mit albanischen Wurzeln sind Mitglieder unserer Partei. Vielleicht hat dies auch damit zu tun, dass die Schweiz eines der ersten L\u00e4nder war, das die Unabh\u00e4ngigkeit von Kosova anerkannt hatte, unter anderem mit Hilfe der sozialdemokratischen Ministerin Micheline Calmy-Rey. Die SP k\u00e4mpft schon seit langer Zeit f\u00fcr die Integration von Ausl\u00e4ndern. Auf Bundesebene setzen uns daf\u00fcr ein, dass die Budgets f\u00fcr Integration erhalten bleiben. Auf kantonaler und komunaler Ebene haben wir Massnahmen f\u00fcr eine bessere Aufnahme und Integtration von Ausl\u00e4ndern vorgeschlagen (st\u00e4rkere demokratische Rechte, Bildung f\u00fcr Kinder und Jugendliche, Sprachkurse, Unterst\u00fctzung f\u00fcr die Gemeinden etc.)<\/p>\n<p><strong>albinfo.ch:<\/strong> Welche Position vertritt die SP bez\u00fcflich der Reform des Einb\u00fcrgerungsrechts?<\/p>\n<p><strong>Savary:<\/strong> Die SP tut alles daf\u00fcr, dass die parlamentarische Initiatiative der Nationalr\u00e4ten Ada Marra f\u00fcr eine erleichterte Einb\u00fcrgerung der dritten Ausl\u00e4ndergeneration durchkommt.<\/p>\n<p>Und \u00fcberhaupt, das Parlament besteht aus Abgeorndeten mit einem mehr oder weniger gleichen Profil: m\u00e4nnlich, \u00fcber 50, Freiberufler mit Schweizer Hintergrund. Die Demokratie in der Schweiz kann nicht ohne Menschen mit Migrationshintergrund funktionieren. Es gibt ein Mangel an Represantivit\u00e4t. Dennoch haben wir in unserer Partei viele Kandidaten mit Migrationshintergrund, viele aus den Balkanl\u00e4ndern und besonders aus Kosova. Viele von denen kommen aus der deutschsprachigen Schweiz.<\/p>\n<p><strong>albinfo.ch:<\/strong> Welche Rolle nimmt der Balkan in der Aussenpolitik der Schweiz ein?<\/p>\n<p><strong>Savary:<\/strong> Es ist eine wichtige Region, von der wir viel lernen k\u00f6nnen. Der Balkan ist die Br\u00fccke zwischen unseren europ\u00e4ischen, slawischen, muslimischen, christlichen und orthodoxen Kulturen. Diese Region im Herzen Europas muss konsolidiert und der Frieden dort muss gesichert werden. Der Balkan muss eine Perspektive haben. Die Schweiz ist Teil der Friedensmission KFOR. L\u00e4ngerfristig m\u00fcssen wir besonders die Zusammenarbeit zwischen der Schweiz und Kosova weiter vertiefen. Die albanische Diaspora ist in dieser Hinsicht sehr wichtig. Wir m\u00fcssen den Austausch und die Partn\u00e4rit\u00e4t st\u00e4rken.<\/p>\n<\/div>\n<div><\/div>\n<div>\n<p><strong>albinfo.ch:<\/strong> In Ihrer Partei haben Sie eine Gruppe f\u00fcr Migrationsfragen und \u00e4hnliche Foren auf kantonaler Ebene. Was ist deren Rolle?<\/p>\n<p><strong>Savary:<\/strong> Deren Rolle besteht darin, die Forderungen der sozialdemokraten mit Migrationshintergrund an die Partei auszuformulieren. Wir wollen mit diesen Gruppen unseren Mitb\u00fcrgern mit Migrationshintergrund zeigen, dass die SP sich f\u00fcr die Grundrechte im Allgemeinen und f\u00fcr die Rechte der Migranten im Besonderen einsetzt.<\/p>\n<p><strong>albinfo.ch:<\/strong> Es gab immer viele Kandidaten der SP f\u00fcr die Gemeinde- und Kantonswahlen, die einen Migrationshintergrund haben. Haben Sie in Ihren Reihen auch vielversprechende Kandidaten f\u00fcr die anstehenden Nationalratswahlen vom 18. Oktober 2015?<\/p>\n<p><strong>Svary:<\/strong> Eine Erkl\u00e4rung hierf\u00fcr ist das Gesetz, das den Ausl\u00e4ndern das Recht einr\u00e4umt, auf komunaler, manchmal auf kantonaler Ebene abstimmen zu d\u00fcrfen. Das Recht auf Stimmabgabe besteht auf nationaler Ebene leider nicht. F\u00fcr Menschen mit Herkunft aus den Balkanl\u00e4ndern, die in den 1980er und 1990er Jahren in die Schweiz gekommen sind, ist es schwierig einen Bekanntheitsgrad zu erreichen, der sie bei den schwierigen Nationalratswahlen in den Nationalrat bringen w\u00fcrde. Doch ich bin davon \u00fcberzeugt, dass sich dies \u00e4ndern wird. Die Politikerinnen und Politiker mit Migrationshintergrund, die auf komunaler und kantonaler Ebene Verantwortung tragen, werden es langsam aber sicher schaffen, auch auf nationaler Ebene politische \u00c4mter und Verantwortung zu \u00fcbernehmen. Die Wahrheit ist, dass die Nationalratswahl ein Wettbewerb mit Hindernissen f\u00fcr ist.<\/p>\n<p><em><strong>Beziehungen der SP zur albanischen Gemeinde<\/strong><\/em><br \/>\n<em>Die Sozialdemokratische Partei pflegt sehr starke Beziehungen zur albanischen Gemeinde &#8211; viele Menschen mt albanischen Wurzeln sind Mitglieder unserer Partei. Vielleicht hat dies auch damit zu tun, dass die Schweiz eines der ersten L\u00e4nder war, das die Unabh\u00e4ngigkeit von Kosova anerkannt hatte, unter anderem mit Hilfe der sozialdemokratischen Ministerin Micheline Calmy-Rey. Die SP k\u00e4mpft schon seit langer Zeit f\u00fcr die Integration von Ausl\u00e4ndern. Auf bundesebene setzen uns daf\u00fcr ein, dass die Budgets f\u00fcr Integration erhalten bleiben. Auf kantonaler und komunaler Ebene haben wir Massnahmen f\u00fcr eine bessere Aufnahme und Integtration von Ausl\u00e4ndern (st\u00e4rkere demokratische Rechte, Bildung f\u00fcr Kinder und Jugendliche, Sprachkurse, Unterst\u00fctzung f\u00fcr die Gemeinden etc.)<\/em><\/p>\n<p><em><strong>Die Schweiz kann mehr Fl\u00fcchtlingen aufnehmen<\/strong><\/em><br \/>\n<em>Die Schweiz hat versprochen, Teil der L\u00f6sung zu sein, und sie muss teil der L\u00f6sung werden. Wir haben die <\/em><br \/>\n<em>n\u00f6tigen menschlichen und technischen Kapazit\u00e4ten, um mehr Fl\u00fcchtlinge aufzunehmen. L\u00e4ngerfristig m\u00fcssen wir sicherhstellen, dass die Asylsuchenden sich intergrieren und arbeiten k\u00f6nnen. Schliesslich m\u00fcssen wir die Asylverfahren beschleunigen , so wie es im neuen Asylgesetz vorgesehen ist. Das System von Dublin hat gezeigt, dass es an seine Grenzen gestossen ist.<\/em><\/p>\n<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>G\u00e9raldine Savary, SP-Vize-Chefin und Mitglied des St\u00e4nderates<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,2499,1140,2234,1158,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-93566","post","type-post","status-publish","format-standard","hentry","category-themen","category-die-schweiz-albaner-und-die-wahlen-2015","category-leben-in-der-schweiz","category-dossier-de","category-themen-vor-ort","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/93566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=93566"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/93566\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=93566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=93566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=93566"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=93566"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=93566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}