{"id":93703,"date":"2015-09-23T09:46:36","date_gmt":"2015-09-23T07:46:36","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=93703"},"modified":"2015-09-27T22:06:24","modified_gmt":"2015-09-27T20:06:24","slug":"muller-die-fdp-schaut-nicht-auf-die-herkunft-sondern-auf-die-integrationsfahigkeit","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/de\/muller-die-fdp-schaut-nicht-auf-die-herkunft-sondern-auf-die-integrationsfahigkeit\/","title":{"rendered":"M\u00fcller: Die FDP schaut nicht auf die Herkunft, sondern auf die Integrationsf\u00e4higkeit"},"content":{"rendered":"<p>In einem Interview f\u00fcr albinfo.ch spricht der Pr\u00e4sident der FDP\/PLR, Philipp M\u00fcller, \u00fcber die Werte, die seine Partei vertritt. Die ethnische Herkunft der Menschen, die in der Schweiz leben, hat f\u00fcr die FDP keine Priorit\u00e4t. Unter anderem sagt er: \u201eF\u00fcr die FDP\/PLR ist nicht die Nationalit\u00e4t bestimmend, sondern der Wille und die F\u00e4higkeit zur Integration.\u201c M\u00fcller spricht auch \u00fcber die Fl\u00fcchtlingskrise und Massnahmen f\u00fcr eine L\u00f6sung derselben.<\/p>\n<p><strong>albinfo.ch:<\/strong> Wie analysieren Sie die aktuelle Krise der Fl\u00fcchtlingsmigration in Richtung Europa und welche L\u00f6sung gibt es Ihrer Meinung nach in dieser Frage?<\/p>\n<p><strong>Philipp M\u00fcller:<\/strong> Die Situation f\u00fcr diese Menschen ist schlimm. Die FDP unterst\u00fctzt die Entwicklungshilfe und will, dass die Hilfe vor Ort und in den Nachbarstaaten der Konfliktzonen intensiviert wird. Die Situation zu verbessern gelingt allerdings nur, wenn eine gesamteurop\u00e4ische L\u00f6sung gefunden wird. Mit dem Status der Schutzbed\u00fcrftigen kann die Schweiz zudem Kriegsvertriebene aufnehmen. Wirtschaftsmigranten sollten aber nicht \u00fcber den Asylbereich zuwandern k\u00f6nnen.<\/p>\n<p><strong>albinfo.ch:<\/strong> Was f\u00fcr Ansichten hat Ihre Partei zur Integration der ausl\u00e4ndischen Bev\u00f6lkerung in der Schweiz? Wie beurteilen Sie den Integrationsprozess der Albanerinnen und Albaner in der Schweiz?<\/p>\n<p><strong>Philipp M\u00fcller:<\/strong> Wer in der Schweiz leben will, hat unsere Verfassung, die Gesetze und die schweizerischen Gepflogenheiten zu respektieren. Ausbildung und Integration sind zentrale Werte unserer Gesellschaft. Das sollte \u00fcber den Abschluss und die Einhaltung von Integrationsvereinbarungen verst\u00e4rkt ins Zentrum r\u00fccken. Das gilt f\u00fcr alle Nationalit\u00e4ten gleichermassen. F\u00fcr die FDP ist nicht die Nationalit\u00e4t, sondern der Wille und die F\u00e4higkeit sich zu integrieren entscheidend.<\/p>\n<p><strong>albinfo.ch:<\/strong> Wie steht Ihre Partei zur Revision des Einb\u00fcrgerungsgesetzes?<\/p>\n<p><strong>Philipp M\u00fcller:<\/strong> Die FDP hat die Revision des B\u00fcrgerrechts unterst\u00fctzt. Dies ist ein wichtiger Meilenstein zu klaren und einheitlichen Kriterien f\u00fcr die Einb\u00fcrgerung. Eine gelungene Integration muss Voraussetzung f\u00fcr die Einb\u00fcrgerung sein.<\/p>\n<p><strong>albinfo.ch:<\/strong> Sollte Ihrer Meinung nach die Migrationsbev\u00f6lkerung in der Schweiz in Bezug auf Teilnahme am gesellschaftlichen und politischen Leben der Schweiz als eigenst\u00e4ndiger Faktor behandelt werden?<\/p>\n<p><strong>Philipp M\u00fcller:<\/strong> Personen mit Migrationshintergrund sind f\u00fcr uns Teil der Gesellschaft. Politische Rechte sind mehrheitlich an das Schweizer B\u00fcrgerrecht gekoppelt. Es ist in erster Linie an den Kantonen und Gemeinden zu entscheiden, ob sie ein Stimm- und Wahlrecht f\u00fcr Ausl\u00e4nderinnen und Ausl\u00e4nder einf\u00fchren wollen. F\u00fcr die politischen Rechte ebenfalls eine gute Integration und eine l\u00e4nger dauernde Niederlassung in der Schweiz vorauszusetzen, kann aber sinnvoll sein.<\/p>\n<p><strong>albinfo.ch:<\/strong> Wie sieht es in Ihrer Partei in Bezug auf Kandidaturen von Personen ausl\u00e4ndischer Herkunft in den eidgen\u00f6ssischen Wahlen aus? Gibt es darunter Leute aus dem Balkan\/ Kosova?<\/p>\n<p><strong>Philipp M\u00fcller:<\/strong> F\u00fcr uns steht das liberale Gedankengut im Vordergrund. Wir unterscheiden nicht nach Herkunft. Wer unsere Werte teilt,\u00a0ist willkommen, mitzumachen.<\/p>\n<p><strong>albinfo.ch:<\/strong> Welche Haltung hat Ihre Partei zur Schweizer Aussenpolitik und welchen Platz nehmen darin die Staaten des Balkans in den Augen Ihrer Partei ein?<\/p>\n<p><strong>Philipp M\u00fcller:<\/strong> Im Bereich der Aussenpolitik steht f\u00fcr uns die Wirtschaftsaussenpolitik im Zentrum, insbesondere auch die Beziehungen der Schweiz zur EU. Wir unterst\u00fctzen den vom Bundesrat festgelegten aussenpolitischen Kurs. Die \u00a0Beziehungen mit den Balkanl\u00e4ndern nehmen darin seit mehreren Jahren einen besonderen Platz ein.<\/p>\n<p><strong>albinfo.ch:<\/strong> Wie sieht es bez\u00fcglich Teilnahme albanischsprachiger Aktivisten und Kandidatinnen in Ihrer Partei aus?<\/p>\n<p><strong>Philipp M\u00fcller:<\/strong> Die FDP f\u00fchrt nicht Buch \u00fcber die Sprachkenntnisse ihrer Mitglieder und Kandidierenden. Vereinzelt wissen wir durch pers\u00f6nliche Kontakte, welche Muttersprache die Mitglieder, Amtstr\u00e4ger oder Kandidierenden haben. Jedoch steht dies f\u00fcr uns nicht im Vordergrund.<\/p>\n<p><strong>albinfo.ch:<\/strong> Wird die FDP\/PLR schweizerische Investitionen im Balkan f\u00f6rdern, um die dort herrschende Arbeitslosigkeit zu mildern?<\/p>\n<p>Wir unterst\u00fctzen den Bundesrat hinsichtlich seiner entwicklungspolitischen Massnahmen.<\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/09\/capture-decran-2015-09-23-a-09.39.34.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-93698\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/09\/capture-decran-2015-09-23-a-09.39.34-199x300.png\" alt=\"Capture d\u2019e\u0301cran 2015-09-23 a\u0300 09.39.34\" width=\"199\" height=\"300\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/09\/capture-decran-2015-09-23-a-09.39.34-199x300.png 199w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/09\/capture-decran-2015-09-23-a-09.39.34-263x396.png 263w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2015\/09\/capture-decran-2015-09-23-a-09.39.34.png 393w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a><\/p>\n<p><em><strong>Nationalit\u00e4t der Kandidierenden steht nicht in Vordergrund <\/strong><\/em><\/p>\n<p><em>Die FDP f\u00fchrt nicht Buch \u00fcber die Sprachkenntnisse ihrer Mitglieder und Kandidierenden. Vereinzelt wissen wir durch pers\u00f6nliche Kontakte, welche Muttersprache die Mitglieder, Amtstr\u00e4ger oder Kandidierenden haben. Jedoch steht dies f\u00fcr uns nicht im Vordergrund.<\/em><\/p>\n<p><em><strong>Wirtschaftsaussenpolitik steht im Zentrum<\/strong><\/em><\/p>\n<p><em>Im Bereich der Aussenpolitik steht f\u00fcr uns die Wirtschaftsaussenpolitik im Zentrum, insbesondere auch die Beziehungen der Schweiz zur EU. Wir unterst\u00fctzen den vom Bundesrat festgelegten aussenpolitischen Kurs. Die \u00a0Beziehungen mit den Balkanl\u00e4ndern nehmen darin seit mehreren Jahren einen besonderen Platz ein.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In einem Interview f\u00fcr albinfo.ch spricht der Pr\u00e4sident der FDP\/PLR, Philipp M\u00fcller, \u00fcber die Werte, die seine Partei vertritt. Die ethnische Herkunft der Menschen, die in der Schweiz leben, hat f\u00fcr die FDP keine Priorit\u00e4t. Unter anderem sagt er: \u201eF\u00fcr die FDP\/PLR ist nicht die Nationalit\u00e4t bestimmend, sondern der Wille und die F\u00e4higkeit zur Integration.\u201c [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,2499,1140,2234,1158,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-93703","post","type-post","status-publish","format-standard","hentry","category-themen","category-die-schweiz-albaner-und-die-wahlen-2015","category-leben-in-der-schweiz","category-dossier-de","category-themen-vor-ort","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/93703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/comments?post=93703"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/posts\/93703\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/media?parent=93703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/categories?post=93703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/tags?post=93703"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/vendi?post=93703"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/de\/wp-json\/wp\/v2\/content_country?post=93703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}