{"id":161121,"date":"2017-09-08T14:37:27","date_gmt":"2017-09-08T12:37:27","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=161121\/"},"modified":"2017-09-11T22:54:17","modified_gmt":"2017-09-11T20:54:17","slug":"la-suisse-renforce-son-engagement-en-faveur-de-legalite-des-sexes-et-des-droits-des-femmes","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/la-suisse-renforce-son-engagement-en-faveur-de-legalite-des-sexes-et-des-droits-des-femmes\/","title":{"rendered":"La Suisse renforce son engagement en faveur de l\u2019\u00e9galit\u00e9 des sexes et des droits des femmes"},"content":{"rendered":"<p><span lang=\"FR\" style=\"margin: 0px; color: #454545; font-family: 'Frutiger Neue'; font-size: 12pt;\">Malgr\u00e9 les progr\u00e8s r\u00e9alis\u00e9s en mati\u00e8re d\u2019\u00e9galit\u00e9 des genres, il demeure partout de grandes disparit\u00e9s entre hommes et femmes, y compris en Suisse. Les femmes et les filles sont en outre touch\u00e9es disproportionnellement par les cons\u00e9quences qui r\u00e9sultent des crises humanitaires, des conflits, de l\u2019extr\u00e9misme violent et de l\u2019ins\u00e9curit\u00e9 alimentaire. Ainsi, les femmes ont plus que jamais un r\u00f4le \u00e0 jouer sur les sujets prioritaires de la politique ext\u00e9rieure de la Suisse, \u00e0 savoir la paix, la s\u00e9curit\u00e9, les droits de l\u2019homme, le d\u00e9veloppement durable et la prosp\u00e9rit\u00e9 : elles sont une force motrice du changement dans un monde en mutation. <\/span><\/p>\n<p><span lang=\"FR\" style=\"margin: 0px; color: #454545; font-family: 'Frutiger Neue'; font-size: 12pt;\">Par sa strat\u00e9gie \u00c9galit\u00e9 des genres et droits des femmes, le D\u00e9partement f\u00e9d\u00e9ral des affaires \u00e9trang\u00e8res (DFAE) entend mettre en lumi\u00e8re son engagement de longue date ; il entend \u00e9galement instaurer les conditions lui permettant d\u2019int\u00e9grer la question de l\u2019\u00e9galit\u00e9 des genres dans tous ses champs d\u2019action. Il n\u2019est plus \u00e0 d\u00e9montrer que tant l\u2019\u00e9galit\u00e9 des genres que l\u2019\u00e9galit\u00e9 des chances profitent autant aux femmes qu\u2019aux hommes, sans compter qu\u2019elles sont des conditions permettant la r\u00e9duction de la pauvret\u00e9, la croissance \u00e9conomique, et le d\u00e9veloppement durable, au b\u00e9n\u00e9fice de l\u2019ensemble de la soci\u00e9t\u00e9. Il est donc particuli\u00e8rement important que la communaut\u00e9 internationale et partant, la Suisse, affirment leurs valeurs et mettent r\u00e9solument en place les m\u00eames droits pour tous. L\u2019engagement de la Suisse en faveur de ces objectifs est ancr\u00e9 dans la Constitution f\u00e9d\u00e9rale. <\/span><\/p>\n<p><span lang=\"FR\" style=\"margin: 0px; color: #454545; font-family: 'Frutiger Neue'; font-size: 12pt;\">La strat\u00e9gie du DFAE sur l\u2019\u00e9galit\u00e9 des genres et les droits des femmes d\u00e9finit six objectifs strat\u00e9giques : s\u2019il convient de renforcer l\u2019autonomie des femmes sur le plan \u00e9conomique ainsi que leur participation \u00e0 la vie politique, il faut \u00e9galement lutter contre toute forme de violences bas\u00e9e sur le genre. Les droits des femmes dans le domaine de la sant\u00e9 sexuelle et reproductive doivent \u00eatre renforc\u00e9s, de m\u00eame que la place centrale de l\u2019\u00e9galit\u00e9 des genres et des droits des femmes constituent dans toutes les activit\u00e9s bilat\u00e9rales et multilat\u00e9rales engag\u00e9es. Il importe enfin que le DFAE s\u2019engage \u00e0 r\u00e9aliser l\u2019\u00e9galit\u00e9 des chances entre hommes et femmes en son sein. Des mesures concr\u00e8tes sont formul\u00e9es pour chaque objectif de la strat\u00e9gie ; elles seront d\u00e8s \u00e0 pr\u00e9sent soumises \u00e0 un examen r\u00e9gulier.<\/span><\/p>\n<p><span lang=\"FR\" style=\"margin: 0px; color: #454545; font-family: 'Frutiger Neue'; font-size: 12pt;\">La Suisse assoit son engagement sur un profil et une exp\u00e9rience d\u2019actrice politique engag\u00e9e, tant dans des forums multilat\u00e9raux que dans sa politique de d\u00e9veloppement. Cultivant l\u2019art du dialogue et la culture du compromis, elle est per\u00e7ue comme une b\u00e2tisseuse de ponts sur la sc\u00e8ne internationale. Elle r\u00e9alise d\u2019ores et d\u00e9j\u00e0 de nombreux projets visant \u00e0 promouvoir l\u2019\u00e9galit\u00e9 des genres et les droits des femmes. Ainsi, par exemple, au B\u00e9nin, elle apporte un appui \u00e0 des femmes dispos\u00e9es \u00e0 exercer un mandat politique ou \u00e0 jouer un r\u00f4le dans d\u2019autres organes d\u00e9cisionnels, tels que des comit\u00e9s de sant\u00e9 ou de gouvernance de l\u2019eau au niveau local. Au Bangladesh et en G\u00e9orgie, elle a investi dans des projets ayant pour objectif de renforcer les capacit\u00e9s \u00e9conomiques des femmes en milieu rural et de r\u00e9duire les obstacles auxquels font face ces derni\u00e8res pour acc\u00e9der au march\u00e9. En Libye, depuis 2015, elle s\u2019engage en faveur d\u2019un renforcement du r\u00f4le des femmes dans le dialogue politique. Elle a notamment soutenu un comit\u00e9 repr\u00e9sentatif refl\u00e9tant leur diversit\u00e9 politique, r\u00e9gionale et sociale, et permettant de tenir compte de leurs pr\u00e9occupations sp\u00e9cifiques dans le processus de dialogue. Autre exemple de l\u2019engagement du DFAE : l\u2019application \u00ab Women\u2019s Human Rights \u00bb (W\u2019sHR), d\u00e9velopp\u00e9e en 2013 et r\u00e9guli\u00e8rement mise \u00e0 jour en collaboration avec le Centre suisse de comp\u00e9tence pour les droits humains (CSDH). Elle permet d\u2019acc\u00e9der facilement \u00e0 une banque de donn\u00e9es contenant les principaux textes internationaux en rapport avec les droits des femmes. <\/span><\/p>\n<p><span lang=\"FR\" style=\"margin: 0px; color: #454545; font-family: 'Frutiger Neue'; font-size: 12pt;\">Pour mettre en \u0153uvre la nouvelle strat\u00e9gie, la Suisse va \u00e9galement s\u2019appuyer sur le dialogue avec la soci\u00e9t\u00e9 civile et chercher \u00e0 intensifier ses partenariats avec le secteur priv\u00e9.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019engagement de la Suisse pour l\u2019\u00e9galit\u00e9 des genres et la r\u00e9alisation des droits des femmes gagnera \u00e0 l\u2019avenir en ampleur et en coh\u00e9rence: la premi\u00e8re strat\u00e9gie sur l\u2019\u00e9galit\u00e9 des genres et les droits des femmes mise en \u0153uvre par le DFAE est un outil qui repose sur des mesures concr\u00e8tes. R\u00e9aliser l\u2019\u00e9galit\u00e9 des genres, c\u2019est cr\u00e9er de meilleures perspectives d\u2019avenir pour toutes et tous, dans l\u2019int\u00e9r\u00eat de la soci\u00e9t\u00e9 dans son ensemble. Avec cette strat\u00e9gie de politique ext\u00e9rieure, la Suisse contribue ainsi \u00e9galement \u00e0 la paix et \u00e0 la s\u00e9curit\u00e9, aux droits de l\u2019homme, \u00e0 un d\u00e9veloppement durable et \u00e0 la prosp\u00e9rit\u00e9 dans le monde. <\/p>\n","protected":false},"author":4,"featured_media":66040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171,1170,1411,2014,1481],"tags":[],"vendi":[],"content_country":[],"class_list":["post-161121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thematique","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr","category-uncategorized-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/161121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=161121"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/161121\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/66040"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=161121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=161121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=161121"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=161121"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=161121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}