{"id":177952,"date":"2018-01-04T13:44:45","date_gmt":"2018-01-04T12:44:45","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=177952\/"},"modified":"2018-01-04T13:45:45","modified_gmt":"2018-01-04T12:45:45","slug":"le-president-de-la-confederation-se-rend-vienne-pour-son-premier-voyage-letranger","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/le-president-de-la-confederation-se-rend-vienne-pour-son-premier-voyage-letranger\/","title":{"rendered":"Le pr\u00e9sident de la Conf\u00e9d\u00e9ration se rend \u00e0 Vienne pour son premier voyage \u00e0 l\u2019\u00e9tranger"},"content":{"rendered":"<p><strong>Le pr\u00e9sident de la Conf\u00e9d\u00e9ration Alain Berset se rendra la semaine prochaine \u00e0 Vienne pour son premier voyage \u00e0 l\u2019\u00e9tranger. Il poursuit ainsi la tradition selon laquelle la Suisse et l\u2019Autriche cultivent leurs contacts au niveau pr\u00e9sidentiel d\u00e8s le d\u00e9but de l\u2019ann\u00e9e. Le pr\u00e9sident de la Conf\u00e9d\u00e9ration rencontrera s\u00e9par\u00e9ment son homologue autrichien Alexander Van der Bellen et le nouveau chancelier Sebastian Kurz, mardi 9 janvier 2018. Le programme de la veille comprendra des rencontres avec des repr\u00e9sentants des organisations internationales sises \u00e0 Vienne. <\/strong><\/p>\n<p>Les entretiens avec le pr\u00e9sident et le chancelier autrichiens porteront en particulier sur les relations bilat\u00e9rales et la politique europ\u00e9enne de la Suisse. L&#8217;Autriche assumera la pr\u00e9sidence du Conseil de l&#8217;Union europ\u00e9enne au second semestre 2018. D&#8217;autres sujets europ\u00e9ens et internationaux seront \u00e9galement abord\u00e9s. La nouvelle ministre de la sant\u00e9 et des affaires sociales Beate Hartinger-Klein participera \u00e0 l&#8217;entretien avec le pr\u00e9sident Van der Bellen. Une rencontre est \u00e9galement pr\u00e9vue avec le ministre de la culture et des affaires europ\u00e9ennes, Gernot Bl\u00fcmel.<\/p>\n<p>Lundi 8 janvier, le pr\u00e9sident de la Conf\u00e9d\u00e9ration rencontrera quatre repr\u00e9sentants d&#8217;organisations internationales: Yuri Fedotov, directeur g\u00e9n\u00e9ral de l&#8217;Office des Nations-Unies \u00e0 Vienne et directeur ex\u00e9cutif de l&#8217;Office des Nations Unies contre la drogue et le crime (ONUDC), Yukiya Amano, directeur g\u00e9n\u00e9ral de l&#8217;Agence internationale de l&#8217;\u00e9nergie atomique (AIEA), Thomas Greminger, secr\u00e9taire g\u00e9n\u00e9ral de l&#8217;Organisation pour la s\u00e9curit\u00e9 et la coop\u00e9ration en Europe (OSCE) et Harlem D\u00e9sir, repr\u00e9sentant de l&#8217;OSCE pour la libert\u00e9 des m\u00e9dias.<\/p>\n<p>Au terme de son voyage en Autriche, le pr\u00e9sident de la Conf\u00e9d\u00e9ration se rendra au mus\u00e9e Leopold, o\u00f9 se tient actuellement une exposition consacr\u00e9e \u00e0 Ferdinand Hodler (1853-1918). En sa qualit\u00e9 de ministre de la culture, le conseiller f\u00e9d\u00e9ral Alain Berset a assum\u00e9 le patronage de l&#8217;exposition en automne 2017, avec son ancien homologue autrichien Thomas Drozda. Il s&#8217;agit de la plus importante exposition Hodler jamais r\u00e9alis\u00e9e dans la ville o\u00f9 l&#8217;artiste suisse a acc\u00e9d\u00e9 \u00e0 la c\u00e9l\u00e9brit\u00e9 internationale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident de la Conf\u00e9d\u00e9ration rencontrera s\u00e9par\u00e9ment son homologue autrichien Alexander Van der Bellen et le nouveau chancelier Sebastian Kurz, mardi 9 janvier 2018<\/p>\n","protected":false},"author":4,"featured_media":174107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171,1170,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-177952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thematique","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/177952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=177952"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/177952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/174107"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=177952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=177952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=177952"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=177952"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=177952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}