{"id":179333,"date":"2018-01-15T12:28:49","date_gmt":"2018-01-15T11:28:49","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=179333\/"},"modified":"2018-01-21T22:53:44","modified_gmt":"2018-01-21T21:53:44","slug":"etrangers-statistiques-2017","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/etrangers-statistiques-2017\/","title":{"rendered":"\u00c9trangers : statistiques 2017"},"content":{"rendered":"<p><strong>L\u2019immigration de personnes \u00e9trang\u00e8res en Suisse a recul\u00e9 pour la quatri\u00e8me ann\u00e9e cons\u00e9cutive. Le solde migratoire de 2017 est de nouveau inf\u00e9rieur \u00e0 celui de l\u2019ann\u00e9e pr\u00e9c\u00e9dente (diminution d\u2019environ 12 %) et se situe d\u00e9sormais \u00e0 un niveau comparable \u00e0 celui de 2002, lors de l\u2019entr\u00e9e en vigueur de l\u2019accord sur la libre circulation des personnes (ALCP) avec l\u2019UE. La Suisse comptait 2 053 589 \u00e9trangers \u00e0 la fin de 2017. La population r\u00e9sidante permanente de nationalit\u00e9 \u00e9trang\u00e8re provient \u00e0 pr\u00e8s de 70 % des \u00c9tats membres de l\u2019UE-28 ou de l\u2019AELE. <\/strong><\/p>\n<p>Avec un total de 53\u00a0221 personnes, le solde migratoire de 2017 est nettement inf\u00e9rieur \u00e0 celui de 2016 (-11,7%). Pendant l&#8217;ann\u00e9e \u00e9coul\u00e9e, 137\u00a0803 \u00e9trangers ont immigr\u00e9 en Suisse, ce qui repr\u00e9sente une baisse d&#8217;environ 4\u00a0% par rapport \u00e0 2016, tandis que l&#8217;effectif des \u00e9migrants (79\u00a0104 personnes) a augment\u00e9 de 2\u00a0%. L&#8217;immigration nette en provenance de pays qui b\u00e9n\u00e9ficient de la libre circulation des personnes (UE-28 \/ AELE) a diminu\u00e9 de plus de 20\u00a0% par rapport \u00e0 l&#8217;an dernier (30\u00a0799\u00a0personnes).<\/p>\n<p>Comme les ann\u00e9es pr\u00e9c\u00e9dentes, l&#8217;exercice d&#8217;une activit\u00e9 lucrative a \u00e9t\u00e9 le principal motif d&#8217;immigration (pr\u00e8s de 47\u00a0% des cas). Vient ensuite le regroupement familial (31\u00a0%), qui inclut celui des ressortissants suisses.<\/p>\n<p>\u00c0 la fin de d\u00e9cembre, 1\u00a0405\u00a0771 citoyens d&#8217;\u00c9tats membres de l&#8217;UE-28 ou de l&#8217;AELE et 647\u00a0818 ressortissants d&#8217;\u00c9tats tiers vivaient en Suisse.<\/p>\n<p>Les Italiens forment, en 2017 \u00e9galement, le groupe d&#8217;\u00e9trangers le plus important de Suisse (319\u00a0367\u00a0personnes), suivis des Allemands (305\u00a0785\u00a0personnes) et des Portugais (268\u00a0012 personnes).<\/p>\n<p>C&#8217;est l&#8217;effectif des ressortissants fran\u00e7ais qui a connu la plus forte progression (+\u00a04212 personnes). \u00c0 l&#8217;inverse, le recul le plus marqu\u00e9 a \u00e9t\u00e9 enregistr\u00e9 pour le groupe des ressortissants portugais (-1509\u00a0personnes).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 la fin de d\u00e9cembre, 1\u00a0405\u00a0771 citoyens d&#8217;\u00c9tats membres de l&#8217;UE-28 ou de l&#8217;AELE et 647\u00a0818 ressortissants d&#8217;\u00c9tats tiers vivaient en Suisse<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1170,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-179333","post","type-post","status-publish","format-standard","hentry","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/179333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=179333"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/179333\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=179333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=179333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=179333"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=179333"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=179333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}