{"id":181045,"date":"2018-01-26T13:11:02","date_gmt":"2018-01-26T12:11:02","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=181045\/"},"modified":"2018-01-30T01:37:33","modified_gmt":"2018-01-30T00:37:33","slug":"exposition-fuir","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/exposition-fuir\/","title":{"rendered":"Exposition \u00abFuir\u00bb"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p><strong>Exposition temporaire \u00ab Fuir \u00bb, du 25 janvier au 16 septembre 2018 Nous voyons tous les jours les images d\u2019hommes, de femmes et d\u2019enfants qui fuient leur pays. Mais savons-nous ce que c\u2019est de devoir abandonner sa maison, son travail, sa famille et sa patrie ? L\u2019exposition \u00ab Fuir \u00bb permet aux visiteurs de s\u2019en faire une id\u00e9e. Cette exposition itin\u00e9rante, qui remporte un vif succ\u00e8s, fait halte du 25 janvier au 16 septembre 2018 au Mus\u00e9e d\u2019Histoire de Berne. <\/strong><\/p>\n<p>Plus de 65 millions d&#8217;hommes, de femmes et d&#8217;enfants sont aujourd&#8217;hui en fuite \u00e0 travers le monde. Jamais le nombre des personnes forc\u00e9es de quitter leur pays n&#8217;avait \u00e9t\u00e9 aussi \u00e9lev\u00e9 depuis la Deuxi\u00e8me Guerre mondiale. L&#8217;exposition \u00ab\u00a0Fuir\u00a0\u00bb braque les projecteurs sur cette th\u00e9matique complexe et la pr\u00e9sente sous diff\u00e9rents angles. Elle permet aux visiteurs de suivre les chemins difficiles et dangereux qu&#8217;ont d\u00fb prendre les r\u00e9fugi\u00e9s et leur famille \u00e0 l&#8217;aide de biographies typiques.<\/p>\n<p>Au d\u00e9but de l&#8217;exposition, les visiteurs se retrouvent face aux images \u00e9mouvantes du r\u00e9alisateur Mano Khalil &#8211; lui-m\u00eame un ancien r\u00e9fugi\u00e9. Ils d\u00e9couvrent les histoires d&#8217;\u00eatres humains que la violence, la guerre ou les pers\u00e9cutions ont forc\u00e9s \u00e0 fuir. Ils prennent conscience des coups du sort, des situations cruciales et souvent traumatisantes qui ont contraint ces gens \u00e0 partir et qu&#8217;ils ont subis pendant leur voyage, et ils peuvent ressentir ce que c&#8217;est que d&#8217;arriver dans un pays inconnu o\u00f9 nul ne vous attend &#8211; un pays o\u00f9 pourtant tous les espoirs sont permis.<\/p>\n<p>Plus de 90% des r\u00e9fugi\u00e9s dans le monde sont tributaires d&#8217;une aide. L&#8217;exposition offre un aper\u00e7u de l&#8217;engagement de la Suisse et de la communaut\u00e9 internationale. Elle explique la proc\u00e9dure d&#8217;asile en Suisse et montre en outre en quoi l&#8217;issue de cette proc\u00e9dure d\u00e9termine l&#8217;avenir des personnes en qu\u00eate de protection.<\/p>\n<p>\u00ab FUIR \u00bb est un projet de la Commission f\u00e9d\u00e9rale des migrations (CFM), du Secr\u00e9tariat d&#8217;\u00c9tat aux migrations (SEM), de l&#8217;Haut-commissariat aux r\u00e9fugi\u00e9s des Nations Unies pour les r\u00e9fugi\u00e9s (HCR) et de la Direction du d\u00e9veloppement et de la coop\u00e9ration (DDC).<\/p>\n<p>&nbsp;<\/p>\n<h3>Autour de l&#8217;exposition<\/h3>\n<p>Le Mus\u00e9e d&#8217;Histoire de Berne propose un programme riche et vari\u00e9 autour de son exposition temporaire\u00a0:<\/p>\n<p>&nbsp;<\/p>\n<p><b><i>VISITES GUID\u00c9ES<\/i><\/b><\/p>\n<p><i>Visites guid\u00e9es publiques<\/i><br \/>\nMercredi 4.4.2018, 12.15 h \/ mercredi 6.6.2018, 12.15 h<br \/>\nDur\u00e9e : 45 min., entr\u00e9e aux tarifs en vigueur, visite guid\u00e9e gratuite<\/p>\n<p><i>Visite guid\u00e9e dialogu\u00e9e<br \/>\n<\/i>Br\u00e8ve visite guid\u00e9e suivie d&#8217;un \u00e9change<br \/>\nMercredi 5.9.2018, 12.15 h : dialogue avec une personne travaillant dans l&#8217;aide humanitaire<br \/>\nVisite guid\u00e9e : 45 min., discussion : 30 min., entr\u00e9es aux tarifs en vigueur, visite guid\u00e9e gratuite<\/p>\n<p><i>Visites guid\u00e9es pour les groupes<br \/>\n<\/i>CHF 150 (+ entr\u00e9es)<br \/>\nDur\u00e9e\u00a0: 60 min., max. 20 pers., sur r\u00e9servation<\/p>\n<p><b><i>\u00a0<\/i><\/b><\/p>\n<p><b><i>MANIFESTATION<\/i><\/b><\/p>\n<p><i>Femmes en fuite<br \/>\n<\/i>Table ronde organis\u00e9e \u00e0 l&#8217;occasion de la Journ\u00e9e des Nations Unies pour les droits de la femme et la paix internationale<br \/>\nJeudi 8.3.2018, 18 h. Entr\u00e9e gratuite, visite de l&#8217;exposition gratuite d\u00e8s 17 h<\/p>\n<p><i>Journ\u00e9e nationale du r\u00e9fugi\u00e9<\/i><i><br \/>\n<\/i>Journ\u00e9e d&#8217;action sur la protection des r\u00e9fugi\u00e9s<br \/>\nSamedi 16.6.2018<\/p>\n<p><i>Journ\u00e9e mondiale de l&#8217;aide humanitaire<br \/>\n<\/i>Journ\u00e9e d&#8217;action sur les diff\u00e9rentes facettes de l&#8217;aide humanitaire internationale et de l&#8217;engagement de la Suisse<br \/>\nDimanche 19.8.2018, de 10 \u00e0 17 h. Entr\u00e9e gratuite<\/p>\n<p>&nbsp;<\/p>\n<p><b><i>OFFRES POUR LES \u00c9COLES<\/i><\/b><\/p>\n<p>Visites guid\u00e9es et entr\u00e9es gratuites pour les \u00e9coles<br \/>\nPlus d&#8217;informations sur le programme complet de m\u00e9diation sur www.bhm.ch\/flucht-fuir<\/p>\n<hr \/>\n<p><strong> Adresse pour l&#8217;envoi de questions <\/strong><\/p>\n<p>Pour les questions d&#8217;ordre g\u00e9n\u00e9ral, veuillez vous adresser \u00e0 :<br \/>\nMus\u00e9e d&#8217;Histoire de Berne, Merja Rinderli, Responsable marketing et communication, T +41 31 350 77 83<\/p>\n<p>Pour les questions sp\u00e9cifiques, veuillez vous adresser \u00e0 :<br \/>\nDirection du d\u00e9veloppement et de la coop\u00e9ration DDC, George Farago, Porte-parole, T +41 58 463 11 28<br \/>\nCommission f\u00e9d\u00e9rale des migrations CFM, Sibylle Siegwart, Cheffe-suppl\u00e9ante, T +41 58 465 85 02<br \/>\nSecr\u00e9tariat d&#8217;Etat aux migrations SEM, Lukas Rieder, Porte-parole, T +41 58 466 78 67<br \/>\nBureau du HCR pour la Suisse et le Liechtenstein, Julia Dao, Responsable de la communication, T +41 79 204 34 09<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab FUIR \u00bb est un projet de la Commission f\u00e9d\u00e9rale des migrations (CFM), du Secr\u00e9tariat d&#8217;\u00c9tat aux migrations (SEM), de l&#8217;Haut-commissariat aux r\u00e9fugi\u00e9s des Nations Unies pour les r\u00e9fugi\u00e9s (HCR) et de la Direction du d\u00e9veloppement et de la coop\u00e9ration (DDC).<\/p>\n","protected":false},"author":4,"featured_media":181046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171,1174,1170,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-181045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thematique","category-manifestations","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/181045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=181045"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/181045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/181046"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=181045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=181045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=181045"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=181045"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=181045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}