{"id":211326,"date":"2018-08-13T10:00:49","date_gmt":"2018-08-13T08:00:49","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=211326"},"modified":"2018-08-14T02:02:20","modified_gmt":"2018-08-14T00:02:20","slug":"information-importante-concernant-la-nouvelle-procedure-pour-les-demandes-de-visa","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/information-importante-concernant-la-nouvelle-procedure-pour-les-demandes-de-visa\/","title":{"rendered":"Information importante concernant la nouvelle proc\u00e9dure pour les demandes de visa\u00a0"},"content":{"rendered":"<p>\u00c0 partir du\u00a03 septembre les\u00a0demandes de visa Schengen\u00a0pour la Suisse, la France, l\u2019Autriche et le Benelux\u00a0doivent \u00eatre soumises par l\u2019interm\u00e9diaire de l\u2019agence de sous-traitance locale TLScontact, qui les transmettra de\u00a0son centre de r\u00e9ception \u00e0 l\u2019Ambassade\u00a0de Suisse \u00e0 Pristina\u00a0pour le traitement ult\u00e9rieur.<\/p>\n<p>Les demandeurs de visas\u00a0peuvent d\u00e9poser une demande\u00a0en ligne et fixer un rendez-vous sur le site\u00a0\u00a0<a href=\"https:\/\/ch.tlscontact.com\/xk\/prn\/index.php\">TLScontact<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 partir du\u00a03 septembre les\u00a0demandes de visa Schengen\u00a0pour la Suisse, la France, l\u2019Autriche et le Benelux\u00a0doivent \u00eatre soumises par l\u2019interm\u00e9diaire de l\u2019agence de sous-traitance locale TLScontact, qui les transmettra de\u00a0son centre de r\u00e9ception \u00e0 l\u2019Ambassade\u00a0de Suisse \u00e0 Pristina\u00a0pour le traitement ult\u00e9rieur. Les demandeurs de visas\u00a0peuvent d\u00e9poser une demande\u00a0en ligne et fixer un rendez-vous sur le [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":211323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3949,1159,1170,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-211326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kosova-fr","category-ch-balkans","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/211326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=211326"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/211326\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/211323"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=211326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=211326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=211326"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=211326"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=211326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}