{"id":225840,"date":"2018-10-31T11:25:46","date_gmt":"2018-10-31T10:25:46","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=225840"},"modified":"2018-11-10T16:21:40","modified_gmt":"2018-11-10T15:21:40","slug":"colloque-international","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/colloque-international\/","title":{"rendered":"Colloque international"},"content":{"rendered":"<p>Les Balkans occidentaux \u00e0 la crois\u00e9e de l\u2019int\u00e9gration europ\u00e9enne et des \u00e9mergents<\/p>\n<p>Center for International Relations Studies (CEFIR)<br \/>\nFacult\u00e9 de Droit, de Science politique et de Criminologie<br \/>\nUniversit\u00e9 de Li\u00e8ge (ULi\u00e8ge)<\/p>\n<p>Le jeudi 28 mars 2019<\/p>\n<p>Liridon Lika, chercheur au CEFIR, ULi\u00e8ge<\/p>\n<p>Le Center for International Relations Studies (CEFIR) du D\u00e9partement de Science politique de l\u2019Universit\u00e9 de Li\u00e8ge (ULi\u00e8ge) lance un appel \u00e0 communications pour un colloque international intitul\u00e9 : Les Balkans occidentaux \u00e0 la crois\u00e9e de l\u2019int\u00e9gration europ\u00e9enne et des \u00e9mergents.<\/p>\n<p>La r\u00e9gion des Balkans occidentaux est actuellement compos\u00e9e de six \u00c9tats : Albanie, Bosnie-Herz\u00e9gov<wbr \/>ine, Kosovo, Mac\u00e9doine, Mont\u00e9n\u00e9gro, Serbie. Dans le cadre de cet \u00e9v\u00e9nement, seront analys\u00e9s \u00e0 la fois les relations bilat\u00e9rales entre les six pays des Balkans occidentaux et simultan\u00e9ment les relations triangulaires entre les Balkans occidentaux, l\u2019Union europ\u00e9enne (UE) et les puissances \u00e9mergentes.<\/p>\n<p>Le processus d\u2019\u00e9largissement<wbr \/> de l\u2019UE a tourn\u00e9 au ralenti ces derni\u00e8res ann\u00e9es pour des raisons \u00e0 la fois internes et externes aux pays des Balkans occidentaux ainsi qu\u2019\u00e0 l\u2019UE elle-m\u00eame.<\/p>\n<p>La crise financi\u00e8re et \u00e9conomique qu\u2019a connue l\u2019UE entre 2007 et 2014 a affect\u00e9 les \u00e9conomies des Balkans occidentaux, particuli\u00e8remen<wbr \/>t dans les domaines des investissements<wbr \/> directs \u00e9trangers (IDE), des financements priv\u00e9s et des transferts de fonds de la diaspora. L\u2019ensemble des probl\u00e8mes politiques et \u00e9conomiques bilat\u00e9raux des pays des Balkans occidentaux conjugu\u00e9 aux d\u00e9boires politiques et \u00e9conomiques de l\u2019UE et \u00e0 la \u00ab fatigue de l\u2019\u00e9largissement<wbr \/> \u00bb ont contribu\u00e9 \u00e0 la cr\u00e9ation d\u2019un vide relatif de puissance dans la r\u00e9gion. Entre temps, des pays \u00e9mergents, tels que la Russie, la Turquie, la Chine ou l\u2019Arabie saoudite, n\u2019ont de cesse d\u2019accro\u00eetre leur pr\u00e9sence dans la r\u00e9gion. La projection de leur influence dans les Balkans occidentaux se fait \u00e0 des degr\u00e9s variables et dans des domaines aussi vari\u00e9s que le politique, l\u2019\u00e9conomique, le financier, le commercial, le militaire, le culturel ou le religieux.<\/p>\n<p>D\u00e8s lors, face \u00e0 ce contexte international changeant, l\u2019UE et certains de ses \u00c9tats membres ont fait part d\u2019une nouvelle prise de conscience en lan\u00e7ant r\u00e9cemment plusieurs initiatives favorisant l\u2019\u00e9largissement<wbr \/> (Processus de Berlin depuis 2014, nouvelle strat\u00e9gie d\u2019\u00e9largissement<wbr \/> de la Commission europ\u00e9enne de 2018 ou le sommet de Sofia de 2018).<br \/>\nCe colloque a pour objectif de r\u00e9pondre \u00e0 la question centrale de savoir quels sont les d\u00e9fis que repr\u00e9sente la p\u00e9n\u00e9tration des puissances \u00e9mergentes dans les Balkans occidentaux pour le d\u00e9ploiement de l\u2019UE dans cette r\u00e9gion. En d\u2019autres termes, il vise \u00e0 analyser les nouveaux rapports de force internationaux dans le contexte du d\u00e9centrage du pouvoir mondial. Cette question se d\u00e9cline en plusieurs sous-questions : quels sont les int\u00e9r\u00eats de l\u2019UE dans les Balkans occidentaux ? Quels sont les int\u00e9r\u00eats des pays \u00e9mergents dans la r\u00e9gion ? Comment les pays des Balkans occidentaux se positionnent par rapport \u00e0 l\u2019UE et aux puissances \u00e9mergentes ? La pr\u00e9sence assertive des puissances \u00e9mergentes dans les Balkans occidentaux pr\u00e9sente-t-elle<wbr \/> des d\u00e9fis pour l\u2019\u00e9largissement<wbr \/> europ\u00e9en ? Les strat\u00e9gies de l\u2019UE et des puissances \u00e9mergentes sont-elles en comp\u00e9tition ou compl\u00e9mentaires<wbr \/> ? Ce colloque tentera d\u2019apporter des r\u00e9ponses \u00e0 ces diff\u00e9rentes interrogations.<wbr \/><\/p>\n<p>Calendrier et modalit\u00e9s pratiques :<br \/>\nNous attendons vos propositions de communications (maximum 500 mots) et vos biographies (maximum 200 mots), pour le vendredi 14 d\u00e9cembre 2018, au plus tard. Elles doivent \u00eatre transmises \u00e0 Liridon Lika \u00e0 l\u2019adresse suivante : Liridon.Lika@ul<wbr \/>iege.be<\/p>\n<p>Les propositions seront \u00e9valu\u00e9es de mani\u00e8re anonyme par le comit\u00e9 scientifique.<br \/>\nLa d\u00e9cision du comit\u00e9 scientifique vous sera communiqu\u00e9e le lundi 14 janvier 2019.<br \/>\nAu cas o\u00f9 la proposition de communication est accept\u00e9e, nous attendons la contribution finale pour le vendredi 1er mars 2019.<br \/>\nUne publication d\u00e9coulera de cet \u00e9v\u00e9nement. Tous les intervenants auront la possibilit\u00e9 de publier une contribution originale \u2013 apr\u00e8s \u00e9valuation externe positive \u2013 dans un ouvrage collectif. Les contributions ne devront pas d\u00e9passer 35.000 signes (espaces compris), Times New Roman, Taille de police 12, Interligne 1,5.<br \/>\nLa date limite de r\u00e9ception des textes en vue de la r\u00e9alisation d\u2019un livre collectif sera le vendredi 31 mai 2019.<br \/>\nLe colloque se tiendra le jeudi 28 mars 2019 \u00e0 la salle du Conseil de la Facult\u00e9 de Droit, de Science politique et de Criminologie de l\u2019Universit\u00e9 de Li\u00e8ge, Quartier Agora, Place des Orateurs 3, B\u00e2timent B31, Sart-Tilman, 4000 Li\u00e8ge (Belgique).<br \/>\nInformations suppl\u00e9mentaires<wbr \/> :<br \/>\nLangues du colloque : fran\u00e7ais et anglais<br \/>\nLangue de la publication : fran\u00e7ais<br \/>\nLa communication de chaque intervenant durera au maximum 20 minutes, afin de laisser une quinzaine de minutes au discutant ainsi qu\u2019\u00e0 l\u2019assembl\u00e9e pour d\u00e9battre de la contribution pr\u00e9sent\u00e9e.<br \/>\nComit\u00e9 scientifique :<br \/>\n<a href=\"https:\/\/mobile.facebook.com\/afrim.krasniqi.50?refid=52&amp;__tn__=%2As-R\">Afrim Krasniqi<\/a>, Academy of Albanian Studies, Albanie<br \/>\n<a href=\"https:\/\/mobile.facebook.com\/bashkim.iseni.5?refid=52&amp;__tn__=%2As-R\">Bashkim Iseni<\/a>, Universit\u00e9 de Fribourg, Suisse<br \/>\nJacques Rupnik, Directeur de recherches, CERI, Sciences Po, France<br \/>\nJean-Christophe<wbr \/> Defraigne, Universit\u00e9 Saint-Louis \u2013 Bruxelles, Belgique<br \/>\nKamal Bayramzadeh, Universit\u00e9 Paris XIII et Universit\u00e9 de Li\u00e8ge, France et Belgique<br \/>\nSebastian Santander, CEFIR, Universit\u00e9 de Li\u00e8ge, Belgique<br \/>\nVjosa Musliu, Vrije Universiteit Brussel, Belgique<br \/>\n<a href=\"https:\/\/mobile.facebook.com\/xhabir.hamiti?refid=52&amp;__tn__=%2As-R\">Xhabir Hamiti<\/a>, Universit\u00e9 de Prishtina, Kosovo<\/p>\n<p>Organisateur<br \/>\n<a href=\"https:\/\/mobile.facebook.com\/liridon.lika1?refid=52&amp;__tn__=%2As-R\">Liridon Lika<\/a>, CEFIR, Universit\u00e9 de Li\u00e8ge, Belgique<\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45066586_2076782039024309_3376522195114131456_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-225836\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45066586_2076782039024309_3376522195114131456_n.jpg\" alt=\"\" width=\"500\" height=\"707\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45066586_2076782039024309_3376522195114131456_n.jpg 679w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45066586_2076782039024309_3376522195114131456_n-212x300.jpg 212w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45066586_2076782039024309_3376522195114131456_n-169x240.jpg 169w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45066586_2076782039024309_3376522195114131456_n-280x396.jpg 280w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45066586_2076782039024309_3376522195114131456_n-71x100.jpg 71w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45066586_2076782039024309_3376522195114131456_n-124x175.jpg 124w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a> <a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45064170_2076782115690968_1132744461214810112_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-225833\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45064170_2076782115690968_1132744461214810112_n.jpg\" alt=\"\" width=\"500\" height=\"707\" srcset=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45064170_2076782115690968_1132744461214810112_n.jpg 679w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45064170_2076782115690968_1132744461214810112_n-212x300.jpg 212w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45064170_2076782115690968_1132744461214810112_n-169x240.jpg 169w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45064170_2076782115690968_1132744461214810112_n-280x396.jpg 280w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45064170_2076782115690968_1132744461214810112_n-71x100.jpg 71w, https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/10\/45064170_2076782115690968_1132744461214810112_n-124x175.jpg 124w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Balkans occidentaux \u00e0 la crois\u00e9e de l\u2019int\u00e9gration europ\u00e9enne et des \u00e9mergents Center for International Relations Studies (CEFIR) Facult\u00e9 de Droit, de Science politique et de Criminologie Universit\u00e9 de Li\u00e8ge (ULi\u00e8ge) Le jeudi 28 mars 2019 Liridon Lika, chercheur au CEFIR, ULi\u00e8ge Le Center for International Relations Studies (CEFIR) du D\u00e9partement de Science politique de [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":225841,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1163,1182,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-225840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fr-e-diaspora","category-agenda","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/225840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=225840"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/225840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/225841"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=225840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=225840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=225840"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=225840"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=225840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}