{"id":369162,"date":"2020-04-06T22:19:29","date_gmt":"2020-04-06T20:19:29","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=369162"},"modified":"2020-04-07T22:00:02","modified_gmt":"2020-04-07T20:00:02","slug":"soutien-au-secteur-culturel-en-lien-avec-le-covid-19-les-demandes-peuvent-etre-deposees","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/soutien-au-secteur-culturel-en-lien-avec-le-covid-19-les-demandes-peuvent-etre-deposees\/","title":{"rendered":"Soutien au secteur culturel en lien avec le COVID-19 : les demandes peuvent \u00eatre d\u00e9pos\u00e9es"},"content":{"rendered":"<p>Le secteur culturel est fortement touch\u00e9 par la pand\u00e9mie du COVID-19 et par les mesures prises par les autorit\u00e9s pour en att\u00e9nuer les effets. Aussi le Conseil f\u00e9d\u00e9ral a d\u00e9cid\u00e9 le 20 mars 2020 d\u2019arr\u00eater un train de mesures \u00e0 hauteur de 280 millions de francs en faveur de la culture. Les demandes d\u2019aides financi\u00e8res peuvent \u00eatre pr\u00e9sent\u00e9es aux cantons, \u00e0 l\u2019association Suisseculture Sociale ou aux associations culturelles d\u2019amateurs.<\/p>\n<p>Le 20 mars 2020, le Conseil f\u00e9d\u00e9ral a arr\u00eat\u00e9 un train de mesures en vue d\u2019att\u00e9nuer l\u2019impact \u00e9conomique de la propagation du COVID-19 (cf. communiqu\u00e9 de presse du Conseil f\u00e9d\u00e9ral du 20 mars 2020). Afin de tenir compte de la situation tr\u00e8s particuli\u00e8re du secteur culturel, le Conseil f\u00e9d\u00e9ral a compl\u00e9t\u00e9 ces mesures, qui sont \u00e9galement ouvertes aux entreprises et aux acteurs culturels, par des instruments sp\u00e9cifiques. Ceux-ci sont d\u00e9finis dans l\u2019ordonnance sur l\u2019att\u00e9nuation des cons\u00e9quences \u00e9conomiques du coronavirus dans le secteur de la culture (Ordonnance COVID dans le secteur de la culture).<\/p>\n<p>Les directives d\u2019ex\u00e9cution \u00e9labor\u00e9es en \u00e9troite collaboration avec les cantons sont pr\u00eates et les demandes pour b\u00e9n\u00e9ficier des mesures compl\u00e9mentaires pour la culture peuvent \u00eatre d\u00e9pos\u00e9es. Les aides financi\u00e8res peuvent \u00eatre demand\u00e9es aux cantons, \u00e0 l\u2019association Suisseculture Sociale et aux associations culturelles d\u2019amateurs. Les diff\u00e9rents cantons pourront proc\u00e9der aux premiers versements apr\u00e8s avoir sign\u00e9 avec la Conf\u00e9d\u00e9ration la convention de prestation qui pr\u00e9cise les modalit\u00e9s. Toutes les informations utiles et les adresses des services comp\u00e9tents se trouvent sur le site de l\u2019Office f\u00e9d\u00e9ral de la culture (OFC). https:\/\/www.bak.admin.ch\/coronavirus<\/p>\n<p>La validit\u00e9 de l\u2019ordonnance est limit\u00e9e \u00e0 deux mois. La Conf\u00e9d\u00e9ration lib\u00e8re pour le financement des mesures compl\u00e9mentaires une premi\u00e8re tranche de 280 millions de francs r\u00e9partis comme suit :<\/p>\n<p>aides d\u2019urgence aux entreprises culturelles (100 millions de francs) et aux acteurs culturels (25 millions de francs)<br \/>\nindemnisations pour pertes financi\u00e8res destin\u00e9es aux entreprises culturelles, \u00e0 but lucratif ou sans but lucratif, et aux acteurs culturels (145 millions de francs)<br \/>\naides financi\u00e8res pour les associations culturelles d\u2019amateurs (10 millions de francs)<br \/>\nCes deux prochains mois, l\u2019OFC et la Fondation suisse pour la culture Pro Helvetia suivront de pr\u00e8s l\u2019\u00e9volution de la situation, en coop\u00e9ration avec les cantons et les organisations culturelles (en particulier Suisseculture sociale) ; ils dresseront un \u00e9tat des lieux \u00e0 l\u2019intention du Conseil f\u00e9d\u00e9ral et examineront s\u2019il est \u00e9ventuellement n\u00e9cessaire de prolonger la dur\u00e9e de validit\u00e9 de l\u2019ordonnance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La validit\u00e9 de l\u2019ordonnance est limit\u00e9e \u00e0 deux mois. La Conf\u00e9d\u00e9ration lib\u00e8re pour le financement des mesures compl\u00e9mentaires une premi\u00e8re tranche de 280 millions de francs<\/p>\n","protected":false},"author":4,"featured_media":365710,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171,22521,1170],"tags":[],"vendi":[],"content_country":[],"class_list":["post-369162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thematique","category-coronavirus-minutes-par-minutes","category-vivre-en-suisse"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/369162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=369162"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/369162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/365710"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=369162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=369162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=369162"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=369162"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=369162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}