{"id":369962,"date":"2020-04-10T09:10:49","date_gmt":"2020-04-10T07:10:49","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=369962"},"modified":"2020-04-10T08:22:37","modified_gmt":"2020-04-10T06:22:37","slug":"coronavirus-de-nouvelles-mesures-pour-eviter-une-vague-de-faillites","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/coronavirus-de-nouvelles-mesures-pour-eviter-une-vague-de-faillites\/","title":{"rendered":"Coronavirus : de nouvelles mesures pour \u00e9viter une vague de faillites"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p>Le Conseil f\u00e9d\u00e9ral ne prolongera pas la suspension des poursuites, ni les f\u00e9ries judiciaires en mati\u00e8re civile et administrative. Ces mesures prendront fin comme pr\u00e9vu le 19 avril 2020 \u00e0 minuit. La suspension des poursuites n&#8217;est pas un instrument appropri\u00e9 pour faire face aux difficult\u00e9s \u00e9conomiques \u00e0 long terme. Le Conseil f\u00e9d\u00e9ral entend plut\u00f4t mettre en place des mesures visant \u00e0 \u00e9viter autant que possible les faillites dues \u00e0 la crise du coronavirus.<\/p>\n<p>Malgr\u00e9 les mesures de compensation importantes que le gouvernement a d\u00e9j\u00e0 prises pour prot\u00e9ger l\u2019\u00e9conomie, en particulier pour surmonter des probl\u00e8mes de liquidit\u00e9s, de nombreuses entreprises sont en danger de surendettement et donc de faillite en raison de la pand\u00e9mie. Lors de sa s\u00e9ance du 8\u00a0avril\u00a02020, le Conseil f\u00e9d\u00e9ral a charg\u00e9 le DFJP de proposer des instruments appropri\u00e9s concernant la protection du capital (CO) et l\u2019assainissement et le sursis (loi f\u00e9d\u00e9rale sur la poursuite pour dettes et la faillite, LP). Une vague de faillites aurait de graves cons\u00e9quences pour l\u2019\u00e9conomie suisse, particuli\u00e8rement pour l\u2019emploi.<\/p>\n<h3>Ajournement de la faillite et sursis COVID-19 de dur\u00e9e limit\u00e9e<\/h3>\n<p>Le DFJP examine sur mandat du Conseil f\u00e9d\u00e9ral notamment une r\u00e8glementation provisoire permettant aux entreprises menac\u00e9es de surendettement en raison du coronavirus de ne pas aussit\u00f4t aviser le juge qui d\u00e9clarera la faillite s\u2019il y a lieu d\u2019esp\u00e9rer que le surendettement puisse prendre fin apr\u00e8s la crise. Le conseil d\u2019administration est actuellement tenu de le faire selon l\u2019art. 725, al.\u00a02, CO.<\/p>\n<p>Le Conseil f\u00e9d\u00e9ral entend en outre modifier ponctuellement la proc\u00e9dure concordataire selon les art.\u00a0293\u00a0ss\u00a0LP pour l\u2019adapter aux circonstances actuelles. Une autre mesure \u00e0 l\u2019\u00e9tude est l\u2019instauration d\u2019un sursis de dur\u00e9e limit\u00e9e, dit &#8220;sursis COVID-19&#8221;, pour les petites et moyennes entreprises que la pand\u00e9mie a plong\u00e9es dans les difficult\u00e9s financi\u00e8res. Ces mesures laisseront du temps aux entreprises aujourd\u2019hui \u00e9branl\u00e9es par la crise pour r\u00e9organiser leur activit\u00e9 et mettre en \u0153uvre des mesures d\u2019assainissement.<\/p>\n<p>Le Conseil f\u00e9d\u00e9ral est par contre parvenu \u00e0 la conclusion que le sursis extraordinaire pr\u00e9vu dans la loi actuelle pour prot\u00e9ger les entreprises menac\u00e9es n\u2019\u00e9tait pas un outil adapt\u00e9 dans le cas de la crise du coronavirus (voir art. 337 ss LP). Les \u00e9ventuelles demandes des cantons seront refus\u00e9es.<\/p>\n<p>L\u2019Office f\u00e9d\u00e9ral de la justice (OFJ) a men\u00e9 une consultation publique sur les mesures projet\u00e9es entre le 1er et le 3 avril. Il a re\u00e7u pr\u00e8s de 100 r\u00e9ponses, fondamentalement favorables \u00e0 l\u2019orientation propos\u00e9e.<\/p>\n<h3>Les tribunaux autoris\u00e9s \u00e0 utiliser les nouvelles technologies<\/h3>\n<p>Afin de d\u00e9charger les tribunaux, le DFJP \u00e9tudie d\u2019autres r\u00e8gles sp\u00e9ciales provisoires dans le domaine de la proc\u00e9dure civile. Notamment, les tribunaux ont sugg\u00e9r\u00e9 que l\u2019on permette d\u2019autoriser l\u2019usage des vid\u00e9oconf\u00e9rences ou des conf\u00e9rences t\u00e9l\u00e9phoniques dans les affaires civiles, comme c\u2019est le cas dans la proc\u00e9dure administrative. Il serait possible de r\u00e9gler ce point pour lever les incertitudes juridiques actuelles et assurer que la justice continue de fonctionner.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le Conseil f\u00e9d\u00e9ral entend prendre des mesures pour pr\u00e9server les entreprises suisses d\u2019une faillite due \u00e0 la crise du coronavirus. Lors de sa s\u00e9ance du 8 avril 2020, il a charg\u00e9 le D\u00e9partement f\u00e9d\u00e9ral de justice et police (DFJP) de lui soumettre des propositions la semaine prochaine. Le Conseil f\u00e9d\u00e9ral a par ailleurs d\u00e9cid\u00e9 de ne pas prolonger la suspension des poursuites, ni les f\u00e9ries judiciaires<\/p>\n","protected":false},"author":4,"featured_media":323575,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171,22521,1170],"tags":[],"vendi":[],"content_country":[],"class_list":["post-369962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thematique","category-coronavirus-minutes-par-minutes","category-vivre-en-suisse"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/369962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=369962"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/369962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/323575"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=369962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=369962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=369962"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=369962"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=369962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}