{"id":379577,"date":"2020-05-19T04:16:02","date_gmt":"2020-05-19T02:16:02","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=379577"},"modified":"2020-05-19T04:16:02","modified_gmt":"2020-05-19T02:16:02","slug":"les-mesures-de-canalisation-vers-lallemagne-et-lautriche-sont-levees","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/les-mesures-de-canalisation-vers-lallemagne-et-lautriche-sont-levees\/","title":{"rendered":"Les mesures de canalisation vers l&#8217;Allemagne et l&#8217;Autriche sont lev\u00e9es"},"content":{"rendered":"<p>Avec l&#8217;entr\u00e9e en vigueur de ces changements, l&#8217;Administration f\u00e9d\u00e9rale des douanes (AFD) a aboli les mesures de canalisation aux points de passage de la fronti\u00e8re vers l&#8217;Allemagne et l&#8217;Autriche. La plupart des barri\u00e8res aux points de passage ferm\u00e9s ont \u00e9t\u00e9 enlev\u00e9es par les autorit\u00e9s douani\u00e8res concern\u00e9es et les travaux devraient \u00eatre achev\u00e9s dans le courant de la journ\u00e9e. Les passages de fronti\u00e8re vers les deux pays voisins sont \u00e0 nouveau ouverts. Toutefois, les contr\u00f4les aux fronti\u00e8res resteront en vigueur; ils seront bas\u00e9s sur une analyse des risques. L&#8217;AFD peut continuer \u00e0 refuser l&#8217;entr\u00e9e en Suisse aux personnes qui ne remplissent pas les conditions requises.<\/p>\n<p>L&#8217;entr\u00e9e en Suisse pour des raisons non mentionn\u00e9es dans l&#8217;Ordonnance 2 COVID-19 ou dans les directives du Secr\u00e9tariat d&#8217;\u00c9tat aux migrations (SEM) reste interdite. Cela inclut les entr\u00e9es pour faire le plein d&#8217;essence ou pour effectuer des achats en Suisse ou les entr\u00e9es \u00e0 des fins purement touristiques. Le SEM r\u00e9pertorie toutes les informations sur les dispositions en vigueur sur son site internet.<\/p>\n<p>Le tourisme d\u2019achat reste sanctionn\u00e9 par une amende conform\u00e9ment \u00e0 l&#8217;Ordonnance 2 COVID-19 s\u2019il est \u00e9tabli, lors de l&#8217;entr\u00e9e en Suisse, que l\u2019importation de marchandises a eu lieu dans le cadre d&#8217;un voyage ayant uniquement eu un tel but. Faire des achats n\u2019est pas consid\u00e9r\u00e9 comme une raison valable pour se d\u00e9placer.<\/p>\n<p>Les passages de la fronti\u00e8re vers l&#8217;Italie et la France ne sont pas concern\u00e9s par ces assouplissements. Une \u00e9ventuelle ouverture de points de passage suppl\u00e9mentaires aura lieu en \u00e9troite collaboration avec les autorit\u00e9s partenaires suisses et \u00e9trang\u00e8res, en fonction de l&#8217;\u00e9volution de la situation. La liste actuelle des points de passage de fronti\u00e8re ouverts peut \u00eatre consult\u00e9e sur le site internet de l&#8217;AFD.<\/p>\n<p><a href=\"https:\/\/www.admin.ch\/gov\/fr\/accueil\/documentation\/communiques.msg-id-79141.html\">admin.ch<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les passages de fronti\u00e8re ferm\u00e9s vers l&#8217;Allemagne et l&#8217;Autriche sont \u00e0 nouveau ouverts. Les ouvertures ont \u00e9t\u00e9 convenues et coordonn\u00e9es entre les trois \u00c9tats et sont en vigueur depuis la nuit du vendredi 15 au samedi 16 mai 2020 \u00e0 minuit.<\/p>\n","protected":false},"author":6,"featured_media":379575,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1187,22521,1170],"tags":[],"vendi":[],"content_country":[],"class_list":["post-379577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breves","category-coronavirus-minutes-par-minutes","category-vivre-en-suisse"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/379577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=379577"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/379577\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/379575"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=379577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=379577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=379577"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=379577"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=379577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}