{"id":380435,"date":"2020-05-22T18:40:09","date_gmt":"2020-05-22T16:40:09","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=380435"},"modified":"2020-05-22T18:48:24","modified_gmt":"2020-05-22T16:48:24","slug":"financement-additionnel-de-lassurance-chomage-et-abandon-progressif-des-mesures-prises-en-lien-avec-le-covid-19","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/financement-additionnel-de-lassurance-chomage-et-abandon-progressif-des-mesures-prises-en-lien-avec-le-covid-19\/","title":{"rendered":"Financement additionnel de l\u2019assurance-ch\u00f4mage"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p>Le nombre des pr\u00e9avis de r\u00e9duction de l\u2019horaire de travail a bondi depuis la mi-mars 2020, pour ensuite se stabiliser. \u00c0 ce jour, quelque 190\u00a0000 entreprises ont demand\u00e9 une indemnit\u00e9 en cas de r\u00e9duction de l\u2019horaire de travail pour environ 1,94\u00a0million de travailleurs, ce qui correspond approximativement \u00e0 37\u00a0% du volume de l\u2019emploi en Suisse.<\/p>\n<p>Cette situation a entra\u00een\u00e9 en tr\u00e8s peu de temps un endettement consid\u00e9rable de l\u2019assurance-ch\u00f4mage. Sans la mise en place rapide d\u2019un financement additionnel, cette assurance sociale pr\u00e9sentera fin 2020 des dettes estim\u00e9es \u00e0 plus de 16\u00a0milliards de francs. Le frein \u00e0 l\u2019endettement fix\u00e9 par la loi serait ainsi d\u00e9clench\u00e9. L\u2019assurance-ch\u00f4mage serait alors tenue de proc\u00e9der \u00e0 une r\u00e9vision de la loi en vue d\u2019une stabilisation financi\u00e8re et d\u2019augmenter les cotisations salariales d\u2019au moins 0,3\u00a0point de pourcentage en 2021 d\u00e9j\u00e0. Le Conseil f\u00e9d\u00e9ral entend \u00e9viter cela dans la situation difficile actuelle et garantir que le syst\u00e8me de l\u2019assurance-ch\u00f4mage sera toujours en mesure de jouer son r\u00f4le de stabilisateur conjoncturel. C\u2019est pourquoi il est pr\u00e9vu que la Conf\u00e9d\u00e9ration prenne en charge le co\u00fbt des indemnit\u00e9s en cas de r\u00e9duction de l\u2019horaire de travail pour l\u2019ann\u00e9e en cours. Le Parlement se verra soumettre \u00e0 cet effet un cr\u00e9dit suppl\u00e9mentaire extraordinaire de 14,2\u00a0milliards de francs.<\/p>\n<p>Le 20\u00a0mai 2020, le Conseil f\u00e9d\u00e9ral s\u2019est \u00e9galement pench\u00e9 sur l\u2019abandon progressif des mesures prises en lien avec le COVID\u201119 qui visaient \u00e0 att\u00e9nuer les r\u00e9percussions n\u00e9gatives, pour les travailleurs, des interdictions et injonctions prononc\u00e9es par les autorit\u00e9s dans le cadre de la situation extraordinaire d\u00e9finie dans la loi sur les \u00e9pid\u00e9mies.<\/p>\n<p>Ces mesures ont contribu\u00e9 \u00e0 maintenir des emplois, \u00e0 pr\u00e9server des revenus et \u00e0 assurer des paiements aux entreprises concern\u00e9es rapidement et sans complications. Elles ont \u00e9galement permis d\u2019all\u00e9ger la charge administrative des organes d\u2019ex\u00e9cution cantonaux de l\u2019assurance-ch\u00f4mage.<\/p>\n<p>Les mesures adopt\u00e9es dans le cadre des ordonnances de n\u00e9cessit\u00e9 seront abandonn\u00e9es progressivement en suivant les \u00e9tapes de l\u2019assouplissement des restrictions pour permettre le red\u00e9marrage de l\u2019\u00e9conomie.<\/p>\n<ul>\n<li>Le droit extraordinaire \u00e0 la r\u00e9duction de l\u2019horaire de travail pour les personnes qui occupent une position assimilable \u00e0 celle d\u2019un employeur et pour les conjoints ou partenaires enregistr\u00e9s de ces personnes, occup\u00e9s dans l\u2019entreprise, sera supprim\u00e9 au terme du mois de mai\u00a02020. Cela correspond \u00e0 peu pr\u00e8s \u00e0 la fin \u00a0des mesures prises en lien avec le COVID-19 pour att\u00e9nuer la perte de gain des ind\u00e9pendants directement ou indirectement touch\u00e9s qui ont pris fin le 16 mai 2020..<\/li>\n<li>Le droit \u00e0 la r\u00e9duction de l\u2019horaire de travail sera supprim\u00e9 simultan\u00e9ment pour les apprentis, le but \u00e9tant que ces derniers puissent poursuivre leur formation le plus rapidement possible.<\/li>\n<li>Enfin, le d\u00e9lai de pr\u00e9avis sera r\u00e9introduit. Il avait \u00e9t\u00e9 supprim\u00e9 parce que les restrictions impos\u00e9es aux entreprises n\u2019\u00e9taient pas pr\u00e9visibles. Toutefois, les mesures du Conseil f\u00e9d\u00e9ral sont \u00e0 pr\u00e9sent connues, et les cons\u00e9quences pour les entreprises sont plus faciles \u00e0 estimer. Ces derni\u00e8res ont donc la possibilit\u00e9 de respecter le d\u00e9lai avant d\u2019annoncer un pr\u00e9avis. Les entreprises pour lesquelles la r\u00e9duction de l\u2019horaire de travail a d\u00e9j\u00e0 \u00e9t\u00e9 approuv\u00e9e ne doivent pas d\u00e9poser de nouvelle demande en raison de cette modification.<\/li>\n<\/ul>\n<p>Les autres mesures relevant du droit de n\u00e9cessit\u00e9 prendront fin comme pr\u00e9vu le 31\u00a0ao\u00fbt 2020, au terme de la dur\u00e9e d\u2019application de l\u2019ordonnance COVID\u201119 assurance-ch\u00f4mage. Les entreprises ont toujours la possibilit\u00e9 de faire appel \u00e0 l\u2019instrument du ch\u00f4mage partiel dans le cadre de la lutte contre le coronavirus, en vue de pr\u00e9server des emplois.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lors de sa s\u00e9ance du 20 mai 2020, le Conseil f\u00e9d\u00e9ral a d\u00e9cid\u00e9 de mettre en place un financement additionnel de 14,2 milliards de francs pour l\u2019assurance-ch\u00f4mage et d\u2019abandonner graduellement dans ce domaine les mesures prises en lien avec le COVID 19. L\u2019abandon de ces mesures interviendra au rythme du red\u00e9marrage progressif de l\u2019\u00e9conomie<\/p>\n","protected":false},"author":4,"featured_media":380436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18826,22521,1170],"tags":[1671],"vendi":[],"content_country":[31835],"class_list":["post-380435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lajme-jeta-ne-zvicer-fr","category-coronavirus-minutes-par-minutes","category-vivre-en-suisse","tag-zvicer-fr","content_country-austria-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/380435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=380435"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/380435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/380436"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=380435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=380435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=380435"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=380435"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=380435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}