{"id":385743,"date":"2020-06-11T00:35:18","date_gmt":"2020-06-10T22:35:18","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=385743"},"modified":"2020-06-16T22:08:30","modified_gmt":"2020-06-16T20:08:30","slug":"la-population-suisse-toujours-plus-sportive-et-plus-active","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/la-population-suisse-toujours-plus-sportive-et-plus-active\/","title":{"rendered":"La population suisse, toujours plus sportive et plus active"},"content":{"rendered":"<div class=\"mod mod-nsbnewsdetails\">\n<p>Le boom du sport perdure en Suisse. C\u2019est ce qu\u2019atteste une nouvelle enqu\u00eate repr\u00e9sentative de l\u2019Office f\u00e9d\u00e9ral du sport OFSPO, portant sur plus de 12 000 personnes. Cette enqu\u00eate s\u2019est int\u00e9ress\u00e9e \u00e0 l\u2019activit\u00e9 et \u00e0 la consommation sportives de la population r\u00e9sidante suisse \u00e2g\u00e9e de 15 ans ou plus. Elle a \u00e9t\u00e9 r\u00e9alis\u00e9e par l\u2019Observatoire Suisse du Sport sur mandat de l\u2019OFSPO. Comme elle le montre, plus de la moiti\u00e9 de la population \u00e9tudi\u00e9e fait partie des personnes tr\u00e8s actives. La population est devenue non seulement plus sportive, mais elle est aussi plus active physiquement: aujourd\u2019hui, en effet, environ 80 % de la population r\u00e9sidante adulte satisfont aux recommandations en mati\u00e8re d\u2019activit\u00e9s physique de l\u2019OFSPO et de l\u2019Office f\u00e9d\u00e9ral de la sant\u00e9 publique OFSP.<br \/>\nLa progression de l\u2019activit\u00e9 sportive est port\u00e9e surtout par les femmes et les personnes dans la seconde moiti\u00e9 de la vie. Les femmes ont rattrap\u00e9 les hommes et sont des sportives particuli\u00e8rement assidues \u00e0 partir de 45 ans. Le sport des a\u00een\u00e9s a globalement progress\u00e9: aujourd\u2019hui, la part des tr\u00e8s actifs est presque aussi \u00e9lev\u00e9e chez les 65-74 ans que chez les 15-24 ans.<\/p>\n<h2>Net recul du nombre d\u2019inactifs<\/h2>\n<p>La part des non-sportifs a diminu\u00e9 pour la premi\u00e8re fois depuis les ann\u00e9es 1970, et de fa\u00e7on marqu\u00e9e puisqu\u2019elle est pass\u00e9e de 26 % \u00e0 16 %. Dans les trois enqu\u00eates sur le sport suisse r\u00e9alis\u00e9es ant\u00e9rieurement, respectivement en 2000, 2008 et 2014, un quart des personnes interrog\u00e9es se disaient non sportives. Cette r\u00e9alit\u00e9 a perdu son immuabilit\u00e9 au cours des six derni\u00e8res ann\u00e9es. Durant la m\u00eame p\u00e9riode, le nombre de sportifs occasionnels a augment\u00e9. En comparaison nationale, la Suisse romande et le Tessin ont rattrap\u00e9 leur retard, entra\u00eenant une r\u00e9duction des diff\u00e9rences r\u00e9gionales.<\/p>\n<h2>Le \u00abcombin\u00e9 helv\u00e9tique\u00bb toujours en t\u00eate<\/h2>\n<p>Comme dans les enqu\u00eates pr\u00e9c\u00e9dentes, le \u00abcombin\u00e9 helv\u00e9tique\u00bb tr\u00f4ne en t\u00eate du classement des activit\u00e9s pr\u00e9f\u00e9r\u00e9es de la population. Il comprend cinq sports qui ont pour particularit\u00e9 de pouvoir se pratiquer tout au long de la vie: randonn\u00e9e p\u00e9destre, cyclisme, natation, ski et jogging. La randonn\u00e9e, en particulier, a fait un nouveau bond en avant depuis l\u2019enqu\u00eate de 2014. Aujourd\u2019hui, elle compte parmi les sports les plus pratiqu\u00e9s, tous sexes et groupes d\u2019\u00e2ge confondus. La musculation, le yoga et la danse ont, eux aussi, nettement gagn\u00e9 en popularit\u00e9 au cours des six derni\u00e8res ann\u00e9es. Ph\u00e9nom\u00e8ne dans l\u2019air du temps, la population est devenue encore plus polysportive, avec 4,5 sports diff\u00e9rents pratiqu\u00e9s en moyenne \u00e0 l\u2019heure actuelle.<\/p>\n<h2>Importance confirm\u00e9e des clubs<\/h2>\n<p>Les clubs de sport sont encore et toujours un ressort important du sport suisse, \u00e0 preuve les 22% de la population adulte qui en sont membres. Les habitants des zones rurales sont plus souvent affili\u00e9s \u00e0 un club que ceux des zones urbaines, qui pr\u00e9f\u00e8rent les centres de fitness. Au cours de la p\u00e9riode \u00e9tudi\u00e9e, le nombre de personnes qui fr\u00e9quentent r\u00e9guli\u00e8rement ces derniers a fortement augment\u00e9.<\/p>\n<p>La Suisse est aussi tr\u00e8s sportive en comparaison internationale. Elle fait partie, avec la Finlande, la Su\u00e8de et le Danemark, des pays les plus sportifs du continent europ\u00e9en. Si l\u2019on consid\u00e8re les personnes qui font du sport au moins une fois par semaine, elle est carr\u00e9ment en t\u00eate du classement europ\u00e9en avec un r\u00e9sultat de 59%.<\/p>\n<p>Le boom que le sport a connu au cours des 20 derni\u00e8res ann\u00e9es a entra\u00een\u00e9 la quasi-disparition des diff\u00e9rences li\u00e9es au sexe et \u00e0 l\u2019\u00e2ge et une forte r\u00e9duction des disparit\u00e9s entre les r\u00e9gions linguistiques. Reste une diff\u00e9rence nette entre l\u2019activit\u00e9 sportive de la population suisse et celle de la majorit\u00e9 des \u00e9trangers vivant en Suisse. Mais l\u2019enqu\u00eate montre que, globalement, les migrantes ont rattrap\u00e9 leur retard et sont devenues plus sportives.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La pratique sportive et l\u2019activit\u00e9 physique ont fait un nouveau bond en avant en Suisse au cours des six derni\u00e8res ann\u00e9es, un essor que l\u2019on doit surtout aux femmes et aux seniors. Simultan\u00e9ment, le nombre des non-sportifs a pour la premi\u00e8re fois significativement diminu\u00e9. Tels sont les principaux r\u00e9sultats de l\u2019enqu\u00eate \u00abSport Suisse 2020\u00bb r\u00e9alis\u00e9e par l\u2019Office f\u00e9d\u00e9ral du sport OFSPO et pr\u00e9sent\u00e9e aujourd\u2019hui \u00e0 Berne par la conseill\u00e8re f\u00e9d\u00e9rale Viola Amherd<\/p>\n","protected":false},"author":4,"featured_media":370437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18826,22521,1169,1170],"tags":[],"vendi":[],"content_country":[31835,31838],"class_list":["post-385743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lajme-jeta-ne-zvicer-fr","category-coronavirus-minutes-par-minutes","category-sport-fr","category-vivre-en-suisse","content_country-austria-fr","content_country-germany-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/385743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=385743"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/385743\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/370437"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=385743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=385743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=385743"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=385743"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=385743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}