{"id":433702,"date":"2020-12-30T23:50:44","date_gmt":"2020-12-30T22:50:44","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=433702"},"modified":"2020-12-31T00:52:09","modified_gmt":"2020-12-30T23:52:09","slug":"coronavirus-le-conseil-federal-ne-renforce-pas-le-dispositif-de-mesures","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/coronavirus-le-conseil-federal-ne-renforce-pas-le-dispositif-de-mesures\/","title":{"rendered":"Coronavirus: le Conseil f\u00e9d\u00e9ral ne renforce pas le dispositif de mesures"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p><strong>Le Conseil f\u00e9d\u00e9ral a proc\u00e9d\u00e9 \u00e0 une analyse d\u00e9taill\u00e9e de la situation \u00e9pid\u00e9miologique actuelle. Celle-ci reste pr\u00e9occupante avec un niveau \u00e9lev\u00e9 de contaminations et l\u2019arriv\u00e9e en Suisse de nouvelles souches du virus. Le Conseil f\u00e9d\u00e9ral estime toutefois que les mesures prises le 18 d\u00e9cembre 2020, \u00e0 savoir la fermeture des restaurants, des \u00e9tablissements culturels et sportifs ainsi que des lieux de loisirs, sont ad\u00e9quates et qu\u2019il n\u2019y a pas lieu de les renforcer.<\/strong><\/p>\n<p>Conform\u00e9ment \u00e0 sa d\u00e9cision du 18 d\u00e9cembre 2020, le Conseil f\u00e9d\u00e9ral a \u00e9t\u00e9 inform\u00e9 par \u00e9crit le 30 d\u00e9cembre 2020 quant \u00e0 la n\u00e9cessit\u00e9 de renforcer les mesures de lutte contre le coronavirus. Apr\u00e8s une analyse d\u00e9taill\u00e9e de la situation \u00e9pid\u00e9miologique, il s\u2019av\u00e8re que les crit\u00e8res qu\u2019il avait fix\u00e9s pour un tel renforcement ne sont pas remplis. Dans ces conditions, le Conseil f\u00e9d\u00e9ral a d\u00e9cid\u00e9 de maintenir les mesures actuelles. Il continue de suivre la situation avec attention et proc\u00e9dera \u00e0 une nouvelle analyse le 6 janvier 2021.<\/p>\n<p>Le taux de reproduction du virus est actuellement inf\u00e9rieur \u00e0 1 (0,86 au 18 d\u00e9cembre 2020). Toutefois, cette baisse ainsi que le faible nombre de nouveaux cas affich\u00e9s ces derniers jours doivent \u00eatre consid\u00e9r\u00e9s avec beaucoup de prudence. Ils s\u2019expliquent en grande partie par la r\u00e9duction du nombre de tests effectu\u00e9s pendant les f\u00eates et par le retard pris pour les annonces de nouveaux cas, d\u2019hospitalisations et de d\u00e9c\u00e8s.<\/p>\n<p><b>Nouvelles souches de coronavirus<\/b><\/p>\n<p>Apr\u00e8s l\u2019apparition de nouvelles souches de coronavirus au Royaume-Uni et en Afrique du Sud, le Conseil f\u00e9d\u00e9ral a pris, le 21 d\u00e9cembre 2020, des mesures pour emp\u00eacher ou ralentir sa diffusion en Suisse. Sept personnes infect\u00e9es par ces nouvelles souches ont \u00e9t\u00e9 jusqu\u2019ici identifi\u00e9es gr\u00e2ce au s\u00e9quen\u00e7age intensifi\u00e9 de tests positifs.<\/p>\n<p>Ces nouvelles souches de coronavirus sont nettement plus contagieuses que la forme connue jusqu\u2019ici, selon les conclusions du Centre europ\u00e9en de pr\u00e9vention et de contr\u00f4le des maladies (ECDC). Par contre, il n\u2019existe aucune preuve scientifique qu\u2019elles provoquent des formes plus s\u00e9v\u00e8res de la maladie ni que les vaccins actuels contre le COVID-19 ne sont pas efficaces. Le Conseil f\u00e9d\u00e9ral estime que les mesures prises le 18 d\u00e9cembre 2020 sont d\u2019autant plus importantes pour limiter le nombre de nouveaux cas et ralentir la propagation de ces nouvelles souches. Les r\u00e8gles d\u2019hygi\u00e8ne et de conduite restent par ailleurs essentielles pour se prot\u00e9ger contre le virus et lutter contre l\u2019\u00e9pid\u00e9mie.<\/p>\n<p>Dans ce contexte, il s\u2019agit \u00e9galement d\u2019augmenter le nombre de tests et d\u2019intensifier le suivi et le tra\u00e7age des contacts. L\u2019Office f\u00e9d\u00e9ral de la sant\u00e9 publique et les cantons, en collaboration avec la task-force scientifique, sont en \u00e9troit contact pour adapter les recommandations en fonction des derniers d\u00e9veloppements. Si ces nouvelles souches devaient se r\u00e9pandre plus largement, des mesures suppl\u00e9mentaires pourraient \u00eatre prises.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Conform\u00e9ment \u00e0 sa d\u00e9cision du 18 d\u00e9cembre 2020, le Conseil f\u00e9d\u00e9ral a \u00e9t\u00e9 inform\u00e9 par \u00e9crit le 30 d\u00e9cembre 2020 quant \u00e0 la n\u00e9cessit\u00e9 de renforcer les mesures de lutte contre le coronavirus<\/p>\n","protected":false},"author":4,"featured_media":415618,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18826,22521,24630,1170],"tags":[],"vendi":[],"content_country":[31835,31838],"class_list":["post-433702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lajme-jeta-ne-zvicer-fr","category-coronavirus-minutes-par-minutes","category-nouvelles","category-vivre-en-suisse","content_country-austria-fr","content_country-germany-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/433702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=433702"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/433702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/415618"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=433702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=433702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=433702"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=433702"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=433702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}