{"id":440192,"date":"2021-01-28T19:04:02","date_gmt":"2021-01-28T18:04:02","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=440192"},"modified":"2021-01-28T19:04:02","modified_gmt":"2021-01-28T18:04:02","slug":"la-confederation-prend-en-charge-le-cout-du-depistage-des-personnes-non-symptomatiques-et-adapte-les-regles-relatives-a-la-quarantaine","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/la-confederation-prend-en-charge-le-cout-du-depistage-des-personnes-non-symptomatiques-et-adapte-les-regles-relatives-a-la-quarantaine\/","title":{"rendered":"La Conf\u00e9d\u00e9ration prend en charge le co\u00fbt du d\u00e9pistage des personnes non symptomatiques et adapte les r\u00e8gles relatives \u00e0 la quarantaine"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p><strong>Lors de sa s\u00e9ance du 27 janvier 2021, le Conseil f\u00e9d\u00e9ral a pris plusieurs d\u00e9cisions visant \u00e0 freiner et \u00e0 endiguer l\u2019\u00e9pid\u00e9mie de coronavirus. La Conf\u00e9d\u00e9ration prendra d\u00e9sormais en charge le co\u00fbt du d\u00e9pistage des personnes non symptomatiques afin de mieux prot\u00e9ger les personnes vuln\u00e9rables et de combattre le plus t\u00f4t possible les foyers locaux d\u2019infection. Il a par ailleurs d\u00e9cid\u00e9 d\u2019adapter les r\u00e8gles relatives aux quarantaines. La quarantaine de dix jours peut \u00eatre raccourcie si la personne se fait tester apr\u00e8s sept jours et que le r\u00e9sultat est n\u00e9gatif. Le Conseil f\u00e9d\u00e9ral a par ailleurs d\u00e9cid\u00e9 qu\u2019il \u00e9tait possible d\u2019infliger des amendes d\u2019ordre en cas de non-respect de certaines mesures. Enfin, la Conf\u00e9d\u00e9ration assumera \u00e9galement le co\u00fbt des vaccinations en pharmacie.<\/strong><\/p>\n<p>On estime que plus de la moiti\u00e9 des contaminations au COVID-19 sont le fait de personnes asymptomatiques, qui ne savent donc pas qu&#8217;elles sont infect\u00e9es. Mi-d\u00e9cembre, la Conf\u00e9d\u00e9ration a donc autoris\u00e9 le d\u00e9pistage des personnes non symptomatiques dans le cadre de plans de protection, par exemple dans les EMS, les h\u00f4tels ou au travail. Afin de renforcer cette pratique, elle prendra d\u00e9sormais en charge le co\u00fbt de ces tests, qui peuvent \u00eatre effectu\u00e9s sur place par le personnel lui-m\u00eame. Les r\u00e9sultats n\u00e9gatifs de ces tests rapides ne devront pas \u00eatre d\u00e9clar\u00e9s. Si le r\u00e9sultat est positif, la personne doit effectuer un test PCR et, dans ce cas, le r\u00e9sultat doit faire l&#8217;objet d&#8217;une d\u00e9claration.<\/p>\n<p>La strat\u00e9gie de d\u00e9pistage \u00e9largie doit aussi permettre d&#8217;identifier et d&#8217;endiguer les foyers locaux d&#8217;infection, notamment dans les \u00e9coles, ce qui est d&#8217;autant plus important que les nouvelles variantes plus contagieuses de coronavirus se propagent en Suisse. Dans ce cas aussi, la Conf\u00e9d\u00e9ration prend en charge les co\u00fbts du d\u00e9pistage des personnes non symptomatiques. Il suffit que le canton concern\u00e9 pr\u00e9sente \u00e0 l&#8217;Office f\u00e9d\u00e9ral de la sant\u00e9 publique (OFSP) un plan pr\u00e9cisant notamment qui sera test\u00e9 et o\u00f9, \u00e0 quelle fr\u00e9quence et avec quels tests.<\/p>\n<p>Les crit\u00e8res de d\u00e9pistage de l&#8217;OFSP seront adapt\u00e9s en cons\u00e9quence. Il faut en outre adapter l&#8217;ordonnance\u00a03 COVID-19, dont la modification entrera en vigueur jeudi 28 janvier 2021.<\/p>\n<p><strong>Adaptation des r\u00e8gles relatives aux quarantaines<br \/>\n<\/strong>La r\u00e9glementation qui pr\u00e9vaut actuellement en mati\u00e8re de quarantaine pour les personnes de contact sera compl\u00e9t\u00e9e par le biais d&#8217;une strat\u00e9gie de d\u00e9pistage et de sortie de quarantaine. Jusqu&#8217;\u00e0 pr\u00e9sent, une personne ayant \u00e9t\u00e9 en contact avec une personne infect\u00e9e devait se mettre en quarantaine pendant dix jours. D\u00e9sormais, la personne pourra sortir de quarantaine plus t\u00f4t que pr\u00e9vu moyennant l&#8217;approbation de l&#8217;autorit\u00e9 cantonale comp\u00e9tente en faisant un test PCR ou un test antig\u00e9nique rapide \u00e0 partir du 7e jour de quarantaine et que le r\u00e9sultat est n\u00e9gatif. C&#8217;est \u00e0 elle de prendre en charge les co\u00fbts du d\u00e9pistage. De plus, elle doit, jusqu&#8217;\u00e0 la fin de la quarantaine pr\u00e9vue (10e jour), porter syst\u00e9matiquement un masque facial et maintenir une distance de 1,5 m avec les autres personnes, sauf lorsqu&#8217;elle se trouve dans son logement ou son lieu d&#8217;h\u00e9bergement (h\u00f4tel, appartement de vacances). Si le r\u00e9sultat du test est positif, la personne doit imm\u00e9diatement se placer en isolement.<\/p>\n<p><strong>Une quarantaine raccourcie pour les voyageurs<br \/>\n<\/strong>La nouvelle strat\u00e9gie de d\u00e9pistage et de sortie de quarantaine s&#8217;applique aussi aux personnes entrant en Suisse depuis un Etat ou zone pr\u00e9sentant un risque \u00e9lev\u00e9 d&#8217;infection. Ces personnes doivent d\u00e9sormais pr\u00e9senter un test PCR n\u00e9gatif datant de moins de 72 h \u00e0 leur entr\u00e9e, puis se mettre en quarantaine pour dix jours comme c&#8217;\u00e9tait le cas jusqu&#8217;\u00e0 pr\u00e9sent. Elles peuvent toutefois en sortir apr\u00e8s sept jours en faisant un test antig\u00e9nique rapide ou un test PCR et que le r\u00e9sultat est n\u00e9gatif. Les personnes entrant en Suisse par les airs en provenance d&#8217;un Etat ou zone ne pr\u00e9sentant pas un risque \u00e9lev\u00e9 d&#8217;infection doivent \u00e9galement pr\u00e9senter un test PCR n\u00e9gatif. Les voyageurs seront contr\u00f4l\u00e9s avant de monter dans l&#8217;avion.<\/p>\n<p><strong>Recensement plus large des coordonn\u00e9es<br \/>\n<\/strong>Jusqu&#8217;\u00e0 pr\u00e9sent, seules les coordonn\u00e9es de personnes en provenance d&#8217;un Etat ou zone \u00e0 risque \u00e9taient enregistr\u00e9es. D\u00e9sormais, cela sera aussi le cas des autres voyageurs arrivant par avion, bateau, bus ou train. Les donn\u00e9es correspondantes seront d\u00e9sormais recens\u00e9es par le biais d&#8217;un formulaire \u00e9lectronique d&#8217;entr\u00e9e sur le territoire, ce qui permettra d&#8217;acc\u00e9l\u00e9rer et de simplifier le tra\u00e7age des contaminations et d&#8217;interrompre plus rapidement les cha\u00eenes de transmission.<\/p>\n<p>Les d\u00e9cisions concernant les quarantaines et l&#8217;entr\u00e9e sur le territoire prises par le Conseil f\u00e9d\u00e9ral appellent une adaptation des ordonnances COVID-19 concern\u00e9es. Les modifications entreront en vigueur le 8 f\u00e9vrier 2021.<\/p>\n<p><strong>Amendes d&#8217;ordre : les d\u00e9lits mentionn\u00e9s explicitement<br \/>\n<\/strong>A partir du 1er f\u00e9vrier 2021, les violations de certaines mesures de lutte contre l&#8217;\u00e9pid\u00e9mie seront explicitement inscrites comme des d\u00e9lits et pourront ainsi \u00eatre sanctionn\u00e9es par des amendes d&#8217;ordre. Les amendes oscilleront entre 50 et 200\u00a0francs selon le d\u00e9lit et permettront de sanctionner les personnes qui, par exemple, ne portent pas de masque dans les transports publics, dans les gares, aux arr\u00eats ainsi que devant et dans les \u00e9tablissements et installations accessibles au public. La participation \u00e0 des manifestations non autoris\u00e9es ou l&#8217;organisation d&#8217;une manifestation priv\u00e9e interdite pourront \u00e9galement \u00eatre punies. Pouvoir infliger sans attendre une amende d&#8217;ordre en cas de violation des mesures doit promouvoir leur respect et d\u00e9charger les autorit\u00e9s de poursuites p\u00e9nales.<\/p>\n<p><strong>La Conf\u00e9d\u00e9ration prend en charge le co\u00fbt de la vaccination en pharmacie<br \/>\n<\/strong>D\u00e8s le 1er f\u00e9vrier, la Conf\u00e9d\u00e9ration prendra aussi en charge le co\u00fbt de la vaccination en pharmacie aux m\u00eames conditions que pour les vaccinations en centre. Les cantons pourront ainsi int\u00e9grer les pharmacies dans leur dispositif de vaccination.<\/p>\n<p><strong>Contr\u00f4le des masques de protection<br \/>\n<\/strong>Les masques de protection susceptibles de pr\u00e9senter un d\u00e9faut de s\u00e9curit\u00e9 qui sont stock\u00e9s par la Conf\u00e9d\u00e9ration ou les cantons doivent pouvoir \u00eatre contr\u00f4l\u00e9s a posteriori. S&#8217;ils ne r\u00e9pondent pas aux exigences pos\u00e9es, ils ne doivent plus pouvoir \u00eatre utilis\u00e9s. Le Conseil f\u00e9d\u00e9ral a modifi\u00e9 l&#8217;ordonnance\u00a03 COVID-19 dans ce sens. Au d\u00e9but de la pand\u00e9mie de COVID-19, les besoins du personnel de sant\u00e9 en masques respiratoires \u00e9taient \u00e9lev\u00e9s et la Suisse a achet\u00e9 de grandes quantit\u00e9s de masques qui pourraient pr\u00e9senter un d\u00e9faut de s\u00e9curit\u00e9.<\/p>\n<p><strong>Le nombre de cas ne baisse que lentement<br \/>\n<\/strong>La situation \u00e9pid\u00e9miologique ne se d\u00e9tend que lentement en Suisse, notamment pour ce qui concerne le nombre de nouvelles infections. La baisse du nombre d&#8217;hospitalisations et de d\u00e9c\u00e8s est quant \u00e0 elle plus marqu\u00e9e, m\u00eame si la pression sur les soins intensifs reste \u00e9lev\u00e9e. La part des nouvelles variantes dans les r\u00e9sultats positifs continue de doubler chaque semaine. Le Conseil f\u00e9d\u00e9ral suit cette \u00e9volution avec pr\u00e9occupation et continue de viser une baisse rapide et significative du nombre de cas.<\/p>\n<p><strong>Acteurs culturels\u00a0: des indemnit\u00e9s r\u00e9troactives<br \/>\n<\/strong>Afin d&#8217;\u00e9viter un d\u00e9faut de couverture, le Conseil f\u00e9d\u00e9ral a par ailleurs d\u00e9cid\u00e9 de demander au Parlement que les acteurs culturels re\u00e7oivent r\u00e9troactivement des indemnit\u00e9s pour pertes financi\u00e8res \u00e0 partir du 1er novembre 2020. Lesdits acteurs pourront d\u00e9poser leur demande d\u00e8s que les cantons, qui sont comp\u00e9tents en la mati\u00e8re, se seront dot\u00e9s des bases l\u00e9gales n\u00e9cessaires.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9sormais, la personne pourra sortir de quarantaine plus t\u00f4t que pr\u00e9vu moyennant l&#8217;approbation de l&#8217;autorit\u00e9 cantonale comp\u00e9tente en faisant un test PCR ou un test antig\u00e9nique rapide \u00e0 partir du 7e jour de quarantaine et que le r\u00e9sultat est n\u00e9gatif<\/p>\n","protected":false},"author":4,"featured_media":439972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18826,22521,24630,1170],"tags":[],"vendi":[],"content_country":[31835,31838],"class_list":["post-440192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lajme-jeta-ne-zvicer-fr","category-coronavirus-minutes-par-minutes","category-nouvelles","category-vivre-en-suisse","content_country-austria-fr","content_country-germany-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/440192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=440192"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/440192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/439972"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=440192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=440192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=440192"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=440192"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=440192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}