{"id":465499,"date":"2021-04-28T20:53:51","date_gmt":"2021-04-28T18:53:51","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=465499"},"modified":"2021-04-28T20:53:51","modified_gmt":"2021-04-28T18:53:51","slug":"coronavirus-davantage-de-securite-pour-planifier-les-grandes-manifestations-a-partir-de-juillet-2021","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/coronavirus-davantage-de-securite-pour-planifier-les-grandes-manifestations-a-partir-de-juillet-2021\/","title":{"rendered":"Coronavirus : davantage de s\u00e9curit\u00e9 pour planifier les grandes manifestations \u00e0 partir de juillet 2021"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p><strong>Le Conseil f\u00e9d\u00e9ral veut offrir des perspectives \u00e0 la branche de l\u2019\u00e9v\u00e9nementiel et aux cantons pour planifier de grandes manifestations. Il a pr\u00e9sent\u00e9 aujourd\u2019hui les conditions qui doivent permettre aux cantons d\u2019autoriser les grandes manifestations \u00e0 partir de l\u2019\u00e9t\u00e9 2021, m\u00eame s\u2019il n\u2019est pas encore certain que l\u2019\u00e9volution \u00e9pid\u00e9miologique permettra leur tenue. Ces dispositions visent \u00e0 donner aux cantons des outils d\u00e9cisionnels pour d\u00e9livrer les autorisations, mais ne correspondent pas \u00e0 des d\u00e9cisions d\u2019assouplissement. Concr\u00e8tement, les manifestations qui auront obtenu une autorisation cantonale et qui se verraient annul\u00e9es pour des raisons \u00e9pid\u00e9miologiques b\u00e9n\u00e9ficieront d\u2019une protection financi\u00e8re (\u00ab parapluie de protection \u00bb). Les cantons et les associations professionnelles concern\u00e9es peuvent prendre position sur ces propositions jusqu\u2019au 10 mai 2021 dans le cadre de la consultation.<\/strong><\/p>\n<p>A l\u2019exception d\u2019une br\u00e8ve parenth\u00e8se en octobre\u00a02020, les grandes manifestations de plus de 1000\u00a0personnes sont interdites depuis fin f\u00e9vrier\u00a02020. En fonction de la progression de la vaccination et de la situation \u00e9pid\u00e9miologique, elles pourraient \u00e0 nouveau \u00eatre autoris\u00e9es \u00e0 partir de l\u2019\u00e9t\u00e9\u00a02021. Le Conseil f\u00e9d\u00e9ral se prononcera vraisemblablement dans la seconde moiti\u00e9 du mois de juin sur les conditions et les dates pr\u00e9cises de ces assouplissements. Toutefois, comme les grandes manifestations exigent des pr\u00e9paratifs relativement longs, il veut donner au plus vite une certaine s\u00e9curit\u00e9 aux organisateurs pour planifier leurs \u00e9v\u00e9nements et fournir aux cantons des outils d\u00e9cisionnels pour d\u00e9livrer les autorisations correspondantes.<\/p>\n<p><b>Une protection financi\u00e8re pour le secteur de l\u2019\u00e9v\u00e9nementiel<\/b><b><\/b><\/p>\n<p>Lors de la session de printemps 2021, le Parlement a introduit un nouvel art.\u00a011<i>a<\/i>\u00a0dans la loi COVID-19 pour soutenir la reprise des manifestations d\u2019importance supracantonale (\u00ab\u00a0parapluie de protection\u00a0\u00bb). Cette disposition permet d\u2019autoriser des manifestations publiques avant de savoir avec certitude si la situation \u00e9pid\u00e9miologique permettra leur tenue. En cas de report ou d\u2019annulation d\u2019une manifestation en raison de la situation \u00e9pid\u00e9miologique, la Conf\u00e9d\u00e9ration et les cantons couvriront une partie du d\u00e9couvert.<\/p>\n<p>Le Conseil f\u00e9d\u00e9ral a pr\u00e9sent\u00e9 aujourd\u2019hui les modalit\u00e9s concr\u00e8tes de ce m\u00e9canisme. Pour toucher l\u2019aide f\u00e9d\u00e9rale, il faudra qu\u2019un organisateur ait obtenu du canton l\u2019autorisation d\u2019organiser sa manifestation et la garantie qu\u2019il b\u00e9n\u00e9ficiera de cette couverture financi\u00e8re. Il faudra aussi que la manifestation s\u2019adresse \u00e0 un public supracantonal et pr\u00e9voie la participation d\u2019au moins 1000\u00a0personnes par jour.<\/p>\n<p>Pour chaque manifestation concern\u00e9e, l\u2019organisateur devra assumer une franchise de 30\u00a0000\u00a0francs sur le d\u00e9couvert et une quote-part de 20% sur le montant restant. Si le canton prend en charge la moiti\u00e9 du d\u00e9couvert, la Conf\u00e9d\u00e9ration paiera l\u2019autre moiti\u00e9. La prise en charge des co\u00fbts par la Conf\u00e9d\u00e9ration et les cantons est plafonn\u00e9e \u00e0 5 millions de francs par manifestation. Cette r\u00e9glementation s\u2019appliquera pour les manifestations organis\u00e9es entre le 1er\u00a0juin\u00a02021 et le 30\u00a0avril\u00a02022. La plupart des cantons doivent encore cr\u00e9er la base l\u00e9gale n\u00e9cessaire \u00e0 sa mise en \u0153uvre.<\/p>\n<p><b>Autorisation des manifestations de 3000\u00a0personnes d\u00e8s juillet<\/b><b><\/b><\/p>\n<p>D\u00e8s fin mai, les cantons pourront autoriser les grandes manifestations de 3000\u00a0personnes au plus \u00e0 partir du 1er\u00a0juillet\u00a02021, moyennant le respect de conditions strictes. A partir du 1er\u00a0septembre, cette limite sera relev\u00e9e \u00e0 10\u00a0000\u00a0personnes. Ces dates et limites de capacit\u00e9 ne correspondent pas \u00e0 un assouplissement formel\u00a0: le Conseil f\u00e9d\u00e9ral d\u00e9cidera ult\u00e9rieurement si les manifestations pourront effectivement avoir lieu. Les cantons devront r\u00e9voquer l\u2019autorisation ou \u00e9mettre des restrictions suppl\u00e9mentaires si la situation \u00e9pid\u00e9miologique se d\u00e9t\u00e9riore au point que la manifestation ne peut plus avoir lieu ou qu\u2019il n\u2019est plus possible de garantir le tra\u00e7age des contacts. Le cas \u00e9ch\u00e9ant, les organisateurs pourront b\u00e9n\u00e9ficier du m\u00e9canisme de couverture financi\u00e8re.<\/p>\n<p><b>Manifestations pilotes de 300 \u00e0 600 personnes en juin<\/b><b><\/b><\/p>\n<p>Le Conseil f\u00e9d\u00e9ral a \u00e9galement d\u00e9termin\u00e9 les mesures de protection \u00e0 respecter pour l\u2019octroi de l\u2019autorisation cantonale. Afin de minimiser le risque de contamination, l\u2019organisateur devra pr\u00e9voir des plans de protection stricts et limiter l\u2019acc\u00e8s \u00e0 la manifestation aux personnes vaccin\u00e9es, gu\u00e9ries ou en possession d\u2019un r\u00e9sultat de test n\u00e9gatif.<\/p>\n<p>Conscient du d\u00e9fi que repr\u00e9sentent les plans de protection pour les grandes manifestations, le Conseil f\u00e9d\u00e9ral propose par ailleurs une phase pilote. Ainsi, durant le mois de juin\u00a02021, chaque canton pourra autoriser la tenue de trois manifestations pilotes rassemblant entre 300 et 600\u00a0personnes. Ces manifestations pilotes devront montrer si \u2013 et, le cas \u00e9ch\u00e9ant, comment \u2013 il est possible d\u2019appliquer les plans de protection aux grandes manifestations et de garantir le contr\u00f4le des justificatifs de vaccination, de test n\u00e9gatif ou de gu\u00e9rison. Il s\u2019agit aussi de v\u00e9rifier si l\u2019utilisation des autotests r\u00e9alis\u00e9s sur place et sous la surveillance de l\u2019organisateur est une solution praticable. Le Conseil f\u00e9d\u00e9ral tiendra compte des r\u00e9sultats de cette phase pilote dans ses d\u00e9cisions concernant les prochaines \u00e9tapes d\u2019assouplissement.<\/p>\n<p>D\u2019ici \u00e0 l\u2019\u00e9t\u00e9, un certificat COVID infalsifiable et valable dans toute la Suisse, qui attestera de la vaccination, d\u2019un r\u00e9sultat de test n\u00e9gatif ou d\u2019une gu\u00e9rison, devrait \u00eatre disponible, ce qui simplifiera consid\u00e9rablement les contr\u00f4les \u00e0 l\u2019entr\u00e9e.<\/p>\n<p><b>Consultation jusqu\u2019au 10\u00a0mai<\/b><b><\/b><\/p>\n<p>Le Conseil f\u00e9d\u00e9ral a soumis ces propositions aux cantons, aux villes et aux communes, aux associations fa\u00eeti\u00e8res des partenaires sociaux, aux associations et aux organisations des domaines de l\u2019\u00e9v\u00e9nementiel et du sport, au Conseil suisse des religions ainsi qu\u2019aux commissions parlementaires concern\u00e9es. Il pr\u00e9voit de prendre une d\u00e9cision d\u00e9finitive le 26\u00a0mai\u00a02021.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e8s fin mai, les cantons pourront autoriser les grandes manifestations de 3000\u00a0personnes au plus \u00e0 partir du 1er\u00a0juillet\u00a02021, moyennant le respect de conditions strictes. A partir du 1er\u00a0septembre, cette limite sera relev\u00e9e \u00e0 10\u00a0000\u00a0personnes<\/p>\n","protected":false},"author":4,"featured_media":403909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18826,22521,24630,1170,1411,2014],"tags":[],"vendi":[],"content_country":[31838,31840],"class_list":["post-465499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lajme-jeta-ne-zvicer-fr","category-coronavirus-minutes-par-minutes","category-nouvelles","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr","content_country-germany-fr","content_country-zvicer-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/465499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=465499"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/465499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/403909"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=465499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=465499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=465499"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=465499"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=465499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}