{"id":530204,"date":"2022-01-02T13:10:22","date_gmt":"2022-01-02T12:10:22","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=530204"},"modified":"2022-01-05T22:32:56","modified_gmt":"2022-01-05T21:32:56","slug":"larmee-convoque-des-troupes-supplementaires-pour-lengagement-corona-2","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/larmee-convoque-des-troupes-supplementaires-pour-lengagement-corona-2\/","title":{"rendered":"L\u2019arm\u00e9e convoque des troupes suppl\u00e9mentaires pour l\u2019engagement CORONA"},"content":{"rendered":"<div class=\"contentHead\">\n<p><span style=\"font-size: 16px;\">Depuis le d\u00e9but du mois de d\u00e9cembre, des militaires soutiennent les \u00e9tablissements de sant\u00e9 des cantons dans le cadre du service sanitaire afin de les aider \u00e0 ma\u00eetriser la pand\u00e9mie de coronavirus et \u00e0 administrer la troisi\u00e8me dose de vaccin (booster). Actuellement, environ 296 militaires en service long et volontaires sont engag\u00e9s dans les cantons du Jura, du Valais, de Neuch\u00e2tel et de Fribourg. <\/span><\/p>\n<p><span style=\"font-size: 16px;\">Pour r\u00e9pondre \u00e0 d\u2019autres demandes approuv\u00e9es des cantons d\u2019Argovie, de Lucerne et de Nidwald et dans la perspective d\u2019une augmentation des missions confi\u00e9es \u00e0 l\u2019arm\u00e9e, cette derni\u00e8re met aujourd\u2019hui \u00e0 disposition des \u00e9l\u00e9ments du bataillon d\u2019h\u00f4pital 66 en tant que formation de milice \u00e0 disponibilit\u00e9 \u00e9lev\u00e9e pour le service d\u2019appui \u00e0 partir du 6 janvier 2022 (\u00e9l\u00e9ments de l\u2019\u00e9tat-major du bataillon) ou du 7 janvier (\u00e9l\u00e9ments de la compagnie d\u2019\u00e9tat-major et de la compagnie d\u2019h\u00f4pital 66\/2). Ainsi, d\u00e8s le 7 janvier, 147 soldats de bataillon h\u00f4pital 66 suppl\u00e9mentaires assureront tant les engagements que la conduite et le service arri\u00e8re pour tous les militaires engag\u00e9s. La convocation des troupes se fait en fonction des besoins.<\/span><\/p>\n<\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p>Le 7 d\u00e9cembre 2021, le Conseil a d\u00e9cid\u00e9 d\u2019un nouveau service d\u2019appui de l\u2019arm\u00e9e au profit des autorit\u00e9s civiles : jusqu\u2019\u00e0 2500 militaires pourront apporter leur soutien aux h\u00f4pitaux pour les soins et le transport de patients et aux cantons pour la vaccination. Ils sont d\u00e9ploy\u00e9s \u00e0 la demande des cantons, si les moyens civils sont insuffisants. Cette d\u00e9cision du Conseil f\u00e9d\u00e9ral pr\u00e9voit la mobilisation de formations de milice \u00e0 disponibilit\u00e9 \u00e9lev\u00e9e.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Arm\u00e9e suisse mobilise des forces suppl\u00e9mentaires pour le service d\u2019appui CORONA. Avec la mise sur pied partielle du bataillon d\u2019h\u00f4pital 66, 119 militaires suppl\u00e9mentaires seront \u00e0 la disposition du secteur de la sant\u00e9 \u00e0 partir du 7 janvier 2022<\/p>\n","protected":false},"author":4,"featured_media":420881,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1187,22521,1170,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-530204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breves","category-coronavirus-minutes-par-minutes","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/530204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=530204"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/530204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/420881"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=530204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=530204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=530204"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=530204"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=530204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}