{"id":911604,"date":"2026-03-28T10:06:27","date_gmt":"2026-03-28T09:06:27","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=911604"},"modified":"2026-03-28T18:52:55","modified_gmt":"2026-03-28T17:52:55","slug":"rame-lahaj-notre-diaspora-est-le-meilleur-reflet-de-notre-identite","status":"publish","type":"post","link":"https:\/\/www.albinfo.ch\/fr\/rame-lahaj-notre-diaspora-est-le-meilleur-reflet-de-notre-identite\/","title":{"rendered":"Ram\u00eb Lahaj: Notre diaspora est le meilleur reflet de notre identit\u00e9"},"content":{"rendered":"<p data-start=\"15\" data-end=\"272\">Le t\u00e9nor albanais de renomm\u00e9e internationale, Ram\u00eb Lahaj, a hautement appr\u00e9ci\u00e9 le r\u00f4le de la diaspora albanaise, la qualifiant de meilleur reflet de l\u2019identit\u00e9 nationale et de preuve forte d\u2019int\u00e9gration dans les soci\u00e9t\u00e9s occidentales, rapporte albinfo.ch.<\/p>\n<p data-start=\"274\" data-end=\"523\">Dans une d\u00e9claration publique, Lahaj a affirm\u00e9 \u00eatre fier du poids et de l\u2019influence que la diaspora exerce dans les pays o\u00f9 elle vit, soulignant que leur int\u00e9gration constitue un exemple fort de pr\u00e9servation des valeurs et de repr\u00e9sentation digne.<\/p>\n<p data-start=\"525\" data-end=\"721\">&#8221; Notre diaspora est le meilleur reflet de notre identit\u00e9. Mon c\u0153ur se remplit de fiert\u00e9 pour leur int\u00e9gration et pour l\u2019importance qu\u2019ils ont dans les soci\u00e9t\u00e9s o\u00f9 ils vivent &#8220;, a d\u00e9clar\u00e9 Lahaj.<\/p>\n<p data-start=\"723\" data-end=\"970\">Il a \u00e9galement \u00e9voqu\u00e9 avec \u00e9motion le concert tenu \u00e0 Gen\u00e8ve, le qualifiant comme l\u2019un des souvenirs les plus beaux et inspirants de son parcours artistique, dans le cadre de ses engagements pour la promotion du Kosovo et de la culture albanaise.<\/p>\n<p data-start=\"972\" data-end=\"1147\">Selon lui, le concert organis\u00e9 par le Consulat du Kosovo \u00e0 Gen\u00e8ve a \u00e9t\u00e9 une preuve claire de l\u2019identit\u00e9 et de la place que les Albanais m\u00e9ritent sur la sc\u00e8ne internationale.<\/p>\n<p data-start=\"1149\" data-end=\"1463\">&#8221; Le concert de Gen\u00e8ve reste l\u2019un des souvenirs les plus beaux et inspirants dans la continuit\u00e9 des activit\u00e9s pour la repr\u00e9sentation de notre pays et de nos valeurs. Ce concert organis\u00e9 par le Consulat du Kosovo \u00e0 Gen\u00e8ve est une preuve claire de qui nous sommes et de la place que nous occupons &#8220;, a-t-il ajout\u00e9.<\/p>\n<p data-start=\"1465\" data-end=\"1750\">Lahaj a \u00e9galement indiqu\u00e9 qu\u2019il avait eu l\u2019honneur d\u2019avoir comme invit\u00e9e sp\u00e9ciale la soprano Marigona Qerkezi, qu\u2019il a qualifi\u00e9e d\u2019artiste qui rend la nation fi\u00e8re, ainsi que le pianiste Kamal Khan, qu\u2019il a d\u00e9crit comme un ami et un proche collaborateur dans de nombreuses activit\u00e9s.<\/p>\n<p data-start=\"1752\" data-end=\"1975\">&#8221; Cette fois, j\u2019ai eu l\u2019honneur d\u2019avoir Marigona Qerkezi comme invit\u00e9e sp\u00e9ciale, une artiste qui nous rend fiers, ainsi que le pianiste Kamal Khan, un ami qui m\u2019a accompagn\u00e9 dans de nombreuses activit\u00e9s &#8220;, a conclu Lahaj.<\/p>\n<p data-start=\"1977\" data-end=\"2194\">Sa d\u00e9claration a \u00e9t\u00e9 accueillie positivement sur les r\u00e9seaux sociaux, attirant une fois de plus l\u2019attention sur l\u2019importance de la diaspora dans la pr\u00e9servation et la promotion de l\u2019identit\u00e9 albanaise dans le monde.\/Albinfo.ch<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Rame Lahaj -  Victoria Hall - Geneva, Switzerland - February 2026\" width=\"587\" height=\"330\" src=\"https:\/\/www.youtube.com\/embed\/a5nHbgavwkA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"ekHMosMWhX\"><p><a href=\"https:\/\/www.albinfo.ch\/revista\/revista-01-2026\/\">Revista 01-2026<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;Revista 01-2026&#8221; &#8212; Albinfo\" src=\"https:\/\/www.albinfo.ch\/revista\/revista-01-2026\/embed\/#?secret=VfTmsIlXs8#?secret=ekHMosMWhX\" data-secret=\"ekHMosMWhX\" width=\"587\" height=\"331\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"3rA4XmkBnc\"><p><a href=\"https:\/\/www.albinfo.ch\/kandidatet-shqiptare-te-zgjedhjeve-zvicerane-ne-qender-te-numrit-te-ri-te-albinfo-ch\/\">Kandidat\u00ebt shqiptar\u00eb t\u00eb zgjedhjeve zvicerane, n\u00eb qend\u00ebr t\u00eb numrit t\u00eb ri t\u00eb albinfo.ch<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;Kandidat\u00ebt shqiptar\u00eb t\u00eb zgjedhjeve zvicerane, n\u00eb qend\u00ebr t\u00eb numrit t\u00eb ri t\u00eb albinfo.ch&#8221; &#8212; Albinfo\" src=\"https:\/\/www.albinfo.ch\/kandidatet-shqiptare-te-zgjedhjeve-zvicerane-ne-qender-te-numrit-te-ri-te-albinfo-ch\/embed\/#?secret=NwH1iZBN4y#?secret=3rA4XmkBnc\" data-secret=\"3rA4XmkBnc\" width=\"587\" height=\"331\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le t\u00e9nor albanais de renomm\u00e9e internationale met en valeur le r\u00f4le de la diaspora et \u00e9voque le concert \u00e0 Gen\u00e8ve comme l\u2019un des plus beaux moments pour repr\u00e9senter le Kosovo et les valeurs nationales<\/p>\n","protected":false},"author":6,"featured_media":911500,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24637,24660,24630,1163,1168],"tags":[],"vendi":[],"content_country":[],"class_list":["post-911604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles-fr-4","category-la-musique","category-nouvelles","category-fr-e-diaspora","category-culture"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/911604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/comments?post=911604"}],"version-history":[{"count":1,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/911604\/revisions"}],"predecessor-version":[{"id":911606,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/posts\/911604\/revisions\/911606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media\/911500"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/media?parent=911604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/categories?post=911604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/tags?post=911604"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/vendi?post=911604"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.ch\/fr\/wp-json\/wp\/v2\/content_country?post=911604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}